{"id":46288,"date":"2024-09-21T12:05:23","date_gmt":"2024-09-21T10:05:23","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=46288"},"modified":"2024-09-23T17:25:56","modified_gmt":"2024-09-23T15:25:56","slug":"oktoberfest-edizione-2024","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/09\/21\/oktoberfest-edizione-2024\/","title":{"rendered":"Oktoberfest &#8211; Edizione 2024"},"content":{"rendered":"<p style=\"text-align: justify;\">Noi l&#8217;<strong>Oktoberfest<\/strong> lo festeggiamo da casa.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Non per essere tirchi, ma oramai i prezzi per qualsiasi genere di consumazione al suo interno, hanno raggiunto cifre esorbitanti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46290\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124344-e1727024840350-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124344-e1727024840350-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124344-e1727024840350-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124344-e1727024840350-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124344-e1727024840350-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Iniziando con la <strong>birra<\/strong>, che si aggira intorno ai 15euro al boccale, per poi proseguire con meta&#8217; pollo arrosto (sui 17euro).<\/p>\n<figure id=\"attachment_46323\" aria-describedby=\"caption-attachment-46323\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46323\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/IMG_20240923_155409-725x1024.jpg\" alt=\"\" width=\"525\" height=\"742\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/IMG_20240923_155409-725x1024.jpg 725w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/IMG_20240923_155409-106x150.jpg 106w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/IMG_20240923_155409-212x300.jpg 212w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/IMG_20240923_155409-768x1084.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/IMG_20240923_155409.jpg 1034w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46323\" class=\"wp-caption-text\">Da Instagram<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Insomma, stanno veramente impazzendo.<br \/>\nPensando poi che una famiglia con figli posso effettuare una visita nella giornata dei &#8220;bambini&#8221;&#8230; ci si lascia quasi uno stipendio!<\/p>\n<p>Nonostante tutti questi prezzi, non proprio a buon mercato, il turismo\u00c2\u00a0 (soprattutto straniero) e&#8217; considerevole e le persone arrivano a fiumi.<\/p>\n<p style=\"text-align: justify;\">Dalle notizie lette, poi, sembrerebbe che il primo sbronzo sia arrivato alle 19:30, del giorno di apertura.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46289\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124350-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124350-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124350-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124350-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240915_124350-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Parlando in casa ho poi appreso che i banchetti al di fuori del Teresianwise vendono birra decisamente piu&#8217; a buon mercato, non certo come dai distributori\/venditori, ma non a prezzi stratosferici.<br \/>\nI visitatori, dunque, l&#8217;acquistano direttamente li, prima di entrare nei tendoni.<br \/>\nIn questo modo hanno la scelta di non dover bere e di &#8220;godere&#8221; solamente dell&#8217;atmosfera.<\/p>\n<p style=\"text-align: justify;\">Personalmente sono andata solo una volta, quando la mia precedente ditta aveva distribuito alcuni biglietti e prenotato un tavolo.<br \/>\nSara&#8217;&#8230; forse l&#8217;atmosfera di festa, goliardica, di canti ma non e&#8217; che poi mi sia piaciuto cosi&#8217; tanto..<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noi l&#8217;Oktoberfest lo festeggiamo da casa.<\/p>\n","protected":false},"author":2,"featured_media":46291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161,110,164],"tags":[26],"class_list":["post-46288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-da-scoprire","category-monaco","category-varie","tag-da_fare"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=46288"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46288\/revisions"}],"predecessor-version":[{"id":46326,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46288\/revisions\/46326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/46291"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=46288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=46288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=46288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}