{"id":46048,"date":"2024-09-19T16:57:30","date_gmt":"2024-09-19T14:57:30","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=46048"},"modified":"2024-09-14T17:13:44","modified_gmt":"2024-09-14T15:13:44","slug":"petto-di-pollo-alla-pizzaiola","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/09\/19\/petto-di-pollo-alla-pizzaiola\/","title":{"rendered":"Petto di pollo alla pizzaiola"},"content":{"rendered":"<p style=\"text-align: justify;\">Stanca del solito &#8220;petto di pollo&#8221; cucinato allo stesso modo.<br \/>\nStanca del fatto che Tobias non tocchi pane a tavola, se non quando c&#8217;e&#8217; la presenza di sugo.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Come risolvere questi due problemi con un colpo solo?<br \/>\nCerto, con il &#8220;<strong>petto di pollo alla pizzaiola<\/strong>&#8220;, nella versione leggera e senza l&#8217;aggiunta di mozzarella \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">Decisamente l&#8217;immagine proposta non esalta il risultato finale, ma vi assicuro era veramente buono.<\/p>\n<figure id=\"attachment_46049\" aria-describedby=\"caption-attachment-46049\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46049\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240909_123326-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240909_123326-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240909_123326-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240909_123326-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240909_123326-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46049\" class=\"wp-caption-text\">Petto di pollo alla pizzaiola<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Petto di pollo alla pizzaiola &#8211; 3 persone<br \/>\n<\/strong><\/p>\n<pre>600gr di petto di pollo , tagliato a fettine\r\n150ml passata di pomodoro\r\nolio\r\n1 spicchio di aglio\r\ncapperi sott'aceto\r\norigano\r\nsale\r\npepe\r\npeperoncino (facoltativo)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate con l&#8217;affettare il petto di pollo sottilmente. Per aiutarvi potete metterlo nel congelatore per una 15ina di minuti, prima di tagliarlo.<\/p>\n<p style=\"text-align: justify;\">In una padella relativamente grande, da poter contenere tutto il pollo, inserite lo spicchio di aglio schiacciato ed un goccio di olio.<br \/>\nAggiungete le fette (*) di petto di pollo e fatele rosolare da entrambe le parti. Rimuovetele appena si saranno rosolate.<\/p>\n<p style=\"text-align: justify;\">Nella stessa padella versate la passata di pomodoro, l&#8217;origano, i capperi, regolate di sale, e fate cuocere per circa 5 minuti con un coperchio.<\/p>\n<p style=\"text-align: justify;\">Inserite nuovamente il petto di pollo nella stessa padella con la passata, abbassate il calore della fimma (fuoco basso), incoperchiate e lasciate cuocere per una decina di minuti.<\/p>\n<p style=\"text-align: justify;\">Se il sugo si dovesse restringere troppo, aggiungete dell&#8217;acqua calda, poca alla volta<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Se volete dare un tocco diverso alla carne, prima di inserire in padella le fettine di carne, passatele leggermente in <strong>farina<\/strong> ed eliminate l&#8217;eccesso.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stanca del solito &#8220;petto di pollo&#8221; cucinato allo stesso modo. Stanca del fatto che Tobias non tocchi pane a tavola, se non quando c&#8217;e&#8217; la presenza di sugo.<\/p>\n","protected":false},"author":2,"featured_media":46049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[257],"class_list":["post-46048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti","tag-light"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=46048"}],"version-history":[{"count":1,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46048\/revisions"}],"predecessor-version":[{"id":46050,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46048\/revisions\/46050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/46049"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=46048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=46048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=46048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}