{"id":46016,"date":"2024-09-17T10:24:19","date_gmt":"2024-09-17T08:24:19","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=46016"},"modified":"2024-09-14T16:26:15","modified_gmt":"2024-09-14T14:26:15","slug":"pane-siciliano_lievitazione-mista","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/09\/17\/pane-siciliano_lievitazione-mista\/","title":{"rendered":"Pane siciliano (lievitazione mista)"},"content":{"rendered":"<p style=\"text-align: justify;\">Lentamente sto rinfrescando Vera, per renderla (nuovamente) pimpante ed attiva.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Nonostante Vera sia gorgogliante e bollosa, ho pensato di preparare questo pane siciliano, con lievitazione prevalentemente effettuata con lievito di birra (ma dove e&#8217; possibile aggiungere anche licoli), aggiungendo quelo pochissimo lievito a coltura liquida a mia disposizione.<\/p>\n<figure id=\"attachment_46032\" aria-describedby=\"caption-attachment-46032\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46032\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_195745-e1726323646603-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_195745-e1726323646603-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_195745-e1726323646603-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_195745-e1726323646603-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_195745-e1726323646603-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46032\" class=\"wp-caption-text\">Pane siciliano (lievitazione mista)<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; <a href=\"https:\/\/www.antonellaaudino.it\/pane-siciliano-u-cucciddatu\/\">Pane siciliano &#8220;u cucciddatu&#8221;<\/a><\/strong><\/p>\n<pre>500 g di semola (*)\r\n350 g di acqua (300 + 50)\r\n100 g di licoli in esubero, si pu\u00c3\u00b2 omettere senza variare nulla (*)\r\n12 g di lievito di birra fresco\r\n20 g di olio EVO\r\n10 g di sale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Inserite la semola ed il licoli in esubero nella ciotola della planetaria con 300 g di acqua, lasciate in autolisi almeno un&#8217;ora.<\/p>\n<p style=\"text-align: justify;\">( L&#8217;autolisi consiste nel bagnare la farina in maniera uniforme in modo che l&#8217;impasto sia pi\u00c3\u00b9 facile da incordare ).<\/p>\n<p style=\"text-align: justify;\">Trascorsa l&#8217;ora aggiungete il lievito sbriciolato ed avviate l&#8217;impasto con la spirale pian piano, appena prende forma aggiungete a filo l&#8217;acqua aumentando la velocit\u00c3\u00a0 dopo ogni inserimento e cos\u00c3\u00ac fino ad esaurimento dell&#8217;acqua.<\/p>\n<p style=\"text-align: justify;\">Con l&#8217;ultimo inserimento dell&#8217;acqua aggiungete il sale ed aumentate la velocit\u00c3\u00a0 spingendola al massimo fino ad incordare.<br \/>\nAggiungete a filo l&#8217;olio senza perdere l&#8217;incordatura.<\/p>\n<p style=\"text-align: justify;\">Ad impasto concluso prelevate l&#8217;impasto (che \u00c3\u00a8 molle), ungete il piano di lavoro e date qualche piega S&amp;F o con il tarocco (*), poggiate in ciotola e fate lievitare fino al raddoppio.<\/p>\n<p style=\"text-align: justify;\">Con l&#8217;impasto al raddoppio, poggiate sul piano di lavoro cosparso di semola e, se si possiede un cestino di lievitazione, fate un buco al centro dell&#8217;impasto e poggiate nel cestino.<\/p>\n<p style=\"text-align: justify;\">Se non si possiede (*) fate un buco dopo aver poggiato in teglia.<br \/>\nNel buco centrale inserite un bicchiere (o un barattolo rivestito di alluminio) e fate lievitare in forma per un&#8217;ora circa.<\/p>\n<p style=\"text-align: justify;\">Accendete il forno a 200\u00c2\u00b0 statico.<\/p>\n<p style=\"text-align: justify;\">(**)<br \/>\nQuando \u00c3\u00a8 arrivato a temperatura, inserite la teglia vaporizzando il forno con uno spruzzino e cuocere per 35\/40 minuti<\/p>\n<figure id=\"attachment_46031\" aria-describedby=\"caption-attachment-46031\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46031\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_144712-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_144712-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_144712-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_144712-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240911_144712-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46031\" class=\"wp-caption-text\">Pane siciliano (lievitazione mista)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">L&#8217;autrice consiglia di mangiare il pane cosi&#8217; preparato in questo modo:<\/p>\n<p style=\"text-align: justify;\">Quando il pane sar\u00c3\u00a0 tiepido o freddo tagliare e farcire con abbondante olio, sale, pepe, origano,fette di provola, pomodoro ed olive o altrimenti con abbondante olio , sale, peperoncino, origano, provola ed acciughe<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">La <strong>semola<\/strong> da me utilizzata era rimacinata ed integrale<\/li>\n<li style=\"text-align: justify;\">Il <strong>licoli<\/strong> l&#8217;ho inserito, in circa 50gr (sono in fase di risveglio della mia pasta madre)<\/li>\n<li style=\"text-align: justify;\">Non ho inserito l&#8217;impasto sul piano di lavoro, ma in una <strong>ciotola unta di olio<\/strong>, per poi procedere con una S&amp;F<\/li>\n<li style=\"text-align: justify;\">Tutti i miei cestini sono rettangolari, quindi ho optato per il bicchiere avvolto di alluminio<\/li>\n<li style=\"text-align: justify;\"><strong>Rimuovete<\/strong> il bicchiere prima di infornare, allargando leggermente la ciambella sulla teglia.<\/li>\n<li style=\"text-align: justify;\">Nelle indicazioni fornite non e&#8217; scritto di effettuare dei <strong>tagli<\/strong> prima di cuocere, e cosi&#8217; NON ho fatto. A mio avviso sarebbe stato decisamente meglio, cosi&#8217; da dare la possibilita&#8217; di svilupparsi meglio<\/li>\n<\/ul>\n<figure id=\"attachment_46035\" aria-describedby=\"caption-attachment-46035\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46035\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_175137-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_175137-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_175137-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_175137-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_175137-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46035\" class=\"wp-caption-text\">Pane siciliano (lievitazione mista)<\/figcaption><\/figure>\n<p>E voi?<br \/>\nCon cosa lo mangereste?<\/p>\n<p style=\"text-align: justify;\">Il pane e&#8217; sparito in una giornata, quindi l&#8217;ho preparato nuovamente secondo le mie scarse conoscenze.<br \/>\nA mio avviso e&#8217; andata un pochino meglio, anche se non si e&#8217; sviluppato come avevo pensato (e desiderato).<\/p>\n<figure id=\"attachment_46033\" aria-describedby=\"caption-attachment-46033\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46033\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133024-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133024-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133024-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133024-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133024-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46033\" class=\"wp-caption-text\">Pane siciliano (lievitazione mista)<\/figcaption><\/figure>\n<figure id=\"attachment_46034\" aria-describedby=\"caption-attachment-46034\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-46034\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133057-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133057-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133057-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133057-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/09\/ok_IMG_20240912_133057-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-46034\" class=\"wp-caption-text\">Pane siciliano (lievitazione mista)<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lentamente sto rinfrescando Vera, per renderla (nuovamente) pimpante ed attiva.<\/p>\n","protected":false},"author":2,"featured_media":46035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[116,112],"class_list":["post-46016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-ldb","tag-licoli"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=46016"}],"version-history":[{"count":10,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46016\/revisions"}],"predecessor-version":[{"id":46037,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/46016\/revisions\/46037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/46035"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=46016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=46016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=46016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}