{"id":45763,"date":"2024-07-20T10:25:17","date_gmt":"2024-07-20T08:25:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=45763"},"modified":"2024-07-16T15:35:39","modified_gmt":"2024-07-16T13:35:39","slug":"civilta-hofflohmarkt","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/07\/20\/civilta-hofflohmarkt\/","title":{"rendered":"Civilta&#8217;. Hofflohmarkt"},"content":{"rendered":"<p style=\"text-align: justify;\">La situazione degli oggetti in sovrappiu&#8217;) in casa sta sfuggendo di mano.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il troppo e&#8217; decisamente tanto, cosi&#8217; che sono giunta alla conclusione che bisogna agire in qualche modo.<\/p>\n<p style=\"text-align: justify;\">In soccorso mi e&#8217; giunta questa opportunita&#8217;, partecipare all&#8217; <strong>Hofflohmarkt<\/strong> del mio paese la scorsa settimana.<\/p>\n<figure id=\"attachment_45768\" aria-describedby=\"caption-attachment-45768\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45768\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG_20240713_063059-733x1024.jpg\" alt=\"\" width=\"525\" height=\"733\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG_20240713_063059-733x1024.jpg 733w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG_20240713_063059-107x150.jpg 107w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG_20240713_063059-215x300.jpg 215w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG_20240713_063059-768x1073.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG_20240713_063059.jpg 1077w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45768\" class=\"wp-caption-text\">Hofflohmarkt<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Di che cosa si tratta?<\/p>\n<p style=\"text-align: justify;\">L&#8217; <strong>Hofflohmarkt<\/strong> non e&#8217; altro che un &#8220;mercatino delle pulci&#8221; svolto nel proprio giardino o nella propria proprieta&#8217;.<br \/>\nE&#8217; uno dei tantissimi progetti di \u00e2\u20ac\u0153partecipazione\u00e2\u20ac\u009d comunitaria per i vicini, la sostenibilit\u00c3\u00a0 e l\u00e2\u20ac\u2122amore per il vicinato.<\/p>\n<p style=\"text-align: justify;\">I residenti vendono i loro vecchi pezzi preferiti nel proprio cortile, giardino o garage, nella loro propriet\u00c3\u00a0 privata.<br \/>\nIl punto forte \u00c3\u00a8 la partecipazione impegnata in una grande comunit\u00c3\u00a0.<br \/>\nSi tratta di un&#8217;occasione unica (una volta all&#8217;anno, almeno per noi), ma perfetta per (tentare) di liberare la cantina o la soffitta ed ottenere nuovi pezzi preferiti, oggetti preziosi e pezzi unici.<\/p>\n<p style=\"text-align: justify;\">I numerosi mercatini delle pulci, diversi e decentralizzati, in date prestabilite creano una giornata colorata e sfaccettata di shopping delle pulci in tutto il quartiere.<\/p>\n<figure id=\"attachment_45769\" aria-describedby=\"caption-attachment-45769\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45769\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0010-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0010-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0010-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0010-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0010-768x1365.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0010.jpg 1080w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45769\" class=\"wp-caption-text\">Hofflohmarkt<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Perche&#8217; tirarsi indietro?<\/p>\n<p style=\"text-align: justify;\">Ho dunque messo sotto la famiglia e predisposto alla semi-alba (erano le 8:45 di sabato!) il mio armamentario di vendita, previa registrazione.<\/p>\n<figure id=\"attachment_45770\" aria-describedby=\"caption-attachment-45770\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45770\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0009-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0009-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0009-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0009-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0009-768x1365.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/ok_IMG-20240714-WA0009.jpg 1080w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45770\" class=\"wp-caption-text\">Hofflohmarkt<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La <em>parte cool<\/em>, dal mio punto di vista, e&#8217; che si ha una mappa virtuale, cosi&#8217; da essere piu&#8217; o meno agevolati negli acquisti.<br \/>\nI venditori, infatti, all&#8217;atto della registrazione indicano il domicilio e, a scelta, che cosa mettono in vendita. In questo modo i possibili acquirenti hanno tutto sotto gli occhi, tralasciando eventuali &#8220;stand&#8221; non interessanti.<\/p>\n<p style=\"text-align: justify;\">Sicuramente piu&#8217; venditori ci sono nella stessa zona, piu&#8217; il numero dei curiosi aumenta&#8230;<br \/>\nNel mio anello eravamo solamente in 4 (gatti).<br \/>\nConfido nell&#8217;anno prossimo. Magari avrei dovuto condividere e pubblicizzare maggiormente l&#8217;evento nel vicinato.<\/p>\n<p style=\"text-align: justify;\">Non mi e&#8217; restato che aspettare&#8230; e guadagnare 30euro in totale.<br \/>\nNon e&#8217; tanto, ma un pochino piu&#8217; di spazio e&#8217; stato guadagnato.<\/p>\n<figure id=\"attachment_45766\" aria-describedby=\"caption-attachment-45766\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45766\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/IMG_20240713_102645-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/IMG_20240713_102645-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/IMG_20240713_102645-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/IMG_20240713_102645-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/07\/IMG_20240713_102645-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45766\" class=\"wp-caption-text\">Hofflohmarkt<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La situazione degli oggetti in sovrappiu&#8217;) in casa sta sfuggendo di mano.<\/p>\n","protected":false},"author":2,"featured_media":45765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161,46,110],"tags":[140],"class_list":["post-45763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-da-scoprire","category-life","category-monaco","tag-civilta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=45763"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45763\/revisions"}],"predecessor-version":[{"id":45771,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45763\/revisions\/45771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/45765"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=45763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=45763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=45763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}