{"id":45492,"date":"2024-06-16T17:11:04","date_gmt":"2024-06-16T15:11:04","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=45492"},"modified":"2024-06-12T17:13:19","modified_gmt":"2024-06-12T15:13:19","slug":"st-ottilien","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/06\/16\/st-ottilien\/","title":{"rendered":"St. Ottilien Erzabtei"},"content":{"rendered":"<p style=\"text-align: justify;\">Con tutti gli anni e le volte in cui sono andata con Stepha da Oma e Opa, non mi ha mai accompagnata nei dintorni, anche non troppo distanti, per fare delle visite\/escursioni.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Questa volta, nonostante la tarda ora, mi sono leggermente &#8220;impuntata&#8221;, cosi&#8217; da arrivare fino all&#8217;<strong>abbazia di St. Ottilien<\/strong>.<\/p>\n<figure id=\"attachment_45536\" aria-describedby=\"caption-attachment-45536\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45536\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180537-e1718204805996-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180537-e1718204805996-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180537-e1718204805996-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180537-e1718204805996-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45536\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">L&#8217;arciabbazia di<strong> Sant&#8217;Ottilien<\/strong> (latino: Archiabbatia Sanctissimi Cordis Iesu ad Sanctam Ottiliam) \u00c3\u00a8 un monastero dei missionari benedettini nel distretto dell&#8217;Alta Baviera di Landsberg am Lech (vicino al lago Ammer), che appartiene alla diocesi di Augusta.<br \/>\nIl monastero, insieme agli edifici circostanti, costituisce la parte di Sankt Ottilien (fino al 1904 Emming) della comunit\u00c3\u00a0 di Eresing.<\/p>\n<p>(Da Google germania)<\/p>\n<p style=\"text-align: justify;\">Il pellegrinaggio a Santa Ottilia a Emming \u00c3\u00a8 documentato in modo attendibile dal 1365. Nel XVI secolo Emming fu ampliato in un palazzo. Furono costruiti la Ottilienkapelle e un piccolo castello. Nel XVII secolo il castello e la cappella furono ristrutturati in stile barocco. La propriet\u00c3\u00a0 pass\u00c3\u00b2 di mano pi\u00c3\u00b9 volte nel corso del tempo; il castello fu demolito nel 1884. Infine Andreas Amrhein, monaco benedettino dell&#8217;arciabbazia di Beuron, acquist\u00c3\u00b2 nel 1886 il borgo senza proprietario e nel 1887 fond\u00c3\u00b2 Sankt Ottilien.<\/p>\n<p style=\"text-align: justify;\">Il monastero crebbe rapidamente fino al 1930 (ulteriori aree di missione furono il Sud Africa, la Corea, la Cina). Durante questo periodo Sankt Ottilien fu ampliato per ospitare il convento, che contava 396 monaci. Nel 1941 i monaci furono espulsi dall&#8217;amministrazione tedesca, che vi install\u00c3\u00b2 un ospedale di guerra. Dopo la fine della guerra e fino al 1948 a Sankt Ottilien esisteva un campo sfollato, fondato dal medico lituano Zalman Grinberg, nel quale venivano curati i prigionieri liberati dai campi di concentramento.<\/p>\n<figure id=\"attachment_45539\" aria-describedby=\"caption-attachment-45539\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45539\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180117-e1718204772189-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180117-e1718204772189-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180117-e1718204772189-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180117-e1718204772189-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45539\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Immediatamente accanto al cimitero del monastero si trova un cimitero ebraico in cui furono sepolti 76 morti.<br \/>\nLa storia del campo DP \u00c3\u00a8 raccontata in dodici stazioni sparse sul sito ed \u00c3\u00a8 anche documentata digitalmente, compresa la memoria del concerto di liberazione degli ex prigionieri ebrei il 27 maggio 1945 e la nascita di 428 bambini tra il 1945 e il 1948.<\/p>\n<figure id=\"attachment_45537\" aria-describedby=\"caption-attachment-45537\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45537\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180312-e1718204795126-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180312-e1718204795126-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180312-e1718204795126-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180312-e1718204795126-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45537\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Oltre ai compiti missionari e al relativo aiuto allo sviluppo nei paesi del terzo mondo, il monastero gestisce una grande casa per ritiri, una propria casa editrice EOS, una fattoria signorile, il Rhabanus-Maurus-Gymnasium Sankt Ottilien per circa 700 studenti con annessa giornata centro e convitto e diverse attivit\u00c3\u00a0 artigianali. Il monastero gestisce anche un piccolo campo sportivo e un campeggio per giovani.<\/p>\n<p style=\"text-align: justify;\"><strong>Chiesa abbaziale del Cuore di Ges\u00c3\u00b9 (Abteikirche Herz Jesu)<\/strong><br \/>\nLa chiesa del monastero (Patrozinium Herz Jesu) fu costruita tra il 1897 e il 1899 su progetto di Hans Schurr. La sua torre appuntita, alta 75 metri, \u00c3\u00a8 visibile da grande distanza.<\/p>\n<figure id=\"attachment_45542\" aria-describedby=\"caption-attachment-45542\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45542\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175518-e1718204745131-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175518-e1718204745131-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175518-e1718204745131-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175518-e1718204745131-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45542\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<figure id=\"attachment_45547\" aria-describedby=\"caption-attachment-45547\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45547\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175007-e1718204692196-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175007-e1718204692196-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175007-e1718204692196-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175007-e1718204692196-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45547\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La chiesa a tre navate fu costruita in stile neogotico e consacrata nel 1903.<br \/>\nLa chiesa fu costruita una volta pi\u00c3\u00b9 corta di quanto originariamente previsto, probabilmente a causa delle proteste delle parrocchie circostanti.<\/p>\n<figure id=\"attachment_45546\" aria-describedby=\"caption-attachment-45546\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45546\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175156-e1718204705670-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175156-e1718204705670-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175156-e1718204705670-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175156-e1718204705670-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45546\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<p>L&#8217;abbazia e&#8217; veramente un piccolo mondo a parte, noi abbiamo fatto un giro velocissimo anche se bisognerebbe spendere un po&#8217; piu&#8217; di tempo.<br \/>\nNon vi nascondo che, una volta dentro &#8220;le mura&#8221;, si respira un&#8217;aria di altri tempi.<\/p>\n<figure id=\"attachment_45545\" aria-describedby=\"caption-attachment-45545\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45545\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175040-e1718204716496-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175040-e1718204716496-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175040-e1718204716496-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175040-e1718204716496-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45545\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<figure id=\"attachment_45544\" aria-describedby=\"caption-attachment-45544\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45544\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175405-e1718204730908-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175405-e1718204730908-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175405-e1718204730908-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175405-e1718204730908-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45544\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Sembra quasi di essere ai tempi de &#8220;Il nome della rosa&#8221;, ed anche a &#8220;Cadfael&#8221;.<\/p>\n<p style=\"text-align: justify;\">Spero solamente di riuscire a convincere Stephan un&#8217;altra volta, magari arrivando ad un orario un po&#8217; piu&#8217; decente, cosi&#8217; da avere anche l&#8217;oppurtunita&#8217; di fare un giretto nel negozio, km0 chiaramente, ed acquistare qualcosina.<\/p>\n<figure id=\"attachment_45543\" aria-describedby=\"caption-attachment-45543\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45543\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175423-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175423-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175423-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175423-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175423-768x576.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45543\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<figure id=\"attachment_45541\" aria-describedby=\"caption-attachment-45541\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45541\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175525-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175525-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175525-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175525-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175525-768x576.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45541\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<figure id=\"attachment_45540\" aria-describedby=\"caption-attachment-45540\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45540\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175930-e1718204759979-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175930-e1718204759979-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175930-e1718204759979-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_175930-e1718204759979-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45540\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<figure id=\"attachment_45538\" aria-describedby=\"caption-attachment-45538\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45538\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180027-e1718204783483-768x1024.jpg\" alt=\"\" width=\"525\" height=\"700\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180027-e1718204783483-768x1024.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180027-e1718204783483-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/06\/ok_IMG_20240607_180027-e1718204783483-225x300.jpg 225w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45538\" class=\"wp-caption-text\">St. Ottilien Erzabtei<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con tutti gli anni e le volte in cui sono andata con Stepha da Oma e Opa, non mi ha mai accompagnata nei dintorni, anche non troppo distanti, per fare delle visite\/escursioni.<\/p>\n","protected":false},"author":2,"featured_media":45543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161,162,168,24,110],"tags":[26],"class_list":["post-45492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-da-scoprire","category-dintorni","category-europa","category-germania","category-monaco","tag-da_fare"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=45492"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45492\/revisions"}],"predecessor-version":[{"id":45549,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45492\/revisions\/45549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/45543"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=45492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=45492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=45492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}