{"id":45392,"date":"2024-05-29T16:54:59","date_gmt":"2024-05-29T14:54:59","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=45392"},"modified":"2024-05-27T17:37:51","modified_gmt":"2024-05-27T15:37:51","slug":"plumcake-cacao-e-latte","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/05\/29\/plumcake-cacao-e-latte\/","title":{"rendered":"Plumcake cacao e latte"},"content":{"rendered":"<p style=\"text-align: justify;\">Ed anche questa settimana ho preparato una torta per la colazione.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Inoltre, dato che domani andro&#8217; da Barbara, gliene portero&#8217; un poco.<br \/>\nPiu&#8217; che altro perche&#8217;, nonostante i diametri della teglia da me utilizzati non sono particolarmente grandi, il dolce a colazione viene mangiato solamente a colazione.<br \/>\nQuindi&#8230; non finisce piu&#8217;.<\/p>\n<p style=\"text-align: justify;\">Questo <strong>plumcake cacao e latte<\/strong> era nella lista delle mie torte da colazione da preparare.<br \/>\nCon la mancanza delle uova e&#8217; leggermente piu&#8217; leggero ma, mi raccomando, non fate come me: setacciate bene gli ingredienti secchi o il risultato sara&#8217; grumoso.<\/p>\n<figure id=\"attachment_45431\" aria-describedby=\"caption-attachment-45431\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45431\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG_20240524_090335-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG_20240524_090335-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG_20240524_090335-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG_20240524_090335-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG_20240524_090335-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45431\" class=\"wp-caption-text\">Plumcake cacao e latte<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; <a href=\"https:\/\/blog.giallozafferano.it\/paola67\/plumcake-al-cacao-e-latte\/\">Plumcake cacao e latte<\/a><\/strong> &#8211; 1 stampo<\/p>\n<pre>200 g di farina 00\r\n180 g di zucchero (*)\r\n60 g di cacao amaro (*)\r\n400 ml di latte\r\n40 olio di semi di mais\r\n1 bustina di lievito istantaneo in polvere per dolci\r\n\r\n<strong>Per decorare (opzionale)<\/strong>\r\n zucchero a velo\r\n glassa<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una ciotola mescolate con un cucchiaio la farina, lo zucchero, la cannella ed il cacao.<br \/>\nAttenzione a non creare grumi, magari setacciando gli ingredienti secchi.<\/p>\n<p style=\"text-align: justify;\">Unite gradualmente gli ingredienti liquidi: il latte e l\u00e2\u20ac\u2122olio.<\/p>\n<p style=\"text-align: justify;\">Mescolate benissimo fino ad ottenere un composto omogeneo, quindi aggiungete il lievito setacciandolo attraverso un colino a maglie fitte.<\/p>\n<p style=\"text-align: justify;\">Versate l\u00e2\u20ac\u2122impasto in uno stampo da plumcake, meglio se rivestito di carta forno o imburrato\/infarinato , rimuovendo la farina in eccesso.<\/p>\n<p style=\"text-align: justify;\">Cuocete il plumcake al cacao e latte in forno statico preriscaldato a 160\u00c2\u00b0 per 55\/60 minuti.<br \/>\nPrima di sfornarlo verificate l\u00e2\u20ac\u2122effettiva cottura infilando al centro uno stecchino che dovr\u00c3\u00a0 uscire asciutto.<\/p>\n<p style=\"text-align: justify;\">Sfornatelo e lasciatelo raffreddare completamente prima di rimuoverlo dallo stampo.<\/p>\n<p style=\"text-align: justify;\">Una volta freddo trasferirlo su una gratella e decoratelo con la glassa o con lo zucchero a velo.<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Dalla ricetta originale ho diminuito lo <strong>zucchero<\/strong>, portandolo a 150gr<\/li>\n<li style=\"text-align: justify;\">Per dare un tocco in piu&#8217; ho inserito della <strong>cannella<\/strong>.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ed anche questa settimana ho preparato una torta per la colazione.<\/p>\n","protected":false},"author":2,"featured_media":45431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[84],"class_list":["post-45392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-torte","tag-cioccolato"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=45392"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45392\/revisions"}],"predecessor-version":[{"id":45438,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45392\/revisions\/45438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/45431"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=45392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=45392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=45392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}