{"id":45307,"date":"2024-06-03T10:23:53","date_gmt":"2024-06-03T08:23:53","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=45307"},"modified":"2024-05-28T17:37:47","modified_gmt":"2024-05-28T15:37:47","slug":"unfrosted_pop-tart","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/06\/03\/unfrosted_pop-tart\/","title":{"rendered":"&#8220;Unfrosted&#8221; &#8211; Pop Tart"},"content":{"rendered":"<p style=\"text-align: justify;\">Mentre cercavo qualcosa da guardare in TV, mi sono fatta catturare da questo &#8220;<strong>Unfrosted<\/strong>&#8220;, titolo alquanto particolare, soprattutto data l&#8217;immagine rappresentativa.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Unfrosted<\/em> e&#8217; una commedia americana del 2024 diretta da Jerry Seinfeld.<\/p>\n<p style=\"text-align: justify;\">Il film, interpretato da un cast che comprende tra gli altri Seinfeld stesso, Melissa McCarthy, Jim Gaffigan, Max Greenfield, Hugh Grant e Amy Schumer, ed e&#8217; vagamente basato sulla storia vera della creazione dei pasticcini scaldati nel tostapane, denominati &#8220;<strong>Pop-Tarts<\/strong>&#8220;.<\/p>\n<figure id=\"attachment_45311\" aria-describedby=\"caption-attachment-45311\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-45311\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/unfrosted.jpg\" alt=\"\" width=\"474\" height=\"266\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/unfrosted.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/unfrosted-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/unfrosted-300x168.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-45311\" class=\"wp-caption-text\">Unfrosted &#8211; Da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Dopo le multitudini di cereali da prima colazione indirizzati principalmente ai bambini\/ragazzini, prodotti in ogni veste e colore pur di accattivare il pubblico, finalmente si giunge al fatidico &#8220;pop tart&#8221; che, come potrete vedere nella pellicola, ha ottenuto un marchio commerciale ben diverso da quanto voluto e pensato all&#8217;origine del suo nome.<\/p>\n<p style=\"text-align: justify;\">Nei supermercati a me vicini, non mi e&#8217; sembrato di aver mai visto una confezione simile venduta sugli scaffali anche se, onestamente, non lo ho neppure mai cercato.<\/p>\n<figure id=\"attachment_45467\" aria-describedby=\"caption-attachment-45467\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-45467\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/Pop-Tarts-Cherry.jpg\" alt=\"\" width=\"800\" height=\"470\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/Pop-Tarts-Cherry.jpg 800w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/Pop-Tarts-Cherry-150x88.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/Pop-Tarts-Cherry-300x176.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/Pop-Tarts-Cherry-768x451.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-45467\" class=\"wp-caption-text\">PopTarts Cherry &#8211; foto da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Per ovviare all&#8217; eventuale acquisto (con relativa preparazione ed il fatidico assaggio) ho chiesto a Tobias (ora dall&#8217;altra parte del mondo) se ne avesse un Pop_tarts a casa, cosi&#8217; da potermi spedire la foto.<br \/>\nProntamente mi ha risposto e questo e&#8217; il suo risultato, al gusto &#8220;marshmellow&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-45469\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG-20240504-WA0011-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG-20240504-WA0011-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG-20240504-WA0011-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG-20240504-WA0011-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG-20240504-WA0011-768x1365.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/ok_IMG-20240504-WA0011.jpg 1080w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Quindi&#8230; non chiedetemi nulla circa il gusto o la fattibilita&#8217; nella sua creazione casalinga.<br \/>\nSe non erro potrebbe essere <strong><em><a href=\"https:\/\/lemonsandzest.com\/the-easiest-homemade-pop-tarts\/\">riproducibile agilmente a casa<\/a><\/em><\/strong>, utilizzando delle fettine di pane in cassetta tostato, ma lascio a voi l&#8217;eventuale possibilita&#8217; di una ulteriore ricerca e riproduzione di questo dolcetto da colazione-merenda.<br \/>\nForse potrei farli al ritorno del ragazzo&#8230;<\/p>\n<p style=\"text-align: justify;\">In <strong>Unfrosted<\/strong>,\u00c2\u00a0 &#8220;storia di ambizione, tradimento, zucchero e minacciosi lattai&#8221;, si possono ritrovare i tentativi dell&#8217;azienda di cereali Kellogg nel battere la rivale Post sul mercato, con un rivoluzionario dolce per la colazione nel 1963 a Battle Creek, Michigan.<\/p>\n<p style=\"text-align: justify;\">Se da un lato abbiamo molte battute e sketch divertenti, dall&#8217;altro possiamo ritrovare un velo di verita&#8217; nella storia: di come i produttori conoscano la pericolosita&#8217; degli zuccheri inseriti nelle merende\/prodotti da forno e colazione; sul come e&#8217; facile a pilotare il marketing facendo leva sui ragazzi e sulle mascot utilizzate per accattivarsi la simpatia.<\/p>\n<figure id=\"attachment_45310\" aria-describedby=\"caption-attachment-45310\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-45310\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/unfrosted2.jpg\" alt=\"\" width=\"474\" height=\"248\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/unfrosted2.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/unfrosted2-150x78.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/05\/unfrosted2-300x157.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-45310\" class=\"wp-caption-text\">Unfrosted &#8211; Da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ed anche la nostra famiglia non e&#8217; esente&#8230; con il mangiare dei cereali confezionati (una montagna di zucchero, ma ora ci sto decisamente piu&#8217; attenta) abbiamo ricevuto una meravigliosa ciotola e 2 cucchiai di Tigro.<\/p>\n<p style=\"text-align: justify;\">Alla fine, <em>cosa sono queste &#8220;Pop-Tart&#8221; di cui sto scrivendo<\/em>?<br \/>\nLe Pop Tarts sono biscotti ripieni e glassati dai sapori pi\u00c3\u00b9 inediti e gustosi che ci siano, una &#8220;gustosa&#8221; colazione che viene mangiata soprattutto dagli americani, preferendola al solito bacon.<br \/>\nSia la glassa zuccherina (nella maggior parte dei casi) che i ripieni di crema, dai diversi gusti, diversificano il prodotto.<br \/>\nLa facilita&#8217; di preparazione, poi, li facilita ancora di piu&#8217;: basta scaldarli nel tostapane ed il pasto e&#8217; pronto.<\/p>\n<p style=\"text-align: justify;\">Sembrerebbe, inoltre, che gli americani mangino questi biscotti variando la preparazione originaria e personalizzandola moltol.<br \/>\nLi possiamo trovare nel freezer, cosi&#8217; da avere una sorta di biscotto-gelato; sbriciolati sul gelato per renderlo piu&#8217; croccante; facendone un milkshake o arrivando al loro utilizzo per la preparazione di ulteriori dolci (parfait e cake pops ad esempio).<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentre cercavo qualcosa da guardare in TV, mi sono fatta catturare da questo &#8220;Unfrosted&#8220;, titolo alquanto particolare, soprattutto data l&#8217;immagine rappresentativa.<\/p>\n","protected":false},"author":2,"featured_media":45309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,101],"tags":[251,129],"class_list":["post-45307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-passatempo","tag-foodmedia","tag-tv_kino"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=45307"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45307\/revisions"}],"predecessor-version":[{"id":45474,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45307\/revisions\/45474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/45309"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=45307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=45307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=45307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}