{"id":45018,"date":"2024-04-28T13:02:49","date_gmt":"2024-04-28T11:02:49","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=45018"},"modified":"2024-04-25T15:04:13","modified_gmt":"2024-04-25T13:04:13","slug":"peperoni-couscous-e-ricotta","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/04\/28\/peperoni-couscous-e-ricotta\/","title":{"rendered":"Peperoni ripieni di couscous e ricotta (vegetariani)"},"content":{"rendered":"<p style=\"text-align: justify;\">Il tempo e&#8217; ancora brutto, ma non voglio cedere alla tentazione di ritrovarmi in un nuovo inverno.<br \/>\nIn fin dei conti siamo a primavera!<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Quindi, seguendo gli ingredienti previsti per la giornata di oggi, ho preparato dei <strong>&#8220;Peperoni ripieni vegetariani<\/strong>&#8220;<\/p>\n<figure id=\"attachment_45066\" aria-describedby=\"caption-attachment-45066\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45066\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542093-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542093-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542093-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542093-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542093-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45066\" class=\"wp-caption-text\">Peperoni ripieni di couscous e ricotta (vegetariani)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Peperoni ripieni di couscous e ricotta (vegetariani)<\/strong><\/p>\n<pre>4 peperoni (*)\r\n100gr coucous (da cucinare)\r\n1\/2 carota\r\n1 cipollotto\r\n200gr di ricotta (*)\r\nerbe e spezie aromatiche (*)\r\nolio\r\nsale\r\npepe\r\ndado\r\n\r\n<strong>Facoltativi<\/strong>\r\nfrutta secca (pinoli, noci)\r\nfrutta disidratata (leggermente rinvenuta in acqua calda)\r\nolive taggiasche\r\ncapperi\r\nmenta<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavate i peperoni, rimuovete la calotta e svuotateli dai semi.<br \/>\nSalate l&#8217;interno della base, un velo di olio (o forse no, vedete voi) e metteteli a pre-cuocere in forno, statico, a 180 gradi per una ventina di 20 minuti.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo preparare il couscous come da indicazione della confezione: aggiungete acqua\/brodo bollente, chiudete il contenitore con coperchio e fate assorbire il liquido.<\/p>\n<p style=\"text-align: justify;\">In un pentolini inserite il cipollotto affettato, olio, la carota a cubetti e la calotta dei peperoni (1-2) a dadini.<br \/>\nFate cuocere lentamente per una 15ina di minuti, cosi&#8217; da ammorbidire il tutto.<br \/>\nPoi fate raffreddare\/intiepidire<\/p>\n<p style=\"text-align: justify;\">In una ciotola inserite la ricotta, il couscous, le verdurine e spezie\/erbe aromatiche a piacere (*), pepate e salate a gusto.<br \/>\nSe volete potete aggiungere anche dei pinoli\/frutta secca tritati grossolanamente.<\/p>\n<p style=\"text-align: justify;\">Svuotate i peperoni dalla loro acqua generata durante la cottura, riepiteli e fate cuocere, in forno, per altri 25 minuti circa, sempre a 180 gradi statico.<\/p>\n<figure id=\"attachment_45064\" aria-describedby=\"caption-attachment-45064\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-45064\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542063-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542063-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542063-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542063-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1713979542063-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-45064\" class=\"wp-caption-text\">Peperoni ripieni di couscous e ricotta (vegetariani)<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Onestamente pensavo che 3 <strong>peperoni<\/strong> fossero sufficienti, vi consiglio di cuocerne 4. Purtroppo, per me, li ho dovuti pressare tantissimo!!!<\/li>\n<li style=\"text-align: justify;\">Le<strong> erbe aromatiche<\/strong> da me scelte sono state timo e zaatar<\/li>\n<li style=\"text-align: justify;\">Se non gradite la ricotta, potete sostituirla con una dadolata di <strong>feta<\/strong>.Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Il tempo e&#8217; ancora brutto, ma non voglio cedere alla tentazione di ritrovarmi in un nuovo inverno. In fin dei conti siamo a primavera!<\/p>\n","protected":false},"author":2,"featured_media":45065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,138],"tags":[54,257,265,256],"class_list":["post-45018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-piatti_unici","tag-cereali","tag-light","tag-nascondo_le_verdure","tag-vegetariano"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=45018"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45018\/revisions"}],"predecessor-version":[{"id":45068,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/45018\/revisions\/45068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/45065"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=45018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=45018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=45018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}