{"id":44801,"date":"2024-04-19T12:13:40","date_gmt":"2024-04-19T10:13:40","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=44801"},"modified":"2024-04-12T17:38:19","modified_gmt":"2024-04-12T15:38:19","slug":"deliziose-ricette-light","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/04\/19\/deliziose-ricette-light\/","title":{"rendered":"Deliziose ricette&#8230; light"},"content":{"rendered":"<p style=\"text-align: justify;\">Proseguo la raccolta di ulteriori ricettine ( secondi piatti ) decisamente leggere, che ho preparato in questi giorni.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Ancora una volta ricordo che le quantita&#8217; sono indicative, e riguardano la mia porzione.<\/p>\n<p><strong>Ingredienti &#8211; Filetti di orata al limone<\/strong> &#8211; 1 porzione<\/p>\n<pre>200gr di filetti di orata\r\nlimone (BIO)\r\n1 spicchio di aglio\r\nrosmarino\r\n1 cucchiaio di farina\r\n1 cucchiaino di olio\r\nsale\r\npepe\r\nprezzemolo<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Spremete il limone per ottenere il suo succo, se volete accentuare il sapore, unitelo alla scorza dello stesso.<\/p>\n<p style=\"text-align: justify;\">In una padella, abbastanza grande da contenere anche il pesce, inserite il cucchiaino di olio, l&#8217;aglio ed il rosmarino.<br \/>\nFate soffriggere il tutto, cosi&#8217; da insaporire bene e profumare l&#8217;olio.<\/p>\n<p style=\"text-align: justify;\">Infarinate i filetti di orata &#8211; da entrambi i lati &#8211; con il cucchiaio di farina, rimuovendo la farina in eccesso.<\/p>\n<p style=\"text-align: justify;\">Mettete i filetti nella padella e fate cuocere, coprendo con il coperchio.<br \/>\nA meta&#8217; cottura regolate di sale ed aggiungete il succo del limone.<\/p>\n<p style=\"text-align: justify;\">Coprite e portate a cottura.<br \/>\nDecorate con il prezzemolo tritato (se vi ricordate!).<\/p>\n<p style=\"text-align: justify;\">Il mio piatto e&#8217; stato completato da insalatina e pane, cosi&#8217; da avere un pasto completo.<\/p>\n<figure id=\"attachment_44803\" aria-describedby=\"caption-attachment-44803\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44803\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712843659165-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712843659165-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712843659165-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712843659165-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712843659165-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44803\" class=\"wp-caption-text\">Filetti di orata al limone<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Filetti di merluzzo al micro <\/strong> &#8211; 1 porzione<\/p>\n<pre>200gr di filetti di merluzzo\r\nsale\r\npepe\r\ncarote\r\nzucchine\r\nolio\r\n<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate con il preparare la verdura: pulitela ed affettatela sottilmente.<br \/>\nFatela cuocere nel forno microonde, per alcuni minuti, con un goccio di acqua, in modo da pre-lessarla leggermente.<\/p>\n<p style=\"text-align: justify;\">In una pentola per la cottura a vapore, ma che possa andare anche nel microonde, inserite i filetti di merluzzo.<br \/>\n(Eventualmente potete creare un cartoccio con carta forno, chiudendolo. )<br \/>\nAggiungete la verdura pre-lessata e fate cuocere a massima potenza per alcuni minuti, quel tanto che basta per cuocere il filetto di pesce ma non seccarlo completamente.<\/p>\n<p style=\"text-align: justify;\">Impiattate, condite con sale, pepe ed un velo di olio.<\/p>\n<figure id=\"attachment_44821\" aria-describedby=\"caption-attachment-44821\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44821\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712851117467-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712851117467-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712851117467-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712851117467-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712851117467-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44821\" class=\"wp-caption-text\">Filetti di merluzzo al micro<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Kuku light<\/strong> &#8211; 2 persone<\/p>\n<pre>2 cucchiaini di olio\r\n2 cipolle piccole, pelate ed affettate\r\n3 melanzane piccole, pelate\r\n4 uova, leggermente sbattute\r\n1 cucchiaio di farina 00\r\n1 cucchiaino e 1\/2 di lievito per dolci\r\n2 cucchiai di pangrattato\r\nprezzemolo tritato, pi\u00c3\u00b9 altro per guarnire\r\n3 spicchi d\u00e2\u20ac\u2122aglio, pelati e schiacciati\r\nsale\r\npepe nero<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Accendete il forno a 210\u00c2\u00b0C.<\/p>\n<p style=\"text-align: justify;\">In una larga padella dal fondo spesso, scaldate il goccio di olio e, quando \u00c3\u00a8 caldo, fatevi stufare la cipolla, a fuoco medio, fino a quando diventer\u00c3\u00a0 morbida e cremosa, senza scurire.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo, tagliate le melanzane in due per il lungo, poi a tocchetti e poi a strisce di circa 1 cm di larghezza.<\/p>\n<p style=\"text-align: justify;\">Aggiungetele alla padella con la cipolla e fate cuocere a fiamma medio-alta, mescolando di tanto in tanto, per circa 10-15 minuti, fino a quando le melanzane diventeranno tenerissime.<\/p>\n<p style=\"text-align: justify;\">Aggiungete, se \u00c3\u00a8 il caso, un goccio d\u00e2\u20ac\u2122olio, ma senza esagerare.<br \/>\nSpegnete il fuoco e mettete da parte.<\/p>\n<p style=\"text-align: justify;\">In una larga terrina, mescolate con una frusta le uova, la farina, il pane grattugiato, il lievito, il prezzemolo, l\u00e2\u20ac\u2122aglio schiacciato, il sale e una bella macinata di pepe.<br \/>\nAmalgamate bene il tutto, fino ad avere un composto morbido, poi aggiungetevi il mix di melanzane e cipolle.<\/p>\n<p style=\"text-align: justify;\">Coprite uno stampo con carta forno e versatevi il composto.<br \/>\nInfornate per 30-40 minuti: la superficie dovr\u00c3\u00a0 essere dorata e la frittata cotta anche all\u00e2\u20ac\u2122interno (fate una prova con uno stuzzicadenti, per verificare che le uova si siano ben rapprese)<\/p>\n<p style=\"text-align: justify;\">Sfornate e lasciate intiepidire, prima di sformare e trasferire su un piatto da portata.<\/p>\n<p style=\"text-align: justify;\">Servite la frittata tiepida o a temperatura ambiente, cosparsa con una leggera spolverata di prezzemolo tritato.<br \/>\nSi mantiene in frigo per due giorni.<\/p>\n<figure id=\"attachment_44810\" aria-describedby=\"caption-attachment-44810\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44810\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984034-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984034-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984034-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984034-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984034-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44810\" class=\"wp-caption-text\">Kuku light<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proseguo la raccolta di ulteriori ricettine ( secondi piatti ) decisamente leggere, che ho preparato in questi giorni.<\/p>\n","protected":false},"author":2,"featured_media":44811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,77,60,61],"tags":[257,265],"class_list":["post-44801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pesce","category-secondi_piatti","category-uova-formaggio","tag-light","tag-nascondo_le_verdure"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=44801"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44801\/revisions"}],"predecessor-version":[{"id":44822,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44801\/revisions\/44822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44811"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=44801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=44801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=44801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}