{"id":44724,"date":"2024-04-01T14:25:59","date_gmt":"2024-04-01T12:25:59","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=44724"},"modified":"2024-04-07T17:37:38","modified_gmt":"2024-04-07T15:37:38","slug":"pasquetta_2024","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/04\/01\/pasquetta_2024\/","title":{"rendered":"Pasquetta 2024"},"content":{"rendered":"<p style=\"text-align: justify;\">Per molti di voi la <strong>Pasquetta<\/strong> indica una gita fuori porta.<br \/>\nPer me il suo solo e vero significato e&#8217; quello della colazione.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Quest&#8217;anno ho tentato qualcosa di diverso dal solito, per lo meno per la sottoscritta.<\/p>\n<p style=\"text-align: justify;\">Come scrivevo precedentemente, non ho trovato nessuna colomba (ad un prezzo modico, ma anche non) e neppure uova di cioccolato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44726\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032383-e1712504127164-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032383-e1712504127164-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032383-e1712504127164-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032383-e1712504127164-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032383-e1712504127164-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Visto che non sono una cima nella cottura della uova sode, ho tentato l&#8217;acquisto di una colazione (a buffet) con l&#8217;App &#8220;<strong>Too Good to go<\/strong>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Questa era in un albergo cosi&#8217;, per l&#8217;orario previsto, eravamo sul posto.<br \/>\nNon avendo fatto molto caso al nome dell&#8217;hotel, abbiamo sbagliato \ud83d\ude42 . Tanto che pensavo fosse un pesce di aprile \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">Ho preparato una scatola con delle brioche e del pain au chocolat, ma anche delle uova sode\/colorate, affettati.<br \/>\nIl &#8220;malloppo&#8221; e&#8217; quello postato nella foto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44728\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032479-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032479-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032479-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032479-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032479-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Logicamente e&#8217; stato integrato il tutto con prodotti casalinghi (treccia dolce, cioccolato e finocchiona), nonche&#8217; spumante, latte, caffe&#8217; e spremuta fresca di arance.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44727\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032407-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032407-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032407-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032407-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712130032407-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>E.. buona pasquetta a tutti!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per molti di voi la Pasquetta indica una gita fuori porta. Per me il suo solo e vero significato e&#8217; quello della colazione.<\/p>\n","protected":false},"author":2,"featured_media":44725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[62],"class_list":["post-44724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-pasqua"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=44724"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44724\/revisions"}],"predecessor-version":[{"id":44730,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44724\/revisions\/44730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44725"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=44724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=44724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=44724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}