{"id":44656,"date":"2024-03-29T12:02:59","date_gmt":"2024-03-29T11:02:59","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=44656"},"modified":"2024-03-21T17:59:49","modified_gmt":"2024-03-21T16:59:49","slug":"burger-buns_lievitazione-mista","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/03\/29\/burger-buns_lievitazione-mista\/","title":{"rendered":"Burger-Buns (lievitazione mista)"},"content":{"rendered":"<p style=\"text-align: justify;\">In previsione del BBQ a Pasqua, ma soprattutto pensando al ritorno del ragazzo dal Canada, ho provato a preparare questi <strong>Burger-Buns.<\/strong><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La ricetta e&#8217; stata presa dalla rivista Brot (03\/19) dove, mi sembra, ci sia anche un errore tra gli ingredienti.<\/p>\n<p style=\"text-align: justify;\">Ad ogni modo&#8230; questo e&#8217; stato il risultato (prima di surgelarli \ud83d\ude42 \ud83d\ude09 \ud83d\ude42 )<\/p>\n<p style=\"text-align: justify;\">Devo ammettere che l&#8217;impasto ottenuto e&#8217; stato veramente bello da sgonfiare, solitamente non mi succede mai \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44664\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Burger-Buns &#8211; 10 panini<\/strong> (circa 90gr cadauno)<\/p>\n<pre>400 gr di farina 405 (00 italiana)\r\n75gr di farina 1050\r\n35gr di Ruchmehl (eventualmente 1050)\r\n175gr di acqua fredda\r\n155gr di latte\r\n50gr di licoli (appena rinfrescato) (*)\r\n20gr di zucchero\r\n1,5 cucchiaio di olio (15gr)\r\n10gr di sale\r\n3 gr di lievito fresco di birra\r\n\r\n<strong>Inoltre<\/strong>\r\n 1 uovo\r\n un goccio di latte\r\n semi di sesamo<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mischiate il latte con l&#8217;acqua, lasciandone un goccio dove inserirete il sale.<\/p>\n<p style=\"text-align: justify;\">Nella ciotola della planetaria inserite il licoli, le farine, lo zucchero, il lievito di birra fresco e bagnate con il mix latte-acqua.<\/p>\n<p style=\"text-align: justify;\">Iniziate a lavorare l&#8217;impasto per una decina di minuti a bassa velocita&#8217;, poi aggiungete la restante acqua con sale, e proseguite.<br \/>\nQuando l&#8217;impasto incorda intorno al gangio, acciungete l&#8217;olio ed alzate la velocita&#8217;di poco, proseguendo fino a ciotola pulita.<br \/>\nPotete fare la prova velo, se volete (lo consiglio).<\/p>\n<p style=\"text-align: justify;\">A questo punto pirlate l&#8217;impasto sul piano da lavoro, leggermente unto, ed inseritelo in una ciotola, con coperchio, anche lei leggermente unta,<br \/>\nFate riposare a temperatura ambiente, dando un giro di pieghe ogni ora.<br \/>\nPotrebbe essere raddoppiato (o quasi) quindi decidete se proseguire o mettere in frigo per la notte (ho optato per questa possibilita&#8217;).<\/p>\n<p style=\"text-align: justify;\">L&#8217;indomani mattina, rimuovete la ciotola e fate acclimatare l&#8217;impasto qualche ora.<\/p>\n<p style=\"text-align: justify;\">Sgonfiatelo, e create delle palline (i burger buns) di circa 90-100gr cadauna.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44667\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684627-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684627-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684627-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684627-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684627-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Posizionateli sulla teglia (*), coperta da carta forno, lasciate a temperatura ambiente per la seconda lievitazione (circa 1,5-2 ore).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44665\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684607-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684607-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684607-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684607-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684607-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Preriscaldate il forno a 220gradi statico.<\/p>\n<p style=\"text-align: justify;\">Sbattete l&#8217;uovo con un goccio di latte, poi passate il liquido sui panini e decorateli con i semi di sesamo.<br \/>\nPrima di infornare, spruzzateli con acqua (*).<\/p>\n<p style=\"text-align: justify;\">In forno, a 220gradi, per circa 2 minuti.<br \/>\nAbbassate poi a 180gradi, proseguiendo per 10 minuti.<br \/>\nAbbassate a 160gradi per altri 5 minuti (nel caso in cui diventino troppo scuri, coprite con un foglio di alluminio.<\/p>\n<p style=\"text-align: justify;\">Rimuovete dal forno, spruzzateli nuovamente di acqua, e fate raffreddare<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44664\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684597-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Note Varie<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Se <strong>non si ha il lievito madre<\/strong>, inserite 7grammi di lievito di birra fresco<\/li>\n<li style=\"text-align: justify;\">Vi consiglio di preparare <strong>due teglie<\/strong>, cosi&#8217; da lasciare i panetti ben distanziati, evitando che si attacchino durante la cottura, come e&#8217; successo alla sottoscritta.<\/li>\n<li style=\"text-align: justify;\">Nonostante tutte le piante che possiedo, non ho uno <strong>spruzzino<\/strong> che funzioni. Per questo ho bagnato, in entrambi i casi, come se stessi benedicendo<\/li>\n<li>Queste le mie farine<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44671\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684677-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684677-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684677-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684677-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/03\/ok_1710954684677-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In previsione del BBQ a Pasqua, ma soprattutto pensando al ritorno del ragazzo dal Canada, ho provato a preparare questi Burger-Buns.<\/p>\n","protected":false},"author":2,"featured_media":44664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[117,116,112],"class_list":["post-44656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-bbq","tag-ldb","tag-licoli"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=44656"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44656\/revisions"}],"predecessor-version":[{"id":44679,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44656\/revisions\/44679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44664"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=44656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=44656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=44656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}