{"id":44384,"date":"2024-04-16T17:53:45","date_gmt":"2024-04-16T15:53:45","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=44384"},"modified":"2024-04-11T18:09:36","modified_gmt":"2024-04-11T16:09:36","slug":"ancora-carne","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/04\/16\/ancora-carne\/","title":{"rendered":"&#8230; ancora carne &#8230;"},"content":{"rendered":"<p style=\"text-align: justify;\">Non pensiate di perdere peso mangiando di meno del dovuto.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; mi e&#8217; parso di capire dalle intenzioni della mia nutrizionista che, per il prossimo mese, mi ha forzato ad attenermi rigorosamente alla quantita&#8217; e qualita&#8217; dei macroingredienti ingeriti.<\/p>\n<p>Diciamo che le mie difficolta&#8217; sono:<\/p>\n<ul>\n<li>non sempre ho voglia di cucinare, e mangerei qualcosa che trovo in frigorifero<br \/>\nla colazione, che faccio, ma non e&#8217; poi sempre cosi&#8217; dietetica (anche se ci tento veramente)<\/li>\n<li>il bere<\/li>\n<li>il fare movimento<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Cosi&#8217; cerco sempre delle alternative alle possibili tristezze della &#8220;bistecchina con verdure&#8221;.<br \/>\nEccezion fatta per il petto di pollo e di tacchino, dei quali ho delle porzioni veramente esagerate !<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/eatsmarter.de\/rezepte\/putenstreifen-mit-brokkoli-zitronen-sauce\">Straccetti di petto di tacchino con broccoli e salsa al limone<\/a><\/strong><\/em> &#8211; 2 persone<\/p>\n<pre>400 g di filetto di petto di tacchino\r\n400 g di broccoli\r\nsale\r\n1 limone bio\r\n1 spicchio d'aglio\r\nprezzemolo\r\n1 cucchiaio di olio di sesamo\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sciacquate il petto di tacchino sotto l&#8217;acqua fredda, asciugatelo e tagliatelo a listarelle.<br \/>\nLavate e pulite i broccoli, tagliateli a cimette e cuocerli in acqua bollente e leggermente salata per circa 5 minuti (*).<\/p>\n<p style=\"text-align: justify;\">Sciacquate il limone con acqua calda, asciugatelo, rimuovete la buccia e spremetene il succo.<br \/>\nSbucciete l&#8217;aglio e tritarlo molto finemente.<br \/>\nLavate il prezzemolo, asciugatelo e tritatelo finemente.<\/p>\n<p style=\"text-align: justify;\">Scaldate l&#8217;olio in una padella e &#8220;friggete&#8221; le strisce di tacchino fino a doratura, per 2-3 minuti.<br \/>\nCondite con sale e pepe.<br \/>\nSfumate con il succo di limone e un goccio d&#8217;acqua se necessario, aggiungete i broccoli, la scorza del limone e l&#8217;aglio. Cuocete brevemente, aggiungete il prezzemolo e condite a piacere.<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Per i broccoli&#8230; potete optare per la versione <strong>surgelata<\/strong>. In questo caso scongelateli nella maniera piu&#8217; consona per voi (io in microonde)<\/li>\n<li style=\"text-align: justify;\">Potete aggiungere una pioggia di <strong>chili<\/strong> (o peperoncino) se preferite<\/li>\n<\/ul>\n<p>\u00e2\u20ac\u2039<\/p>\n<figure id=\"attachment_44403\" aria-describedby=\"caption-attachment-44403\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44403\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1708371919393-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1708371919393-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1708371919393-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1708371919393-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1708371919393-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44403\" class=\"wp-caption-text\">Straccetti di petto di tacchino con broccoli e salsa al limone<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Pollo alla bella Napoli<\/strong><\/p>\n<pre>400gr di petto di pollo\r\n2 spicchi di aglio\r\npomodori pelati\r\nfoglie di basilico\r\nolio\r\nolive nere\r\norigano\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Pulite il petto di pollo, disossatelo (se necessario) e ricavate delle fette.<br \/>\nSchiacciate l&#8217;aglio senza romperlo e fatelo rosolare in una padella con l&#8217;olio.<\/p>\n<p style=\"text-align: justify;\">Toglietelo dal tegame e fate dorare le fette di pollo da entrambe le parti.<\/p>\n<p style=\"text-align: justify;\">Aggiungete i pelati, salate, pepate e proseguite la cottura per 15 minuti a fuoco basso.<\/p>\n<p style=\"text-align: justify;\">Tritate il basilico e mescolatelo all&#8217;origano; distribuitelo sul pollo insieme alle olive snocciolate e tagliate a filetti.<\/p>\n<p style=\"text-align: justify;\">Cuocete ancora per un paio di minuti e servite ben caldo.<\/p>\n<figure id=\"attachment_44805\" aria-describedby=\"caption-attachment-44805\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44805\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712849222196-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712849222196-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712849222196-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712849222196-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712849222196-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44805\" class=\"wp-caption-text\">Pollo alla bella Napoli<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Sovraccoscia di pollo al forno con porro e carote<\/strong><\/p>\n<pre>sovraccoscia di pollo\r\nporro\r\ncarota\r\nolio\r\narancia (BIO)\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate a scaldare il forno, statico, a 180gradi.<\/p>\n<p style=\"text-align: justify;\">Lavate il porro e la carota, affettate il tutto finemente.<br \/>\nIn una teglia piccola da forno, inserite un goccio di olio e la verdura tagliata.<\/p>\n<p style=\"text-align: justify;\">Iniziate ad infornare per una decina di minuti, mescolando, cosi&#8217; da far appassire la verdura ma non farla attaccare e bruciare.<\/p>\n<p style=\"text-align: justify;\">Prendete la sovraccoscia, eliminate la pelle e l&#8217;eventuale grasso in eccesso.<br \/>\nSpremete l&#8217;arancia.<\/p>\n<p style=\"text-align: justify;\">Inserite la sovraccoscia nella teglia, salate, pepate, bagnate il tutto con il succo dell&#8217;arancio e decorate con una fettina.<\/p>\n<p style=\"text-align: justify;\">Fate cuocere la carne, rigirandola verso meta&#8217; cottura.<\/p>\n<p style=\"text-align: justify;\">Servite ben calda la carne, con le sue verdurine ed il suo sughetto.<\/p>\n<figure id=\"attachment_44807\" aria-describedby=\"caption-attachment-44807\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44807\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712652216197-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712652216197-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712652216197-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712652216197-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712652216197-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44807\" class=\"wp-caption-text\">Sovraccoscia di pollo al forno con porro e carote<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Polpette\/hamburger di pollo<\/strong><\/p>\n<pre>200gr di macinato di pollo\r\n1 cipolla\r\n1 carota\r\n1 cucchiaio di pangrattato\r\n1 cucchiaio di curry\r\nprezzemolo\r\nolio\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Pulite ed affettate finemente la cipolla e la carota.<br \/>\nIn una ciotola abbastanza capiente, mescolate a mano tutti gli ingredienti: la trita di pollo, la cipolla, la carota, il pangrattato, il curry, il prezzemolo, sale e pepe.<\/p>\n<p style=\"text-align: justify;\">Con le mani bagnate, preparate delle polpettine, o un unico hamburger.<\/p>\n<p style=\"text-align: justify;\">Disponete il tutto su una teglia da forno, coperta di carta.<br \/>\nAiutandovi con un pennellino, distribuite l&#8217;olio sulla carne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44812\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984082-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984082-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984082-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984082-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850984082-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Infornate a forno caldo, 180gradi statico, per circa 25-30 minuti (dipende dalla dimensione che darete alla vostra preparazione).<\/p>\n<p>Servite caldo.<\/p>\n<figure id=\"attachment_44808\" aria-describedby=\"caption-attachment-44808\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44808\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850384259-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850384259-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850384259-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850384259-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/04\/ok_1712850384259-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44808\" class=\"wp-caption-text\">Hamburger di pollo al curry<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non pensiate di perdere peso mangiando di meno del dovuto.<\/p>\n","protected":false},"author":2,"featured_media":44805,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[257,265,49,183],"class_list":["post-44384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti","tag-light","tag-nascondo_le_verdure","tag-ww","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=44384"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44384\/revisions"}],"predecessor-version":[{"id":44813,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44384\/revisions\/44813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44805"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=44384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=44384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=44384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}