{"id":44269,"date":"2024-02-23T15:43:43","date_gmt":"2024-02-23T14:43:43","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=44269"},"modified":"2024-02-06T17:40:19","modified_gmt":"2024-02-06T16:40:19","slug":"carote-e-porri-al-limone","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/02\/23\/carote-e-porri-al-limone\/","title":{"rendered":"Crema di carote e porri al limone"},"content":{"rendered":"<p style=\"text-align: justify;\">Ecco una <strong>crema di carote e porri<\/strong> leggera, ottima per il pasto nella stessa giornata della pizza.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nMa anche per scaldare le lunghe serate fredde, con una spinta vitaminica in piu&#8217;, data dall&#8217;agrume presente.<\/p>\n<figure id=\"attachment_44286\" aria-describedby=\"caption-attachment-44286\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44286\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1707230185383-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1707230185383-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1707230185383-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1707230185383-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1707230185383-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44286\" class=\"wp-caption-text\">Crema di carote e porri al limone<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; Crema di carote e porri al limone<\/strong> &#8211; 3-4 persone<\/p>\n<pre>600-800gr di carote\r\nun limone BIO (serve la buccia!)\r\n1 porro (o 2 cipollotti)\r\nriso\r\n1 litro brodo vegetale\r\nolio\r\npepe\r\n\r\n<strong>Per decorare<\/strong>\r\n erba cipollina<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p>Pulite le carote ed i porri\/cipollotti e affettateli.<br \/>\nGrattugiate la scorza di mezzo limone e spremetelo.<br \/>\nPelate al vivo la meta&#8217; rimasta e tagliatela a dadini.<\/p>\n<p>Portate ad ebollizione il brodo, unote le verdure e cuocete su fiamma vivace, parzialmente coperto, per circa 20 minuti.<\/p>\n<p>Aggiungete la scorza ed il succo di limone e rfullate.<\/p>\n<p>Nel frattempo lessate il riso, scolatelo al dente e conditelo con un cucchiaio di olio, un poco di erba cipollina tagliuzzata e la polpa del linome.<\/p>\n<p>Versate la zuppa nelle ciotole, disponete al centro il riso e condite con un filo d&#8217;olio e una macinata di pepe.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Se preferite un sapore piu&#8217; <strong>dolce<\/strong>, e&#8217; meglio orientarsi sui cipollotti, tralasciando il porro<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco una crema di carote e porri leggera, ottima per il pasto nella stessa giornata della pizza.<\/p>\n","protected":false},"author":2,"featured_media":44286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,51,57],"tags":[257,256],"class_list":["post-44269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-primi_piatti","category-zuppa","tag-light","tag-vegetariano"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=44269"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44269\/revisions"}],"predecessor-version":[{"id":44287,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44269\/revisions\/44287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44286"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=44269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=44269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=44269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}