{"id":44143,"date":"2024-02-13T12:15:01","date_gmt":"2024-02-13T11:15:01","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=44143"},"modified":"2024-01-30T17:17:55","modified_gmt":"2024-01-30T16:17:55","slug":"spaccatelle_ldb_giornata","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/02\/13\/spaccatelle_ldb_giornata\/","title":{"rendered":"Spaccatelle di pasta dura &#8211; ldb fresco &#8211; In giornata"},"content":{"rendered":"<p style=\"text-align: justify;\">Questa notte stavo giusto pensando al fatto di voler preparare del pane, ma non sapevo ancora quale.<br \/>\nIn effetti ce ne sono cosi&#8217; tanti tipi diversi, che una persona rimane confusa.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">A togliermi dai pensieri e&#8217; stata Mara, che mi ha spedito un link da IG ( da lericettedimamma_gy ), di un pane velocissimo, anche se con 20gr di lievito di birra fresco.<br \/>\nPer me questa quantita&#8217; e&#8217; veramente tanta&#8230; ma ho seguito ugualmente le istruzioni arrivando a questo risultato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44150\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720846-e1706631254767-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720846-e1706631254767-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720846-e1706631254767-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720846-e1706631254767-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720846-e1706631254767-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; <em><a href=\"https:\/\/www.lericettedimammagy.com\/ricetta\/caravanini-pagnotte-di-pasta-dura\/\">Spaccatelle di pasta dura<\/a><\/em><\/strong> &#8211; 6 panini<\/p>\n<pre>550gr farina 00\r\n300gr di acqua tiepida\r\n15gr di sale\r\n20 gr di lievito di birra fresco\r\nmezzo cucchiaino di zucchero\r\n20ml di olio (evo)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sciogliete il lievito in 30ml di acqua presa dal totale ed aggiungete lo zucchero, mescolando.<br \/>\nSciogliete il sale in poca acqua, presa dal totale, nella restante acqua unite l&#8217;olio.<\/p>\n<p style=\"text-align: justify;\">Nella ciotola della planetaria inserite la farina e, con il gancio, iniziate ad impastare unendo il lievito e la sua acqua zuccherata.<br \/>\nAggiungete l&#8217;acqua e l&#8217;olio, procedendo con il gancio.<br \/>\nPer ultimo il sale con il restante goccio di acqua.<\/p>\n<p style=\"text-align: justify;\">Continuate fino a quando l&#8217;impasto non si sara&#8217; staccato dalla parete della ciotola ed avra&#8217; passato il window-test , ci vorranno circa 15 minuti.<\/p>\n<p style=\"text-align: justify;\">Quando l&#8217;impasto sara&#8217; pronto, lavoratelo subito senza farlo lievitare.<br \/>\nTagliate l&#8217;impasto in 6 parti uguali.<\/p>\n<p style=\"text-align: justify;\">Con il mattarello appiattite un pezzo di pasta e poi arrotolatelo su se stesso, fino ad ottenere un rotolo lungo e stretto<br \/>\nRuotate l&#8217;impasto di novanta gradi, schiacciate nuovamente il rotolo con il mattarello fino ad ottenere una striscia piatta e lunga di pasta.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44154\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720922-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720922-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720922-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720922-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720922-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nArrotolate nuovamente su se stessa fino, poi effettuate la stessa operazione un&#8217;altra volta (in tutto 3 giri).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44160\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720936-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720936-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720936-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720936-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720936-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Coprite bene con un canovaccio e lasciate lievitare per circa 50 minuti.<br \/>\nCon un coltello molto affilato o una lametta effettuate un taglio profondo nel centro di ogni panino<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44153\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720886-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720886-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720886-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720886-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720886-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Infornate nel forno statico preriscaldato, a 220gradi per circa 30-40 minuti (dipende dal vostro forno).<\/p>\n<p style=\"text-align: justify;\">Fate raffreddare e, nell&#8217;attesa, meditate su come riempirlo!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44152\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720870-e1706631266229-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720870-e1706631266229-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720870-e1706631266229-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720870-e1706631266229-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1706543720870-e1706631266229-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Nella ricetta originale la cottura e&#8217; stimata a 40\/45 minuti. O il mio forno cuoce troppo o non saprei&#8230; ho preferito diminuire il tempo, <strong>guardando a vista<\/strong> il prodotto.<\/li>\n<li style=\"text-align: justify;\">Onestamente il risultato non e&#8217; stato male, peccato per l&#8217;<strong>enorme<\/strong> quantita&#8217; di lievito utilizzato.<\/li>\n<li style=\"text-align: justify;\">Assomigliano molto alle <strong>mantovane<\/strong>, nonostante contengano olio.<\/li>\n<li style=\"text-align: justify;\">I Caravanini o Mantovanine, Spaccatelle sono dei deliziosi panini di pasta dura tipici del nord Italia.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa notte stavo giusto pensando al fatto di voler preparare del pane, ma non sapevo ancora quale. In effetti ce ne sono cosi&#8217; tanti tipi diversi, che una persona rimane confusa.<\/p>\n","protected":false},"author":2,"featured_media":44151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[116],"class_list":["post-44143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=44143"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44143\/revisions"}],"predecessor-version":[{"id":44163,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44143\/revisions\/44163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44151"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=44143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=44143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=44143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}