{"id":44077,"date":"2024-01-25T14:21:36","date_gmt":"2024-01-25T13:21:36","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=44077"},"modified":"2024-01-22T18:24:30","modified_gmt":"2024-01-22T17:24:30","slug":"insalata-di-gamberi-e-zucchine","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/01\/25\/insalata-di-gamberi-e-zucchine\/","title":{"rendered":"Insalata di gamberi e zucchine"},"content":{"rendered":"<p style=\"text-align: justify;\">Se cercate un secondo piatto sfizioso, con poche calorie e tante proteine, allora siete approdati nel Post giusto \ud83d\ude42<\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_44092\" aria-describedby=\"caption-attachment-44092\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44092\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705853339080-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705853339080-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705853339080-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705853339080-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705853339080-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44092\" class=\"wp-caption-text\">Insalata di gamberi e zucchine<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Insalata di gamberi e zucchine<\/strong> &#8211; 2 persone<\/p>\n<pre>200gr di gamberi\r\ninsalata verde mista (o anche no)\r\n400gr di zucchine\r\n\r\n<strong>Salsina<\/strong> (indicativamente, dipende dal gusto)\r\n 1 cucchiaio di capperi\r\n 1 limone (succo)\r\n 1 scalogno\r\n 1 cucchiaino di senape\r\n prezzemolo\r\n 2 cucchiaini di olio\r\n sale\r\n pepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lessate i gamberi in acqua salata per 2 minuti, unite la zucchina a tocchetti e cuocete, finche&#8217; saranno tenere.<br \/>\nSgocciolateli e mescolateli alle insalate lavate ed asciugate.<\/p>\n<p style=\"text-align: justify;\"><strong>Per la salsa<\/strong><br \/>\nFrullate i capperi (eventualmente dissalati) con il succo del limone, lo scalogno, il prezzemolo, la senape, l&#8217;olio, sale e pepe.<\/p>\n<p style=\"text-align: justify;\">Condite l&#8217;insalata ed i gamberi con la salsina preparata.<\/p>\n<p style=\"text-align: justify;\">Noi abbiamo mangiato con gusto questo piatto, soprattutto grazie alla sfiziosa salsina che ha donato un tocco di personalita&#8217;.<\/p>\n<p style=\"text-align: justify;\">Cosa ne pensate?<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se cercate un secondo piatto sfizioso, con poche calorie e tante proteine, allora siete approdati nel Post giusto \ud83d\ude42<\/p>\n","protected":false},"author":2,"featured_media":44092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,77,60],"tags":[257,49],"class_list":["post-44077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pesce","category-secondi_piatti","tag-light","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=44077"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44077\/revisions"}],"predecessor-version":[{"id":44093,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44077\/revisions\/44093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44092"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=44077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=44077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=44077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}