{"id":44055,"date":"2024-01-31T12:27:38","date_gmt":"2024-01-31T11:27:38","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=44055"},"modified":"2024-01-12T17:32:02","modified_gmt":"2024-01-12T16:32:02","slug":"ciambella-ricotta-frutti_bosco","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/01\/31\/ciambella-ricotta-frutti_bosco\/","title":{"rendered":"Ciambella di ricotta e frutti di bosco"},"content":{"rendered":"<p style=\"text-align: justify;\">Quando sei a dieta ma hai le voglie&#8230; non puoi proprio rinunciare e le devi soddisfare, cercando di limitarti al massimo, altrimenti vivi male.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Senza contare che, nella stragrande maggioranza dei regimi alimentari controllati, esiste sempre il &#8220;pasto libero&#8221; dove e&#8217; consentito mangiare una fetta di torta.<\/p>\n<p style=\"text-align: justify;\">OK, onestamente avevo acquistato della ricotta in surplus proprio perche&#8217; era mia intenzione preparare una crostata.<br \/>\nAdoro le crostate, in ogni declinazione.<br \/>\nPeccato per il resto della famiglia che non e&#8217; della stessa idea.<\/p>\n<figure id=\"attachment_44066\" aria-describedby=\"caption-attachment-44066\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44066\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871583-694x1024.jpg\" alt=\"\" width=\"525\" height=\"775\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871583-694x1024.jpg 694w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871583-102x150.jpg 102w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871583-203x300.jpg 203w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871583-768x1134.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44066\" class=\"wp-caption-text\">Ciambella di ricotta e frutti di bosco<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Quindi, per evitare di doverla surgelare per tanto (troppo) tempo, sebbene affettata, ho dovuto cambiare a malincuore idea.<\/p>\n<p style=\"text-align: justify;\"><em>(Visto il risultato ottenuto, non direi che il mio lascito e&#8217; stato proprio con nostalgia..)<\/em><\/p>\n<p style=\"text-align: justify;\">Ho trovato quindi questa &#8220;<strong>Ciambella di ricotta e frutti di bosco<\/strong>&#8221; , nel gruppo FB che seguo, postata da<em> Antonella Audino<\/em> (Dal blog Dolci Follie).<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Ciambella di ricotta e frutti di bosco<\/strong> &#8211; Stampo di circa 26 cm di diametro<\/p>\n<pre>300 g di farina 00\r\n100 g di farina di mandorle\r\n250 g di ricotta vaccina\r\n140 g di zucchero semolato\r\n4 uova\r\n100 ml di olio di semi di girasole (*)\r\n16 g di lievito (*)\r\n30 ml di latte\r\nla scorza grattugiata di un limone\r\n150 g di frutti di bosco misti (*)\r\nfrutti di bosco misti per la decorazione<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavorate con le fruste la ricotta e lo zucchero.<br \/>\nInserite le uova uno alla volta, aggiungete le due farine precedentemente setacciate con il lievito e amalgamate bene. Incorporate la scorza e l\u00e2\u20ac\u2122olio a filo, il latte e infine aggiungete molto delicatamente i frutti di bosco.<br \/>\nVersate il composto in uno stampo precedentemente imburrato e infarinato, livellate bene e infornate a 180\u00c2\u00b0 per 40\u00e2\u20ac\u2122\/45\u00e2\u20ac\u00b2 circa.<\/p>\n<p style=\"text-align: justify;\">Verificate la cottura con la prova stuzzicadenti prima di sfornare la torta.<\/p>\n<p style=\"text-align: justify;\">Una volta raffreddata completamente sformate la vostra ciambella e decorate a piacere con tanti frutti di bosco e, se vi piace, anche una spolverata di zucchero a velo.<\/p>\n<figure id=\"attachment_44065\" aria-describedby=\"caption-attachment-44065\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44065\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871572-1024x587.jpg\" alt=\"\" width=\"525\" height=\"301\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871572-1024x587.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871572-150x86.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871572-300x172.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1705075871572-768x441.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-44065\" class=\"wp-caption-text\">Ciambella di ricotta e frutti di bosco<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">L&#8217;olio di girasole e&#8217; stato sostituito da <strong>olio di riso<\/strong><\/li>\n<li style=\"text-align: justify;\">il lievito utilizzato era una bustina, da noi si trovano di <strong>15gr<\/strong><\/li>\n<li style=\"text-align: justify;\">i frutti di bosco utilizzati dalla sottoscritta erano <strong>surgelati<\/strong>.<\/li>\n<li style=\"text-align: justify;\">Il risultato e&#8217; stata una torta morbida ma asciutta il giusto, dalla crosticina croccante che va giu&#8217; che e&#8217; un piacere!<\/li>\n<\/ul>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando sei a dieta ma hai le voglie&#8230; non puoi proprio rinunciare e le devi soddisfare, cercando di limitarti al massimo, altrimenti vivi male.<\/p>\n","protected":false},"author":2,"featured_media":44065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[107,106],"class_list":["post-44055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-torte","tag-frutta","tag-ricetta_perfetta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=44055"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44055\/revisions"}],"predecessor-version":[{"id":44069,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/44055\/revisions\/44069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44065"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=44055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=44055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=44055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}