{"id":43896,"date":"2024-03-02T12:06:59","date_gmt":"2024-03-02T11:06:59","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43896"},"modified":"2024-02-18T18:08:40","modified_gmt":"2024-02-18T17:08:40","slug":"contorni-unici-leggeri-idee","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/03\/02\/contorni-unici-leggeri-idee\/","title":{"rendered":"Contorni (o piatti unici) leggeri \u00e2\u20ac\u201c idee"},"content":{"rendered":"<p style=\"text-align: justify;\">Sicuramente, in mezzo a tutta questa leggerezza di piatti, non potevo dimenticare di inserire delle idee leggere, ed alternative, per i <strong>contorni<\/strong> e le verdure.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Come anticipato, ecco una breve carrellata di nuove proposte<\/p>\n<p><strong>Ingredienti &#8211; Carote al marsala<\/strong><\/p>\n<pre>800gr di carote\r\n4 cucchiaini di olio\r\n4 cucchiaini di marsala\r\nprezzemolo tritato\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Pulite le carote e tagliatele a fettine sottili, mettetele in un tegame inaderente con l&#8217;olio, sale e pepe e, mescolando, cuocete per alcuni minuti.<br \/>\nUnite il marsala e portate a cottura aggiungendo poca acqua quando occorre.<br \/>\nPoco prima di toglierle dal fuoco, unite il prezzemolo tritato.<\/p>\n<figure id=\"attachment_43986\" aria-describedby=\"caption-attachment-43986\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-43986\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1704633770947-1024x749.jpg\" alt=\"\" width=\"525\" height=\"384\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1704633770947-1024x749.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1704633770947-150x110.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1704633770947-300x220.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1704633770947-768x562.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-43986\" class=\"wp-caption-text\">Carote al marsala<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Insalata con arance e finocchi, con gamberetti<\/strong> &#8211; 4 persone<\/p>\n<pre>1 cucchiaio di pinoli \/ filetti di mandorle\r\n1 cucchiaino di semi di finocchio\r\n2 finocchi\r\n3 arance bionde\r\n1 cipolla rossa\r\n4 cucchiai d\u00e2\u20ac\u2122olio d\u00e2\u20ac\u2122oliva\r\n2 cucchiai di Condimento bianco\r\nsale\r\npepe\r\n100 g d\u00e2\u20ac\u2122olive , ad es. Kalamata\r\n450 g di gamberetti tail-on<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Tostate i pinoli\/filetto di mandorle in una padella antiaderente senza grassi e metteteli da parte.<br \/>\nTostate brevemente anche i semi di finocchio poi pestateli finemente in un mortaio.<br \/>\nTagliate il finocchio per il lungo a fettine sottili con una mandolina e mettete da parte i ciuffi verdi (per decorazione).<br \/>\nPelate al vivo due terzi delle arance poi tagliatele a fette. Spremete l\u00e2\u20ac\u2122arancia rimasta. Dividete la cipolla in spicchi.<\/p>\n<p style=\"text-align: justify;\">Mescolate la met\u00c3\u00a0 dell\u00e2\u20ac\u2122olio con l\u00e2\u20ac\u2122aceto ed il succo d\u00e2\u20ac\u2122arancia, poi condite con sale e pepe.<br \/>\nDisponete nei piatti le arance, i finocchi, le cipolle e le olive e irrorate con poca salsa.<\/p>\n<p style=\"text-align: justify;\">Rosolate i gamberetti nell\u00e2\u20ac\u2122olio rimato, conditeli con sale, pepe ed i semi di finocchio poi bagnateli con la salsa rimasta.<br \/>\nDistribuite i gamberetti sull\u00e2\u20ac\u2122insalata e insaporite con la salsa.<br \/>\nGuarnite con le foglie verdi dei finocchi, i pinoli\/filetti di mandorle e un pizzico di pepe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44265\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1706900311878-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1706900311878-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1706900311878-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1706900311878-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_1706900311878-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Sedano in padella<\/strong><\/p>\n<pre>sedano rapa\r\n\u00c2\u00bd cipolla\r\n1 cucchiaio senape\r\n\u00c2\u00bd bicchiere acqua\r\nprezzemolo\r\nolio\r\nsale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavate il sedano rapa e tamponatelo con carta da cucina.<br \/>\nEliminate la buccia con un coltello e tagliate a tocchetti la polpa.<br \/>\nMondate e affettate la cipolla in modo grossolano.<br \/>\nVersate un filo di olio in padella e lasciate rosolare la cipolla per un paio di minuti<br \/>\nAggiungete i tocchetti di sedano rapa, lasciate saltare per qualche minuto e insaporite con un po&#8217; di sale<\/p>\n<p style=\"text-align: justify;\">Versate l&#8217;acqua e fate cuocere in padella per 10-15 minuti a fuoco medio<br \/>\nUnite la senape e continuate la cottura per almeno 5 minuti<br \/>\nImpiattate e servite il sedano rapa in padella, aggiungendo una manciata di prezzemolo tritato<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-44352\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_IMG_20240209_182946-01-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_IMG_20240209_182946-01-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_IMG_20240209_182946-01-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_IMG_20240209_182946-01-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/02\/ok_IMG_20240209_182946-01-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Insalata con cavolo rapa (Kohlrabi)<\/strong> &#8211; 2 persone<\/p>\n<pre>1 scalogno piccolo\r\n200 g di cavolo rapa piccolo (1 cavolo rapa piccolo)\r\n1 finocchio\r\npepe\r\nolio d'oliva\r\nsale\r\n3 cucchiai di aceto di mele\r\n\u00c2\u00bd cucchiaino di senape\r\n1 cucchiaino di miele liquido<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mondate lo scalogno e tagliatelo a dadini fini. Mettetelo in un colino fine e versatevi sopra l&#8217;acqua bollente.<\/p>\n<p style=\"text-align: justify;\">Sbucciate e pulite il cavolo rapa, lavate e pulite il finocchio. Tagliateli entrambi a cubetti.<br \/>\nMescolate l&#8217;aceto, la senape, il miele e l&#8217;olio in una piccola ciotola.<br \/>\nMescolate il cavolo rapa, il finocchio, lo scalogno con la salsa.<\/p>\n<p style=\"text-align: justify;\">(Foto della preparazione non pervenuta :)\u00c2\u00a0 :)\u00c2\u00a0 )<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sicuramente, in mezzo a tutta questa leggerezza di piatti, non potevo dimenticare di inserire delle idee leggere, ed alternative, per i contorni e le verdure.<\/p>\n","protected":false},"author":2,"featured_media":44266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22,77],"tags":[257,49],"class_list":["post-43896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food","category-pesce","tag-light","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43896"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43896\/revisions"}],"predecessor-version":[{"id":44385,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43896\/revisions\/44385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/44266"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}