{"id":43805,"date":"2024-01-17T12:38:25","date_gmt":"2024-01-17T11:38:25","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43805"},"modified":"2023-12-15T17:40:54","modified_gmt":"2023-12-15T16:40:54","slug":"pane-integrale-di-farro","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/01\/17\/pane-integrale-di-farro\/","title":{"rendered":"Pane integrale di farro"},"content":{"rendered":"<p style=\"text-align: justify;\">Oramai Stephan si sta abituando bene con il pane sempre fresco a casa.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Ed io non ne posso che essere felice.<\/p>\n<p style=\"text-align: justify;\">Oggi ho provato la preparazione di questo &#8220;<strong>Pane integrale di farro<\/strong>&#8220;, tratto dal libro &#8220;<em>La mia Pasta Madre &#8211; Il pane, i dolci, la vita in montagna<\/em>&#8221; di Vea Carpi .<\/p>\n<p style=\"text-align: justify;\">Diciamo che ho iniziato a seguire anche il procedimento, alla fine ho fatto (decisamente) come ho voluto io, stravolgendo il tutto.<br \/>\nIn effetti ho lasciato integro solo la quantita&#8217; e l&#8217;inizio della preparazione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43810\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367765-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367765-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367765-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367765-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367765-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Pane integrale di farro<\/strong> &#8211; 1 pagnotta<\/p>\n<pre><strong>Lievitino<\/strong>\r\n 20gr pasta madre rinfrescata\r\n 50gr farina\r\n 45gr acqua\r\n\r\n<strong>Impasto<\/strong>\r\n tutto il lievitino\r\n 150gr farina 0\r\n 350gr farina (integrale) di farro\r\n 450gr acqua\r\n 9gr sale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Lievitino<\/strong> &#8211; la sera precedente<br \/>\nImpastate bene gli ingredienti e lasciate riposare l\u00e2\u20ac\u2122impasto tutta la notte coperto.<\/p>\n<p style=\"text-align: justify;\"><strong>Impasto<\/strong><br \/>\nAl mattino (o comunque dopo 8 ore circa) aggiungete la farina 0, la farina integrale di farro e l&#8217;acqua al lievitino (che nel frattempo si sar\u00c3\u00a0 riempito di bolle).<\/p>\n<p style=\"text-align: justify;\">Date una prima, veloce impastata, fino a che la farina non avr\u00c3\u00a0 assorbito l\u00e2\u20ac\u2122acqua.<\/p>\n<p style=\"text-align: justify;\">Lasciate in autolisi per mezz\u00e2\u20ac\u2122ora.<br \/>\nPassata la mezz\u00e2\u20ac\u2122ora di autolisi aggiungete il sale e bagnate l\u00e2\u20ac\u2122impasto con un po\u00e2\u20ac\u2122 di acqua.<br \/>\nFinite di impastare, fino ad avere un impasto morbido, liscio e compatto.<\/p>\n<p style=\"text-align: justify;\">Fate dei giri di pieghe S&amp;F a 30-60-90 minuti, lasciando l&#8217;impasto a temperatura ambiente.<\/p>\n<p style=\"text-align: justify;\">Personalmente mi e&#8217; risultato un impasto veramente molto liquido, nonostante le pieghe.<br \/>\nL&#8217;impasto era molto incordato fino all&#8217;inserimento del sale poi, unendo 30ml di acqua, si e&#8217; disperso.<\/p>\n<p style=\"text-align: justify;\">A questo punto ho deciso di tentare di formarlo subito, inserendolo in una cestino di lievitazione rettangolare.<\/p>\n<p style=\"text-align: justify;\">Lasciate lievitare per circa un\u00e2\u20ac\u2122ora, poi riponete l\u00e2\u20ac\u2122impasto in un luogo fresco (frigorifero) per altre 24 ore.<\/p>\n<p style=\"text-align: justify;\">Il mattino successivo, giorno di cottura, tirate fuori l\u00e2\u20ac\u2122impasto dal frigo ed infornate immediatamente in forno pre-riscaldato (passaggio frigo-forno).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43811\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367780-e1702658256809-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367780-e1702658256809-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367780-e1702658256809-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367780-e1702658256809-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1702657367780-e1702658256809-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Infornate a 220 gradi per i primi 15 minuti, poi abbassate a 200 gradi per un\u00e2\u20ac\u2122altra mezz\u00e2\u20ac\u2122ora.<\/p>\n<p style=\"text-align: justify;\">Il risultato ottenuto, almeno per me, e&#8217; stato quello di un &#8220;disco volante&#8221;, come potete notare dalla foto.<br \/>\nAd ogni modo, dopo il taglio, era abbastanza bucoso e dal buon sapore.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oramai Stephan si sta abituando bene con il pane sempre fresco a casa.<\/p>\n","protected":false},"author":2,"featured_media":43810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[112],"class_list":["post-43805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-licoli"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43805"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43805\/revisions"}],"predecessor-version":[{"id":43812,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43805\/revisions\/43812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/43810"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}