{"id":43626,"date":"2023-12-06T12:10:39","date_gmt":"2023-12-06T11:10:39","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43626"},"modified":"2023-12-03T19:21:22","modified_gmt":"2023-12-03T18:21:22","slug":"gulash-di-cervo","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/12\/06\/gulash-di-cervo\/","title":{"rendered":"Gulash di cervo"},"content":{"rendered":"<p style=\"text-align: justify;\">Ho acquistato dello <strong>spezzatino di cervo<\/strong>, pensando di prepararlo nelle fredde giornate invernali.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">E la situazione piu&#8217; opportuna e&#8217; arrivata: domenica 3 dicembre, con un tiepido sole ed una tregua alla nevicata eccezionale che si e&#8217; svolta la notte precedente.<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda le temperature?<br \/>\nDiciamo che e&#8217; stato il momento adatto, essendo grandemente al di sotto dello ZERO.<\/p>\n<p style=\"text-align: justify;\">Ed ora, eccomi ai fornelli.<\/p>\n<figure id=\"attachment_43667\" aria-describedby=\"caption-attachment-43667\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-43667\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840982-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840982-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840982-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840982-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840982-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-43667\" class=\"wp-caption-text\">Gulash di cervo con polenta<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Gulash di cervo<\/strong> &#8211; 4 persone<\/p>\n<pre>600gr di polpa di cervo tagliata a cubi\r\n2 cipolle grandi\r\n1 bicchiere di passata di pomodoro\r\n1 cucchiaio di farina\r\n1 spicchio di aglio\r\n1 foglia di alloro\r\ntimo\r\nrosmarino\r\nsemi di cumino\r\n5-6 bacche di ginepro\r\n1 cucchiaio di paprica dolce\r\n1\/5 litro di brodo (*)\r\n1\/2 bicchiere di vino rosso (*)\r\n1 cucchiaio di strutto\r\nsale\r\npepe<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sbucciate le cipolle e tritatele.<br \/>\nScaldate lo strutto in un tegame, unite le cipolle e fatele appassire a fuoco dolce per 8-10 minuti, mescolando.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43671\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841034-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841034-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841034-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841034-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841034-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete la carne, gli aromi (timo, alloro e rosmarino) e fate rosolare per una decina di minuti a fuoco medio-alto, facendo attenzione a non bruciare le cipolle.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43670\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841018-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841018-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841018-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841018-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625841018-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Spolverizzate la carne con il cucchiaio di farina e mescolate per alcuni istanti.<br \/>\nBagnate con il vino, fate evaporare completamente poi unite la paprica, il cumino, l&#8217;aglio (tritato se lo gradite), le bacche di ginepro e la conserva di pomodoro.<br \/>\nRegolate di sale e pepe, mescolate ed aggiungete 2-3 mestoli di brodo bollente.<\/p>\n<p style=\"text-align: justify;\">Mettete il coperchio e cuocete a fuoco dolce per non meno di 2 ore, aggiungendo altro brodo se necessario, fino a quando il fondo di cottura risultera&#8217; denso.<\/p>\n<p style=\"text-align: justify;\">Servitelo caldo.<\/p>\n<figure id=\"attachment_43668\" aria-describedby=\"caption-attachment-43668\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-43668\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840994-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840994-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840994-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840994-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/12\/ok_1701625840994-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-43668\" class=\"wp-caption-text\">Gulash di cervo con polenta<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Potete servirlo con patate lessate, speatzle, knodel, pure&#8217; o polenta.<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\">Avendo tempo, ho preferito utilizzare la <strong>dutch oven<\/strong> al posto della pentola a pressione, cosi&#8217; da cuocere lentamente.<\/li>\n<li style=\"text-align: justify;\">Non avendo vino rosso per casa, ho <strong>bagnato<\/strong> con del brodo<br \/>\nIl brodo da me acquistato era di <strong>selvaggina<\/strong>, se non lo avete potete usare anche quello fatto di dado.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Per la polenta, ho seguito la mia ricetta preparandola con la pentola a pressione.<\/p>\n<p><strong>Ingredienti \u00e2\u20ac\u201c Polenta<\/strong><\/p>\n<pre>farina fioretto ( 1 misurino )\r\nacqua (4 misurini)\r\nsale\r\nolio<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Portate a bollore l\u00e2\u20ac\u2122acqua (in proporzione 4:1 rispetto alla farina) con il sale ed un goccio di olio.<br \/>\nButtate la farina tutta in una volta, e mescolate con una frusta cosi\u00e2\u20ac\u2122 da non creare grumi.<br \/>\nAbbassate al minimo e mettete il coperchio alla pentola.<br \/>\nPortate a bollore il contenuto della pentola a pressione, ma mantenendo la temperatura del gas al minimo.<br \/>\nAl fischio riducete ancora di piu\u00e2\u20ac\u2122 il fuoco se riuscite (o spegnete temporaneamente) cosi\u00e2\u20ac\u2122 che si stabilizzi.<br \/>\nCuocete per 20minuti se vi piace un po\u00e2\u20ac\u2122 morbida, dai 22-24 se la preferite un po\u00e2\u20ac\u2122 piu\u00e2\u20ac\u2122 soda.<br \/>\nLasciate sfiatare un attimo, prima di forzare l\u00e2\u20ac\u2122apertura del coperchio.<\/p>\n<p>Alla prossima!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ho acquistato dello spezzatino di cervo, pensando di prepararlo nelle fredde giornate invernali.<\/p>\n","protected":false},"author":2,"featured_media":43668,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[249],"class_list":["post-43626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti","tag-dutch_oven"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43626"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43626\/revisions"}],"predecessor-version":[{"id":43672,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43626\/revisions\/43672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/43668"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}