{"id":43529,"date":"2023-12-15T12:48:56","date_gmt":"2023-12-15T11:48:56","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43529"},"modified":"2023-11-22T17:10:51","modified_gmt":"2023-11-22T16:10:51","slug":"muffins-allo-yoghurt","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/12\/15\/muffins-allo-yoghurt\/","title":{"rendered":"Muffins allo yoghurt"},"content":{"rendered":"<p style=\"text-align: justify;\">Con lo yoghurt avanzato, ho pensato di preparare dei muffin (allo yoghurt, appunto).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Quale migliore occasione per utilizzare il mio <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/12\/12\/yoghurt-homemade\/\">yoghurt homemade<\/a><\/strong><\/em>, preparato in modo casalingo?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43530\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1700652965718-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1700652965718-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1700652965718-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1700652965718-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1700652965718-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Ingredienti &#8211; Muffins allo yoghurt<\/strong> &#8211; 10-12 pezzi<\/p>\n<pre>220gr di farina\r\n1\/2 pacchetto di lievito in polvere\r\n120gr di zucchero\r\n3 uova\r\n100ml di olio di girasole\r\n125gr di yoghurt naturale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una ciotola mischiate farina, lievito per dolci e zucchero.<br \/>\nUnite le uova leggermente sbattute, l&#8217;olio e lo yoghurt, mescolando.<\/p>\n<p style=\"text-align: justify;\">Distribuite l&#8217;impasto nei pirottini da muffins e cuocete, in forno statico preriscaldato a 180gradi, per 15-20 minuti.<\/p>\n<p style=\"text-align: justify;\">Fate intiepidire prima di assaporarli!<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">La mia versione e&#8217; stata veramente <strong>basic<\/strong>.<\/li>\n<li style=\"text-align: justify;\">L&#8217;aggiunta di scorza di limone\/arancia, naturalmente BIO, cosi&#8217; come fava tonka o vaniglia non guasta sicuramente il risultato, Anzi, questo viene notevolmente esaltato.<\/li>\n<li style=\"text-align: justify;\">Se lo gradite, potete impreziosirla ulteriormente con del cioccolato: rimuovete circa 12 grossi cucchiaini di impasto dal totale. Unite circa <strong>50gr di cioccolato<\/strong> sciolto e mescolate. Aiutandovi con una sac a poche, inserite l&#8217;impasto scuro nei pirottini pieni di impasto basic e, con l&#8217;ausilio di uno stuzzicadenti, mischiate le miscele.<br \/>\nProcedete con la cottura come indicato.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con lo yoghurt avanzato, ho pensato di preparare dei muffin (allo yoghurt, appunto).<\/p>\n","protected":false},"author":2,"featured_media":43530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,80],"tags":[183],"class_list":["post-43529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-muffins","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43529"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43529\/revisions"}],"predecessor-version":[{"id":43536,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43529\/revisions\/43536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/43530"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}