{"id":43474,"date":"2024-01-03T12:54:40","date_gmt":"2024-01-03T11:54:40","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43474"},"modified":"2024-03-28T13:39:42","modified_gmt":"2024-03-28T12:39:42","slug":"zaatar-cacio-pepe_ottolenghi","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2024\/01\/03\/zaatar-cacio-pepe_ottolenghi\/","title":{"rendered":"Ottolenghi. Za\u00e2\u20ac\u2122atar cacio e pepe"},"content":{"rendered":"<p style=\"text-align: justify;\">Mentre ero alla ricerca di cosa preparare, mi sono ritrovata tra le mani alcune copie (che avevo fatto) del libro &#8220;<strong>Flavor<\/strong>&#8221; di <strong>Ottolenghi<\/strong>.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">E da li, e&#8217; partita l&#8217;idea di preparare la SUA ricetta per la pasta &#8220;Za\u00e2\u20ac\u2122atar cacio e pepe&#8221;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43595\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1701258208399-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1701258208399-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1701258208399-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1701258208399-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2024\/01\/ok_1701258208399-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/ottolenghi.co.uk\/recipes\/zaatar-cacio-e-pepe\">Za\u00e2\u20ac\u2122atar cacio e pepe<\/a><\/strong><\/em> &#8211; per quattro persone<\/p>\n<pre>sale da tavola\r\n400g di bucatini secchi (o altra pasta lunga)\r\n50 g di burro non salato\r\n1 cucchiaio di za\u00e2\u20ac\u2122atar, pi\u00c3\u00b9 1 cucchiaino e mezzo\r\n2 cucchiai di pepe nero\r\n130g di parmigiano, grattugiato \r\n30g di pecorino, grattugiato \r\n7\u00c2\u00bd cucchiai di olio d\u00e2\u20ac\u2122oliva\r\n2 cucchiai di maggiorana intera (facoltativo)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Portate a ebollizione abbastanza acqua in una pentola larga a fuoco medio-alto, quindi salate con 1 cucchiaino di sale.<br \/>\nAggiungete la pasta lunga e secca prescelta e cuocetela secondo le istruzioni della confezione, al dente, mescolando di tanto.<\/p>\n<p style=\"text-align: justify;\">Scolate la pasta conservando tutta l\u00e2\u20ac\u2122acqua di cottura (dovreste ottenere circa 520ml \u00e2\u20ac\u201c se cos\u00c3\u00ac non fosse, rabboccate con un po\u00e2\u20ac\u2122 di acqua calda).<\/p>\n<p style=\"text-align: justify;\">Sciogliete il burro in un\u00e2\u20ac\u2122ampia padella antiaderente dai bordi alti a fuoco vivo fino a quando non spumeggia, quindi aggiungete 1 cucchiaio di za\u00e2\u20ac\u2122atar e il pepe e cuocete per 1 minuto, mescolando, fino a quando non sara&#8217; fragrante.<\/p>\n<p style=\"text-align: justify;\">Aggiungete l\u00e2\u20ac\u2122acqua di cottura, portare a ebollizione rapida e cuocete per 5 minuti, finch\u00c3\u00a9 l&#8217;acqua della pasta non si riduce leggermente.<\/p>\n<p style=\"text-align: justify;\">Aggiungete la pasta e mescolate vigorosamente nella salsa.<\/p>\n<p style=\"text-align: justify;\">Aggiungete il parmigiano in due riprese, continuando a mescolare energicamente e aspettando che la prima met\u00c3\u00a0 si sia sciolta prima di aggiungere la successiva.<\/p>\n<p style=\"text-align: justify;\">Una volta sciolto tutto il parmigiano, aggiungete il pecorino, continuando a mescolare finch\u00c3\u00a9 non si sar\u00c3\u00a0 sciolto anch\u00e2\u20ac\u2122esso e la salsa non sar\u00c3\u00a0 liscia e setosa.<\/p>\n<p style=\"text-align: justify;\">Trasferite la pasta su un piatto da portata e completate con l\u00e2\u20ac\u2122olio d\u00e2\u20ac\u2122oliva, la maggiorana, il rimanente cucchiaino e mezzo di za\u00e2\u20ac\u2122atar e un pizzico di sale.<\/p>\n<p style=\"text-align: justify;\">Servite subito.<\/p>\n<p><strong>Note Personali e varie<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">L\u00e2\u20ac\u2122uso di una padella larga e di poca acqua per cuocere la pasta \u00c3\u00a8 essenziale perch\u00c3\u00a9 garantisce la presenza di molto amido nell\u00e2\u20ac\u2122acqua, che \u00c3\u00a8 la chiave per far emulsionare la salsa.<\/li>\n<li style=\"text-align: justify;\">Le indicazioni fornite sono per una pasta per 4 persone, io ho dimezzato le quantita&#8217;.<\/li>\n<\/ul>\n<p>Buon appetito e&#8230; mangiatela calda!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentre ero alla ricerca di cosa preparare, mi sono ritrovata tra le mani alcune copie (che avevo fatto) del libro &#8220;Flavor&#8221; di Ottolenghi.<\/p>\n","protected":false},"author":2,"featured_media":43595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,51],"tags":[253],"class_list":["post-43474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-primi_piatti","tag-ottolenghi"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43474"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43474\/revisions"}],"predecessor-version":[{"id":44689,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43474\/revisions\/44689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/43595"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}