{"id":43367,"date":"2023-11-22T14:59:30","date_gmt":"2023-11-22T13:59:30","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43367"},"modified":"2023-12-11T17:14:18","modified_gmt":"2023-12-11T16:14:18","slug":"nussschnecken_licoli","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/11\/22\/nussschnecken_licoli\/","title":{"rendered":"Nussschnecken &#8211; Girelle\/chiocciole alla nocciola (non crema!)"},"content":{"rendered":"<p style=\"text-align: justify;\">Finalmente una ricetta di un dolcino che.. proprio non mi piace \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Perche&#8217; allora ho deciso di cucinare queste &#8220;<strong>Girelle\/chiocciole alla nocciola&#8221; (Nussschnecken)<\/strong>?<br \/>\nPer fare cosa gradita all&#8217;uomo di casa (quello che al momento e&#8217; rimasto a casa) e che ama tanto.<\/p>\n<p style=\"text-align: justify;\">Karin mi ha fornito la ricetta che ha provato delle girelle di cannella, presa dal suo libro sulla Pasta Madre, utilizzando il suo licoli &#8220;Barbara&#8221;, cosi&#8217; ho tentato anche io con Vera.<\/p>\n<p style=\"text-align: justify;\">Ho voluto seguire anche io le stesse indicazioni, ma il risultato ottenuto, per quanto concerne l&#8217;impasto, proprio non mi e&#8217; piaciuto risultando esso molliccio, appiccicoso e per niente lievitato.<\/p>\n<p style=\"text-align: justify;\">Dato che le cose non sempre sono perfette, inserisco la ricetta ugualmente, cosi&#8217; come si trova sul libro, omettendo il ripieno (che ho poi fatto io, vedi di seguito).<br \/>\nNaturalmente ho altre ricette di impasto da provare e, se mi ricordo, aggiornero&#8217; questo posto, cosi&#8217; che si possa scegliere quale seguire.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Nussschnecken<\/strong><\/p>\n<pre><strong>Lievitino<\/strong>\r\n 20gr pm\r\n 50gr farina bio\r\n 45gr acqua\r\n\r\n<strong>Impasto<\/strong>\r\n tutto il lievitino\r\n 50gr acqua\r\n 200gr latte intero\r\n 1 uovo\r\n 70gr zucchero\r\n 5gr sale\r\n 550gr farina bio<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Lievitino<\/strong>.<br \/>\nPreparatelo la sera preparate.<br \/>\nImpastate bene gli ingredienti e lasciate riposare l\u00e2\u20ac\u2122impasto tutta la notte coperto da un canovaccio bagnato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43402\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699357424736-1-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699357424736-1-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699357424736-1-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699357424736-1-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699357424736-1-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Impasto<\/strong><br \/>\nAl mattino impastate il lievitino con l\u00e2\u20ac\u2122acqua e il latte intero.<br \/>\nAggiungete l\u00e2\u20ac\u2122uovo, lo zucchero e il sale.<br \/>\nDa ultimo aggiungete la farina e impastate fino a formare una palla liscia, che metterete a lievitare coperta da un canovaccio.<br \/>\nLasciate lievitare 5\/6 ore.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo preparate il ripieno.<\/p>\n<p style=\"text-align: justify;\">Dopo la lievitazione, stendete l\u00e2\u20ac\u2122impasto su un ripiano di legno cosparso di farina in modo che non si attacchi.<br \/>\nFormate un rettangolo di pasta spesso circa 1 cm.<br \/>\nSpennellate l\u00e2\u20ac\u2122impasto con il ripieno lasciando puliti circa 5 cm del bordo superiore.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43406\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675745-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675745-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675745-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675745-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675745-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Partendo dal bordo inferiore del rettangolo (il bordo pi\u00c3\u00b9 vicino a voi, per intenderci), cominciate ad arrotolare l\u00e2\u20ac\u2122impasto. Alla fine chiudete il rotolo premendo leggermente il bordo che avevate lasciato pulito.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43405\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675727-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675727-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675727-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675727-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675727-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nCon un coltello da cucina affilato, tagliate il rotolo in girelle spesse circa 5 cm.<br \/>\nAdagiate le girelle su una teglia rivestita di carta da forno, una vicino all\u00e2\u20ac\u2122altra e lasciate lievitare coperte per altre 2ore circa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43404\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675708-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675708-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675708-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675708-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675708-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Infornate a forno caldo a 180gradi per circa mezz\u00e2\u20ac\u2122ora.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43403\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675680-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675680-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675680-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675680-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1699449675680-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<p style=\"text-align: justify;\">Penso di aver capito parte dei miei errori&#8230;<\/p>\n<ul style=\"text-align: justify;\">\n<li>l&#8217;<strong>uovo<\/strong> inserito era XXL , quindi molto grosso<\/li>\n<li>mentre pesavo la <strong>bilancia<\/strong>, ad un certo punto si e&#8217; spenta. Presuppongo di aver inserito meno farina del necessario. Ad ogni modo ho imparato che devo preparare TUTTI gli ingredienti gia&#8217; minurati, invece di posizionare le ciotole sulla bilancia.<\/li>\n<li>Vista la consistenza dell&#8217;impasto che ho ottenuto, non me la sono sentita di proseguire ulteriormente con l&#8217;ultima lievitazione, cosi&#8217;<strong> ho cotto direttamente.<\/strong><\/li>\n<li>Il gusto non e&#8217; poi male, sono commestibili e sono state anche mangiate. Devo solo migliorare enormemente nell&#8217;impasto.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Per quanto <strong>riguarda<\/strong> il ripieno, in rete ho trovato diverse ricette con ingredienti diversi, cosi&#8217;&#8230; ho improvvisato (tanto).<\/p>\n<p style=\"text-align: justify;\">Soprattutto quando sei convinta di avere in casa tutti gli ingredienti necessari e, alla resa dei conti, non trovi.<br \/>\nAd ogni modo, penso che terro&#8217; buono queste proporzioni anche per le prossime volte.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Nussschnecken &#8211; Ripieno<\/strong><\/p>\n<pre>200gr di nocciole a pezzetti\r\n50 gr di farina di mandorle\r\nun pizzico di cannella (non ne avevo piu)\r\nintegrazione con \"vaniglia\" ?\r\n2 cucchiai circa di zucchero\r\n80ml di latte (non ne avevo piu)\r\nintegrazione con bevanda alla noce (OraSI)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mescolate tutti gli ingredienti e fate insaporire bene<\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalmente una ricetta di un dolcino che.. proprio non mi piace \ud83d\ude42<\/p>\n","protected":false},"author":2,"featured_media":43403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145,22,90],"tags":[88,112],"class_list":["post-43367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dolci","category-food","category-lievitati","tag-frutta_secca","tag-licoli"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43367"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43367\/revisions"}],"predecessor-version":[{"id":43408,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43367\/revisions\/43408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/43403"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}