{"id":43222,"date":"2023-11-08T18:07:31","date_gmt":"2023-11-08T17:07:31","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43222"},"modified":"2023-10-31T18:47:09","modified_gmt":"2023-10-31T17:47:09","slug":"spezzatino-con-verdure","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/11\/08\/spezzatino-con-verdure\/","title":{"rendered":"Spezzatino con verdure (senza pomodoro e senza patate)"},"content":{"rendered":"<p style=\"text-align: justify;\">Oggi&#8230; Spezzatino con verdure, senza pomodoro e senza patate, ma con quanto si dispone, solitamente, in casa<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<figure id=\"attachment_43242\" aria-describedby=\"caption-attachment-43242\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-43242\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624778-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624778-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624778-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624778-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624778-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-43242\" class=\"wp-caption-text\">Spezzatino senza patate<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Spezzatino con verdure (senza pomodoro e senza patate)<\/strong> &#8211; 4\/3 persone<\/p>\n<pre>500gr di spezzatino (*)\r\nuna manciata di piselli (*)\r\n2 carote\r\n1 cipolla\r\n1 costa di sedano\r\n1 peperone rosso\r\nolio \/ burro\r\nvino \r\ndado di carne (brodo) *\r\nsale\r\npepe\r\nconcentrato di pomodoro (facoltativo)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Eliminate i nervetti e l&#8217;eventuale grasso alla carne, tagliatela a pezzetti di egual misura (per favorire la cottura uniforme).<\/p>\n<p style=\"text-align: justify;\">Sbucciate la cipolla e tagliatela a fettine<br \/>\nRaschiate le carote, pulite il sedano eliminando la base ed i filamenti, tagliate le verdure a fettine<br \/>\nPulite il peperone, eliminate il picciolo, i semi ed i filamenti interni, e tagliatelo a filetti<\/p>\n<p style=\"text-align: justify;\">Nella pentola (anche a pressione) sciogliete il burro\/olio e rosolatevi per circa 5 minuti il mix di cipolla, sedano e carota.<\/p>\n<p style=\"text-align: justify;\">Unite la carne, lasciatela dorare una decina di minuti rigirando perche&#8217; i pezzi si coloriscano da tutte le parti.<br \/>\nBagnate con un goccio di vino e procedete la cottura facendolo evaporare, ci vorranno circa 5 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43244\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624826-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624826-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624826-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624826-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624826-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Aggiungete nel tegame della carne il peperone a filetti.<br \/>\nSe lo gradite, potete aggiungere un cucchiaio di concentrato di pomodoro.<br \/>\nSalate, pepate, e versate il brodo (anche di dado) (*); coprite il tegame e cuocete per circa 1 ora a fuoco basso, mescolando di tanto in tanto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43243\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624804-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624804-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624804-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624804-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/11\/ok_1698773624804-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Se cuocete con la pentola a pressione, basteranno 30 minuti dal fischio.<\/p>\n<p style=\"text-align: justify;\">Allo scadere, inserite i piselli e cuocete per ulteriori 5 minuti, senza coperchio (in entrambi i casi).<\/p>\n<p style=\"text-align: justify;\">Spolverizzate di pepe \/ peperoncino prima di servire<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Come <strong>carne<\/strong> va bene vitello o maiale, io ho acquistato ed usato il secondo tipo<\/li>\n<li>I <strong>piselli<\/strong> possono essere in scatola o surgelati. Giusto per dare un po&#8217; di allegria al piatto<\/li>\n<li style=\"text-align: justify;\">La quantita&#8217; di <strong>liquido<\/strong> del brodo dipende molto dal vostro gusto e dalla vostra pentola. Nel mio caso, i liquidi non evaporano molto, quindi tendo a non inserirne molto.<\/li>\n<li style=\"text-align: justify;\">Se preferite ottenere un <strong>sughetto<\/strong> un po&#8217; piu&#8217; <strong>consistente<\/strong> e meno liquido, potete infarinare la carne (bastano veramente 2 cucchiai di farina) prima di farla cuocere. Oppure inserire un addensante (farina, maizena, etc..) insieme ai piselli, e mescolare benissimo per prevenire la formazione di grumi.<\/li>\n<li style=\"text-align: justify;\">Se avanza parte di questa preparazione, e&#8217; possibile <strong>surgelarla<\/strong> senza problemi.<\/li>\n<li style=\"text-align: justify;\">Aggiungendo del riso \/ pasta \/ cuscus diventa un perfetto<strong> piatto unico<\/strong>.<br \/>\nNoi lo abbiamo accompagnato con del pane tostato.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi&#8230; Spezzatino con verdure, senza pomodoro e senza patate, ma con quanto si dispone, solitamente, in casa<\/p>\n","protected":false},"author":2,"featured_media":43242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,180,60],"tags":[53],"class_list":["post-43222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-pentola-a-pressione","category-secondi_piatti","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43222"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43222\/revisions"}],"predecessor-version":[{"id":43245,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43222\/revisions\/43245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/43242"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}