{"id":43136,"date":"2023-10-21T14:02:18","date_gmt":"2023-10-21T12:02:18","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43136"},"modified":"2023-10-29T14:24:21","modified_gmt":"2023-10-29T13:24:21","slug":"ikebana","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/10\/21\/ikebana\/","title":{"rendered":"Ikebana"},"content":{"rendered":"<p style=\"text-align: justify;\">La mia amica Francesca e&#8217; venuta a trovarmi per andare, insieme, alla fiera IBA 2023 di Monaco.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Avendo il sabato libero, ed essendo una bella giornata di sole ottobrino, abbiamo fatto un po&#8217; di passi fuori di casa, ciaccolando un po&#8217;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43142\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495406-e1698585670647-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495406-e1698585670647-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495406-e1698585670647-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495406-e1698585670647-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495406-e1698585670647-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Siamo arrivate in Comune, vabbe&#8217;, non e&#8217; distante da casa, cosi&#8217; da soffermarci per l&#8217;esposizione di Ikebana \/ Ikebono.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43148\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495491-e1698585716741-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495491-e1698585716741-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495491-e1698585716741-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495491-e1698585716741-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495491-e1698585716741-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43147\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495480-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495480-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495480-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495480-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495480-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Dopo dieci anni di pausa, l&#8217;arte giapponese e&#8217; tornata a mettersi in mostra nel nostro comune, cosi&#8217; abbiamo potuto ammirare le composizini floreali che Ingrid Eichinger (professoressa \u00e2\u20ac\u201c Sokakyo \u00e2\u20ac\u201c da 35 anni) ed i suoi studenti hanno preparato.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingrid Eichinger<\/strong> \u00e2\u20ac\u0153Suihaku\u00e2\u20ac\u009d e&#8217; conosciuta attraverso numerose mostre, dimostrazioni e seminari in patria e all&#8217;estero, e vive da 50 anni &#8220;la via dei fiori &#8221; &#8211; KADO &#8211; (*).<br \/>\nHa ricevuto la sua formazione dal Professor Senior Shusui Pointner-Komoda e durante numerose visite di studio presso la IKENOBO Society of Floral Art a Kyoto in Giappone.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43146\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495468-e1698585697132-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495468-e1698585697132-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495468-e1698585697132-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495468-e1698585697132-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495468-e1698585697132-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">L&#8217;ikebana \u00c3\u00a8 una forma d&#8217;arte indipendente come la cerimonia del t\u00c3\u00a8, la musica o la calligrafia.<br \/>\nIl simbolo giapponese dell&#8217;Ikebana significa qualcosa come: \u00e2\u20ac\u0153risvegliare i fiori nella loro vera, pi\u00c3\u00b9 bella forma\u00e2\u20ac\u009d. Chi intraprende questo viaggio \u00c3\u00a8 in grado di svilupparsi interiormente e di guardare nelle profondit\u00c3\u00a0 piu&#8217; intime, che rimangono nascoste a causa del ritmo frenetico della vita quotidiana.<br \/>\nIn questo modo possiamo acquisire nuova forza e la concentrazione mentale giusta che ci permette di dimenticare le tante piccole preoccupazioni quotidiane.<\/p>\n<p style=\"text-align: justify;\">Da molti secoli in Giappone incontriamo quest&#8217;arte unica della disposizione dei fiori, profondamente radicata in tutti gli aspetti della vita<\/p>\n<p style=\"text-align: justify;\">Il Sentiero dei Fiori &#8211; KADO &#8211; non solo ci insegna a padroneggiare la tecnica di disporre i fiori, ma richiede anche da parte nostra la volont\u00c3\u00a0 interiore di diventare\/essere un tutt&#8217;uno per sintonizzarci con la natura delle piante e sperimentare pace e relax attraverso questa concentrazione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43144\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495439-e1698585687422-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495439-e1698585687422-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495439-e1698585687422-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495439-e1698585687422-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495439-e1698585687422-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">L&#8217;ikebana riflette la vita e il pensiero delle persone della rispettiva epoca in cui \u00c3\u00a8 stata creata.<br \/>\nQuando in Giappone si parla del contenuto spirituale di una forma d&#8217;arte, si pensa anche a DO-WAY.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43143\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495422-e1698585678916-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495422-e1698585678916-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495422-e1698585678916-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495422-e1698585678916-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495422-e1698585678916-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>NOTE<\/strong> (anche tratte\u00c2\u00a0 da http:\/\/sakuramagazine.com )<\/p>\n<p style=\"text-align: justify;\">Il termine <strong>ikebana<\/strong> (\u00e7\u201d\u0178\u00e3\u0081\u2018\u00e8\u0160\u00b1 o \u00e3\u0081\u201e\u00e3\u0081\u2018\u00e3\u0081\u00b0\u00e3\u0081\u00aa) in giapponese significa letteralmente \u00e2\u20ac\u0153fiori viventi\u00e2\u20ac\u009d o \u00e2\u20ac\u0153portare i fiori alla vita\u00e2\u20ac\u009d.<\/p>\n<p style=\"text-align: justify;\"><strong>kad\u00c5\u008d<\/strong> significa invece \u00e2\u20ac\u0153via dei fiori\u00e2\u20ac\u009d, ed e&#8217; un elemento imprescindibile dell\u00e2\u20ac\u2122ikebana: \u00c3\u00a8 l\u00e2\u20ac\u2122armonia tra uomo e universo, in cui spesso confluisce un elemento di celebrazione della vita e di esaltazione del luogo di origine.<br \/>\nQuesta tecnica infatti affonda le sue radici nel buddismo, in cui \u00c3\u00a8 comune portare fiori all\u00e2\u20ac\u2122altare, e si sviluppa nei periodi seguenti dapprima fra i nobili e in seguito fra tutto il popolo<br \/>\nEssa non si limita alla sola realizzazione di una composizione floreale ma aiuta a creare uno stato di calma e di serenit\u00c3\u00a0, a ritrovare le proprie qualit\u00c3\u00a0 e valori umani.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43140\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495384-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495384-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495384-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495384-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698573495384-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mia amica Francesca e&#8217; venuta a trovarmi per andare, insieme, alla fiera IBA 2023 di Monaco.<\/p>\n","protected":false},"author":2,"featured_media":43145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,46],"tags":[],"class_list":["post-43136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43136"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43136\/revisions"}],"predecessor-version":[{"id":43149,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43136\/revisions\/43149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/43145"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}