{"id":43128,"date":"2023-10-31T11:24:58","date_gmt":"2023-10-31T10:24:58","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=43128"},"modified":"2023-11-01T15:32:20","modified_gmt":"2023-11-01T14:32:20","slug":"halloween-2023","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/10\/31\/halloween-2023\/","title":{"rendered":"Halloween"},"content":{"rendered":"<p style=\"text-align: justify;\">Questo anno proprio non voglio subirmi la solita processione di coloro che passano di casa in casa alla ricerca di caramelle o dolcetti vari per <strong>Halloween<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">L&#8217;anno passato avevo lasciato fuori anche una ciotola piena e, nel giro di pochi minuti, era terminata alla grande.<br \/>\nNo, non sono stati i bimbi piccoli. Loro solitamente si accontentano di una caramellina. Mi riferisco a quelli leggermente piu&#8217; grandi, che fanno razzia senza problemi.<\/p>\n<p style=\"text-align: justify;\">A parte questo, non ho intenzione di rinunciare ad addobbare che, a ben guardare, lo faccio molto piu&#8217; volentieri per questo giorno che per Natale (o Pasqua).<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ho deciso di creare una &#8220;barriera&#8221; alla porta e di non aprire.<\/p>\n<p style=\"text-align: justify;\">Detto fatto, mi sono messa anche all&#8217;opera.<br \/>\nLa coincidenza ha voluto che, nella puntata di Elisir, si faceva notare che le persone annoiate sono anche le piu&#8217; creative.<br \/>\nEcco, la creativita&#8217; non mi e&#8217; mancata.<br \/>\nMi sono semplicemente persa nei dettagli, che fanno decisamente la differenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43133\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598057-e1698423944198-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598057-e1698423944198-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598057-e1698423944198-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598057-e1698423944198-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598057-e1698423944198-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Giocando Stephan a pingpong da decenni, ero sicura che avesse una scatola di palline.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43132\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598043-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598043-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598043-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598043-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598043-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Quale miglior uso se non farle diventare degli <strong>occhi<\/strong>?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43131\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598031-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598031-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598031-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598031-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598031-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Per questi ho utilizzato dei pennarelli indelebili, ma e&#8217; possibile colorare con dei pennarelli normali o con delle tempere.<\/p>\n<p>Qui di seguito, invece, il miglior utilizzo della scatola della lampada Ikea.<br \/>\nAlcune macchiette sono di sangue vero, dato che mi sono tagliuzzata mentre tagliavo ed utilizzavo il materiale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43130\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598019-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598019-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598019-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598019-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698421598019-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Poi ho voluto provare a fare del &#8220;<strong>sangue finto<\/strong>&#8221; ed e&#8217; risultata la schifezza.<br \/>\nVabbe&#8217;.<\/p>\n<p style=\"text-align: justify;\">Per il <em>sangue finto<\/em>, commestibilissimo, basta unire del miele, del colorante rosso (attenzione che lascia il colore, quindi proteggete gli indumenti mentre lo utilizzate) ed un poco di cacao (per dare la consistenza)<\/p>\n<p style=\"text-align: justify;\">Ed ecco la porta terminata<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43239\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271567-e1698773817974-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271567-e1698773817974-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271567-e1698773817974-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271567-e1698773817974-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271567-e1698773817974-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ora proprio non capisco&#8230;<br \/>\nO i genitori se ne strafregano o non sanno leggere.<\/p>\n<p>Al momento in cui scrivo ( 6:40pm ) hanno gia&#8217; suonato 28 persone.<br \/>\nIo ignoro e vado avanti.<br \/>\nMa che stress! Dovro&#8217; pensare a qualcosa di altro per l&#8217;anno prossimo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-43238\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271556-e1698773825290-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271556-e1698773825290-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271556-e1698773825290-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271556-e1698773825290-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1698772271556-e1698773825290-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo anno proprio non voglio subirmi la solita processione di coloro che passano di casa in casa alla ricerca di caramelle o dolcetti vari per Halloween.<\/p>\n","protected":false},"author":2,"featured_media":43240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,46],"tags":[94,96],"class_list":["post-43128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-life","tag-diy","tag-halloween"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=43128"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43128\/revisions"}],"predecessor-version":[{"id":43241,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/43128\/revisions\/43241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/43240"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=43128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=43128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=43128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}