{"id":42848,"date":"2023-10-16T11:29:35","date_gmt":"2023-10-16T09:29:35","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=42848"},"modified":"2023-10-03T18:02:08","modified_gmt":"2023-10-03T16:02:08","slug":"james-e-la-pesca-gigante-pesca","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/10\/16\/james-e-la-pesca-gigante-pesca\/","title":{"rendered":"&#8220;James e la pesca gigante&#8221; &#8211; pesca"},"content":{"rendered":"<p style=\"text-align: justify;\">Uno dei frutti che piu&#8217; simboleggia l&#8217;estate e&#8217; senza ombra di dubbio la <strong>pesca<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Nella versione crostata, degustata come parfait, nei dessert, a fettine nel vino ross ma anche come semplice frutto rinfresca la bocca con la sua polpa carnosa.<\/p>\n<p style=\"text-align: justify;\">Ecco perche&#8217; mi e&#8217; venuto in mente il romanzo scritto, da Roald Dahl, <strong>&#8220;James e la pesca gigante<\/strong>&#8221; riadattato in modo magistrale anche per la televisione, proprio mentre ne assaporavo una.<\/p>\n<figure id=\"attachment_42852\" aria-describedby=\"caption-attachment-42852\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42852\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/james3.jpg\" alt=\"\" width=\"474\" height=\"296\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/james3.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/james3-150x94.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/james3-300x187.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-42852\" class=\"wp-caption-text\">Da Internet &#8211; James e la Pesca gigante<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em>James Henry Trotter<\/em> \u00c3\u00a8 un bambino che, fino a quattro anni, vive con la mamma e il pap\u00c3\u00a0 in una bellissima casetta sul mare.<\/p>\n<p style=\"text-align: justify;\">Un brutto giorno i suoi genitori vanno a Londra e vengono mangiati da un rinoceronte rabbioso fuggito dallo zoo.<\/p>\n<p style=\"text-align: justify;\">Cos\u00c3\u00ac James resta orfano.<br \/>\nViene affidato alla zia Spugna (bassa e grassa) e alla zia Stecco (alta e magrissima), che vivono in una specie di castello su una collina.<br \/>\nLe zie sono cattivissime e chiamano James con dei brutti nomignoli, lo maltrattano, lo insultano, lo picchiano senza motivo e lo fanno lavorare come un mulo. Inoltre sono talmente pigre che non lo fanno mai uscire dal loro giardino.<br \/>\nJames, quindi, non ha nemmeno un amico ed \u00c3\u00a8 sempre solo.<\/p>\n<figure id=\"attachment_42850\" aria-describedby=\"caption-attachment-42850\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42850 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696347083182-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696347083182-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696347083182-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696347083182-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696347083182-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-42850\" class=\"wp-caption-text\">La Pesca Gigante con la zia Stecco e la zia Spugna<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ma ecco che improvvisamente dall\u00e2\u20ac\u2122albero nasce una <strong>pesca<\/strong> che cresce a vista d\u00e2\u20ac\u2122occhio e a dismisura.<br \/>\nLe zie pensano di allontanare James e di lucrare sul fenomeno facendo pagare il biglietto a chi volesse andare a vedere la sorprendente pesca nel loro giardino. Ma James, lasciato fuori di casa una sera, cerca rifugio proprio nella pesca entrando da un buco. E l\u00c3\u00ac incontra degli amici animali con i quali inizia un lungo viaggio e straordinarie avventure a bordo del frutto in direzione di New York..<\/p>\n<p style=\"text-align: justify;\">Protagonisti, assieme al bambino, alcuni insetti di dimensioni enormi, che diventano suoi amici, mentre le due zie fanno la fine che si meritano.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Ai <strong>Walt Disney Animation Studios,<\/strong> all&#8217;inizio degli anni &#8217;80, Joe Ranft cerc\u00c3\u00b2 di convincere lo studio a produrre un film basato su James e la pesca gigante (1961) di Roald Dahl, un libro che lo aveva affascinato per il suo materiale &#8220;liberatorio&#8221; fin dalla prima lettura in terza elementare.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, la Disney rifiut\u00c3\u00b2 per motivi legati a un processo di animazione potenzialmente costoso e difficile e al soggetto bizzarro del materiale di partenza. Tra gli animatori esposti al libro da Ranft c&#8217;era Henry Selick che, pur avendo apprezzato il libro e pensato di adattarlo allo schermo per diversi anni, si rese conto degli ostacoli che avrebbe incontrato, come la natura onirica del materiale di partenza, la struttura episodica e la reputazione di altri libri di Dahl, cos\u00c3\u00ac controversi da essere banditi in alcune parti del mondo.<\/p>\n<p style=\"text-align: justify;\">Felicity Dahl, vedova di Roald ed esecutrice del suo patrimonio, inizi\u00c3\u00b2 a offrire i diritti cinematografici del libro nell&#8217;estate del 1992; tra gli interessati c&#8217;erano Steven Spielberg e Danny DeVito.<\/p>\n<p style=\"text-align: justify;\">La Walt Disney Pictures acquist\u00c3\u00b2 i diritti cinematografici del libro dalla Dahl Estate nel 1992.<\/p>\n<figure id=\"attachment_42853\" aria-describedby=\"caption-attachment-42853\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42853\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/james2.jpg\" alt=\"\" width=\"474\" height=\"266\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/james2.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/james2-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/james2-300x168.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-42853\" class=\"wp-caption-text\">Da Internet &#8211; James e la Pesca gigante<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Secondo la vedova di Roald Dahl, Felicity &#8220;Liccy&#8221;, lo scrittore &#8220;sarebbe stato felicissimo di quello che hanno fatto con James. \u00c3\u02c6 un film meraviglioso&#8221;.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno dei frutti che piu&#8217; simboleggia l&#8217;estate e&#8217; senza ombra di dubbio la pesca.<\/p>\n","protected":false},"author":2,"featured_media":42851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[251,107,129],"class_list":["post-42848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","tag-foodmedia","tag-frutta","tag-tv_kino"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/42848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=42848"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/42848\/revisions"}],"predecessor-version":[{"id":42857,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/42848\/revisions\/42857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/42851"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=42848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=42848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=42848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}