{"id":42815,"date":"2023-10-11T15:56:27","date_gmt":"2023-10-11T13:56:27","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=42815"},"modified":"2023-10-02T17:25:29","modified_gmt":"2023-10-02T15:25:29","slug":"funghi-e-carote","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/10\/11\/funghi-e-carote\/","title":{"rendered":"Funghi e carote"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Carote e funghi<\/strong> e&#8217; un binomio perfetto, ottimo come contorno autunnale (se si acquistano funghi stagionali) o per riempire una omelette.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Purtroppo, per me, non me ne posso deliziare cosi&#8217; spesso quanto vorrei.<br \/>\nA nessuno in casa piacciono i funghi.<\/p>\n<p>In questo modo, quando sono in casa da sola, ne approfitto.<br \/>\nCome del resto anche pasteggiando con preparazioni ed ingredienti diversi me lo preparo quando sono sola.<\/p>\n<figure id=\"attachment_42818\" aria-describedby=\"caption-attachment-42818\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-42818\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156868993-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156868993-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156868993-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156868993-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156868993-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-42818\" class=\"wp-caption-text\">Carote e funghi<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ad ogni modo, questo contorno e&#8217; veramente molto facile nella sua preparazione, non certo nella resa: i funghi veramente spariscono con la cottura.<\/p>\n<p><strong>Ingredienti &#8211; Funghi e carote<\/strong><\/p>\n<pre>olio\r\naglio\r\ncarote\r\nfunghi\r\nprezzemolo\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate a preparare gli ingredienti.<\/p>\n<p style=\"text-align: justify;\">Pelate ed affettate le carote in pezzetti piu&#8217; o meno simili, cosi&#8217; che possano cuocere uniformemente.<\/p>\n<p style=\"text-align: justify;\">Pulite i funghi ed affettateli.<br \/>\nPotete utilizzare i funghi che piu&#8217; preferite, o che trovate. Anche quelli secchi, lasciandoli ammollare preventivamente in acqua tiepida.<\/p>\n<p style=\"text-align: justify;\">In una larga padella fate rosolare, in goccio di olio, l&#8217;aglio per un paio di minuti, cosi&#8217; da insaporirsi bene.<br \/>\nInserite le carote, mescolando con un cucchiaio di legno qualche minuto, poi aggiungete i funghi tagliati.<\/p>\n<p style=\"text-align: justify;\">Salate, pepate, quindi proseguite la cottura, mescolando delicatamente, fino a quando le carote resteranno tenere ma che non si spappoleranno.<\/p>\n<figure id=\"attachment_42819\" aria-describedby=\"caption-attachment-42819\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-42819\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156869013-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156869013-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156869013-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156869013-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/10\/ok_1696156869013-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-42819\" class=\"wp-caption-text\">Carote e funghi<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Rimuovete dal fuoco la padella, aggiungete il prezzemolo e mescolate con delicatezza.<\/p>\n<p>Buon appetito!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carote e funghi e&#8217; un binomio perfetto, ottimo come contorno autunnale (se si acquistano funghi stagionali) o per riempire una omelette.<\/p>\n","protected":false},"author":2,"featured_media":42818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22],"tags":[],"class_list":["post-42815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/42815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=42815"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/42815\/revisions"}],"predecessor-version":[{"id":42822,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/42815\/revisions\/42822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/42818"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=42815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=42815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=42815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}