{"id":41581,"date":"2023-04-18T13:45:58","date_gmt":"2023-04-18T11:45:58","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=41581"},"modified":"2023-07-05T13:05:59","modified_gmt":"2023-07-05T11:05:59","slug":"torta-di-carote-ananas-e-noci","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/04\/18\/torta-di-carote-ananas-e-noci\/","title":{"rendered":"Torta di carote, ananas e noci (Oster Poke Cake)"},"content":{"rendered":"<p style=\"text-align: justify;\">Oramai aspetto con ansia le grandi occasioni, in cui ci sono diverse persone familiari (e non) per poter sperimentare nuove ricette.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Quest&#8217;anno ho preparato questa torta di carote, con l&#8217;aggiunta di ananas e noci (Oster Poke Cake), ricetta trovata su una rivista di <em>AldiSud<\/em><\/p>\n<figure id=\"attachment_41589\" aria-describedby=\"caption-attachment-41589\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-41589 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_tortacarote-1024x601.jpeg\" alt=\"\" width=\"525\" height=\"308\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_tortacarote-1024x601.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_tortacarote-150x88.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_tortacarote-300x176.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_tortacarote-768x451.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-41589\" class=\"wp-caption-text\">Torta di carote, ananas e noci (Oster Poke Cake)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Torta di carote, ananas e noci (Oster Poke Cake) &#8211; 24cm di diametro<\/strong><\/p>\n<pre>320gr di farina\r\n 3 cucchiaini di lievito in polvere\r\n 1\/2 cucchiaino di sale\r\n 2 cucchiaini di mix di spezie in polvere (cannella, zenzero e noce moscata)\r\n 240gr di olio\r\n 250gr di zucchero di canna\r\n 4 uova grosse\r\n 1 cucchiaino di pasta di vaniglia\r\n 400gr di carote grattugiate\r\n 1 lattina di ananas a pezzetti\r\n 125gr di noci rotte grossolanamente\r\n\r\n<strong>Crema<\/strong>\r\n 1 pacchetto di budino alla vaniglia\r\n 500ml di latte\r\n 40gr di zucchero bianco\r\n\r\n<strong>Frosting<\/strong>\r\n 200gr di cioccolato bianco\r\n 400gr di formaggio fresco (temperatura ambiente) - tipo philadelphia\r\n 100gr di burro (temperatura ambiente)\r\n 150 gr di zucchero a velo<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Per la torta<\/strong><br \/>\nMischiate la farina, il lievito per dolci, il sale ed il mix di spezie.<br \/>\nUnite l&#8217;olio, lo zucchero di canna, le uova e la pasta di vaniglia agli ingredienti secchi.<\/p>\n<p style=\"text-align: justify;\">Aggiungete le carote, l&#8217;ananas e le noci.<\/p>\n<p style=\"text-align: justify;\">Imburrate una tortiera da 24cm di diametro ed inserite l&#8217;impasto.<\/p>\n<p style=\"text-align: justify;\">Fate cuocere la base della torta a 180gradi ventilato (200gradi statico) per 45-55 minuti, in forno preriscaldato.<br \/>\nPrima di rimuovere la torta dal forno, verificate la cottura con uno stuzzicadenti di legno.<\/p>\n<p style=\"text-align: justify;\"><strong>Per la crema.<\/strong><br \/>\nPreparate il budino alla vaniglia seguendo le indicazioni riportate sulla confezione, aggiungendo il latte e lo zucchero (se non presente direttamente nel prodotto).<\/p>\n<p style=\"text-align: justify;\"><strong>Per il frosting.<\/strong><br \/>\nTagliate grossolanamente il cioccolato bianco a pezzi e fatelo sciogliere a bagnomaria (oppure in microonde, come la sottoscritta).<br \/>\nFate raffreddare la preparazione, fino a che non diventa tiepido. Aggiungete il formaggio, lo zucchero bianco e lo zucchero a velo e mischiate bene con un mixer, per un minutino circa.<\/p>\n<p style=\"text-align: justify;\"><strong>Composizione della torta<br \/>\n<\/strong>Dopo che la base della torta si e&#8217; raffreddata, effettuate dei fori sulla superficie, fino ad arrivare alla base della torta, aiutandovi con il manico di un cucchiaio di legno.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-41593\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268581-1024x692.jpg\" alt=\"\" width=\"525\" height=\"355\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268581-1024x692.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268581-150x101.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268581-300x203.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268581-768x519.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nInserite il budino alla vaniglia liquido e tiepido.<br \/>\nFate raffreddare.<\/p>\n<p style=\"text-align: justify;\">A questo punto non vi resta che coprire la torta con il frosting e le eventuali decorazioni.<br \/>\nPersonalmente ho optato per delle carotine di marzapane \ud83d\ude09<\/p>\n<figure id=\"attachment_41590\" aria-describedby=\"caption-attachment-41590\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-41590 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268548-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268548-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268548-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268548-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268548-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-41590\" class=\"wp-caption-text\">Torta di carote, ananas e noci (Oster Poke Cake)<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Il <strong>budino<\/strong> e&#8217; avanzato&#8230; e lo abbiamo poi mangiato cosi&#8217;<\/li>\n<li style=\"text-align: justify;\">Lo stesso vale per il <strong>frosting<\/strong>, avendo comunque seguito la ricetta, tanto da decidere di surgelarlo per la prossima preparazione \ud83d\ude42<\/li>\n<\/ul>\n<figure id=\"attachment_41591\" aria-describedby=\"caption-attachment-41591\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-41591 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268560-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268560-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268560-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268560-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_1681220268560-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-41591\" class=\"wp-caption-text\">Torta di carote, ananas e noci (Oster Poke Cake)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Alla prossima!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oramai aspetto con ansia le grandi occasioni, in cui ci sono diverse persone familiari (e non) per poter sperimentare nuove ricette.<\/p>\n","protected":false},"author":2,"featured_media":41589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[107,88,265,62],"class_list":["post-41581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-torte","tag-frutta","tag-frutta_secca","tag-nascondo_le_verdure","tag-pasqua"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/41581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=41581"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/41581\/revisions"}],"predecessor-version":[{"id":41599,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/41581\/revisions\/41599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/41589"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=41581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=41581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=41581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}