{"id":41024,"date":"2023-03-30T12:11:04","date_gmt":"2023-03-30T10:11:04","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=41024"},"modified":"2023-03-11T10:19:48","modified_gmt":"2023-03-11T09:19:48","slug":"salmone-arancia-riso-noci","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/03\/30\/salmone-arancia-riso-noci\/","title":{"rendered":"Salmone all&#8217;arancia con riso alle noci"},"content":{"rendered":"<p style=\"text-align: justify;\">Qui di seguito potrete trovare un&#8217;idea per pranzo\/cena veloce nella sua preparazione.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Un pasto sano e, accompagnato a dell&#8217;insalata o ad un contorno vegetale, completo.<\/p>\n<p style=\"text-align: justify;\">Per velocizzare la preparazione potreste cuocere del riso anticipatamente e lasciarlo conservato, in un contenitore coperto, in frigorifero.<\/p>\n<figure id=\"attachment_41033\" aria-describedby=\"caption-attachment-41033\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-41033\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-41033\" class=\"wp-caption-text\">Salmone all&#8217;arancia con riso alle noci<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/eatsmarter.de\/rezepte\/orangen-lachs-mit-nussreis\">Salmone all&#8217;arancia con riso alle noci<\/a><\/strong><\/em> &#8211; 4 persone<\/p>\n<pre>250 g di riso integrale basmati (*)\r\nsale\r\n1 arancia biologica\r\n40 g erbe aromatiche (1 manciata; prezzemolo e aneto)\r\n5 cucchiai di olio d'oliva\r\npepe\r\n600 g filetto di salmone (4 filetti di salmone)\r\n50 g di anacardi salati<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Cuocete il riso in acqua salata, seguendo le istruzioni riportate sulla confezione, fino ad averlo cotto al dente.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo lavate l&#8217;arancia con acqua calda, asciugatela, grattugiate finemente la scorza e spremetene il succo.<\/p>\n<p style=\"text-align: justify;\">Per preparare la marinata<br \/>\nLavate le erbe aromatiche, scuoteterle per asciugarle, tritatele e mescolatele al succo e scorza d&#8217;arancia.<br \/>\nUnite anche 4 cucchiai di olio d&#8217;oliva, sale e pepe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-41032\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416603-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416603-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416603-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416603-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416603-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Spennellate una pirofila con l&#8217;olio rimasto.<br \/>\nSciacquate il salmone sotto l&#8217;acqua fredda, asciugatelo e conditelo con la marinata.<\/p>\n<p style=\"text-align: justify;\">Tritate grossolanamente le noci\/anacardi.<\/p>\n<p style=\"text-align: justify;\">Distribuite il riso nella pirofila, unite le noci e adagiatevi sopra i filetti di pesce.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-41031\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416594-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416594-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416594-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416594-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416594-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Irrorate con la restante marinatura<\/p>\n<figure id=\"attachment_41030\" aria-describedby=\"caption-attachment-41030\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-41030\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416573-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416573-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416573-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416573-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750416573-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-41030\" class=\"wp-caption-text\">Salmone all&#8217;arancia<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">cuocete in forno preriscaldato a 200\u00c2\u00b0C (forno ventilato a 180 \u00c2\u00b0C) per circa 20 minuti.<\/p>\n<figure id=\"attachment_41033\" aria-describedby=\"caption-attachment-41033\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-41033\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/03\/ok_1677750445866-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-41033\" class=\"wp-caption-text\">Salmone all&#8217;arancia con riso venere nocciolato<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Ho sostituito il riso integrale con del riso Venere.<\/li>\n<li style=\"text-align: justify;\">Le erbe aromatiche utilizzate erano surgelate<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui di seguito potrete trovare un&#8217;idea per pranzo\/cena veloce nella sua preparazione.<\/p>\n","protected":false},"author":2,"featured_media":41030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,77,138],"tags":[107,88],"class_list":["post-41024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pesce","category-piatti_unici","tag-frutta","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/41024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=41024"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/41024\/revisions"}],"predecessor-version":[{"id":41035,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/41024\/revisions\/41035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/41030"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=41024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=41024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=41024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}