{"id":40531,"date":"2023-01-27T12:52:04","date_gmt":"2023-01-27T11:52:04","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=40531"},"modified":"2023-01-22T17:11:39","modified_gmt":"2023-01-22T16:11:39","slug":"dolcetto-post-caffe","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/01\/27\/dolcetto-post-caffe\/","title":{"rendered":"Dolcetto post-caffe&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">Oramai e&#8217; risaputo che un quadratino di <strong>cioccolato<\/strong>, circa 25grammi, non fa assolutamente male.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Quello che non fa bene, invece, e&#8217; lo zucchero in esso contenuto.<br \/>\nEcco perche&#8217; si preferisce un cioccolato fondente, amaro, partendo dal 65% in su di cacao.<\/p>\n<p style=\"text-align: justify;\">Cosa dobbiamo fare, allora, di quanto ancora in casa?<br \/>\nSemplice.<br \/>\nFinirlo prima di iniziare a diventare veramente critica e &#8220;bendata&#8221; durante il giro al supermercato.<\/p>\n<p style=\"text-align: justify;\">Ecco perche&#8217;, con questo post, voglio mostrare le ultime dolcezze assaporate insieme al caffe&#8217; post pranzo.<br \/>\nUltime rispetto alla mia serie, iniziata con diversi Post in questo Blog, ma non certo comparando alla moltitudine di pacchetti sparsi ancora per casa.<\/p>\n<p style=\"text-align: justify;\">Della serie di cioccolato <strong>Alpia<\/strong> ne avevo parlato <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/01\/15\/alpia-cioccolato-carote-mandorle\/\">tempo fa<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40528\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371315-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371315-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371315-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371315-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371315-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nLa tavoletta viene immediatamente riconoscita dai conoscitori del cibo degli Dei per la sua confezione rosa ed il panorama alpino.<\/p>\n<p style=\"text-align: justify;\">Da oltre 100 anni la ditta offre a tutti dei deliziosi momenti di piacere degustando il loro prodotto.<\/p>\n<p style=\"text-align: justify;\">I gusti proposti sono decisamente molto particolari, che si affiancano a quelli tradizionali.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Cosa si puo&#8217; dire della tavoletta quadrata di <strong>RitterSport<\/strong>?<br \/>\nDecisamente un&#8217;istituzione qui in Germania, oltre al suo particolare e personale sistema di apertura della tavoletta, senza sporcarsi le mani.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40527\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371305-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371305-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371305-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371305-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400371305-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ogni anno si hanno nuove scoperte, nuovi gusti, pur mantenendo l&#8217;alta qualita&#8217; del prodotto e le materie pure.<br \/>\nChe dire?<br \/>\nHo provato tantissimi sapori, restando sempre soddisfatta.<br \/>\nVabbe&#8217;, ci vuole poco con me&#8230;<\/p>\n<p style=\"text-align: justify;\">Sicuramente vi e&#8217; capitato di valicare le Alpi e di imbattervi in quei deliziosi cioccolatini rotondi, con la loro cartina dorata, meglio conosciuti come <strong>Mozartkugel<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40529\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400407873-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400407873-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400407873-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400407873-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674400407873-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Il Mozartkugel \u00c3\u00a8 un dolce a base di cioccolato, pistacchi, marzapane e torrone.<br \/>\nSecondo le sue stesse dichiarazioni, \u00c3\u00a8 stato creato dal pasticcere di Salisburgo Paul F\u00c3\u00bcrst nel 1890 e prende il nome dal compositore Wolfgang Amadeus Mozart, morto quasi 100 anni prima. Il nome originale era Mozart Bonbon.<br \/>\nGli originali Mozartkugeln, preparati a mano secondo la ricetta originale, sono ancora oggi prodotti da Konditorei F\u00c3\u00bcrst e vengono venduti solo nei loro negozi e offerti per corrispondenza su Internet.<br \/>\nA causa della mancanza di diritti di propriet\u00c3\u00a0 dell&#8217;azienda F\u00c3\u00bcrst, esistono numerosi prodotti di imitazione che vengono prodotti principalmente industrialmente, distinguibili dalla carta che avvolge ogni singolo cioccolatino.<br \/>\nNel nostro caso si tratta di &#8220;<strong>Mirabell<\/strong>&#8220;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oramai e&#8217; risaputo che un quadratino di cioccolato, circa 25grammi, non fa assolutamente male.<\/p>\n","protected":false},"author":2,"featured_media":40528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[84],"class_list":["post-40531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","tag-cioccolato"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=40531"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40531\/revisions"}],"predecessor-version":[{"id":40536,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40531\/revisions\/40536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/40528"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=40531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=40531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=40531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}