{"id":40481,"date":"2023-02-19T12:19:58","date_gmt":"2023-02-19T11:19:58","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=40481"},"modified":"2023-02-01T17:02:50","modified_gmt":"2023-02-01T16:02:50","slug":"guancia-al-vino-rosso","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/02\/19\/guancia-al-vino-rosso\/","title":{"rendered":"Guancia di vitello al vino rosso"},"content":{"rendered":"<p style=\"text-align: justify;\">Tobias aveva voglia del <strong>brasato<\/strong>, io avevo deciso di preparare la guancia (di vitello), prendendo spunto dal film &#8220;<em><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/11\/01\/chef-uova-pancetta-patate-rosti\/\"><strong>Chef<\/strong><\/a><\/em>&#8220;<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; e&#8217; nato questo post e questa ricetta.<\/p>\n<p style=\"text-align: justify;\">In rete si trovano diverse opzioni varie per la preparazione ma, come sempre, ho deciso di fare un mix ed ecco il risultato.<\/p>\n<p style=\"text-align: justify;\">Vi posso assicurare che e&#8217; risultato veramente tenero, un burro, tanto che si scioglieva direttamente in bocca!<\/p>\n<figure id=\"attachment_40505\" aria-describedby=\"caption-attachment-40505\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40505 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-40505\" class=\"wp-caption-text\">Guancia di vitello al vino rosso<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; <a href=\"https:\/\/www.agrodolce.it\/ricette\/guancia-di-vitello-brasata-al-vino-rosso\/\"><em>Guancia<\/em> di vitello al vino rosso<\/a> &#8211; 3 persone<\/strong><\/p>\n<pre>1kg di guancia di vitello\r\n500 ml di vino rosso\r\nbrodo vegetale\r\n2 carote\r\n2 cipolle\r\n1 foglia di alloro\r\n1 rametto di rosmarino\r\n1 rametto di timo (facoltativo)\r\n1 gambo di sedano (facoltativo)\r\n2 foglie di alloro (facoltativo)\r\n2 chiodi di garofano (facoltativo)\r\nfarina (facoltativo)\r\n40gr olio\/burro (*)\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate con l&#8217;affettare le cipolle, le carote e il sedano a dadini piccoli.<br \/>\nScaldate l&#8217;olio e fate soffriggere le verdure con\u00c2\u00a0 il rosmarino ed il timo, per poi lentamente fare appassire il tutto.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40501\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548986-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548986-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548986-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548986-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548986-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nSe utilizzate i chiodi di garofano e non volete disperderli immediatamente, appuntateli su un pezzo di cipolla.<\/p>\n<p style=\"text-align: justify;\">Asciugate le guance di vitello con della carta assorbente da cucina.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40500\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548975-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548975-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548975-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548975-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548975-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Rimuovete le verdure stufate, aggiungete la carne poco alla volta (dipende dalla dimensione della pentola che state usando) e fate rosolare la guancia a fuoco vivo, in modo da sigillare bene la carne da tutti i lati<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40498\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548954-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548954-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548954-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548954-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548954-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Se avete altra carne a disposizione, rimuovete quella cotta e sostituitela con quella ancora cruda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40499\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548964-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548964-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548964-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548964-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548964-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Al termine, reinserite sotto le verdure, poi disponete le guance di vitello al di sopra.<br \/>\nSalate e pepate, aggiungete le foglie di alloro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40497\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548943-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548943-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548943-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548943-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548943-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Alzate la fiamma e sfumate con un poco vino rosso, facendo evaporare la parte alcolica.<br \/>\nAggiungete il restante vino (oppure il brodo), poco alla volta, abbassate la fiamma quasi al minimo e coprite la pentola con il suo coperchio.<br \/>\nAggiungete altri mestoli di liquido al bisogno, non appena il fondo di cottura si ritira.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40496\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548931-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548931-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548931-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548931-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1674397548931-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Lasciate cuocere a fuoco bassissimo per almeno 3 ore o fino a che la carne non sar\u00c3\u00a0 diventata tenera e succosa.<br \/>\nRegolate di sale e pepe.<br \/>\nServite con il fondo di cottura (*)<\/p>\n<figure id=\"attachment_40508\" aria-describedby=\"caption-attachment-40508\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40508 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia4-1024x622.jpeg\" alt=\"\" width=\"525\" height=\"319\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia4-1024x622.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia4-150x91.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia4-300x182.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia4-768x466.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-40508\" class=\"wp-caption-text\">Guancia di vitello al vino rosso<\/figcaption><\/figure>\n<p>Potete accompagnare il piatto con della polenta, oppure con un pure&#8217;, oppure con contorni a base di patate, topinambur e barbabietole.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li>Se volete potete anche <strong>infarinare<\/strong> leggermente la carne prima di farla rosolare nella padella.<\/li>\n<li>Se lo gradite, una volta cotta la carne potete <strong>frullare il fondo<\/strong> di cottura e servirlo come salsa<strong>, oppure potete semplicemente filtrarlo<br \/>\n<\/strong><\/li>\n<li>Dopo 3 ore di <strong>cottura<\/strong>, ho spento (cucinato il sabato pomeriggio per la domenica a pranzo). L&#8217;indomani, mentre preparavo il pure&#8217;, ho proseguito la cottura, sempre lentamente.<\/li>\n<li>Solitamente nelle ricette classiche la guancia viene brasata con il <strong>Barolo<\/strong>, ma potete optare per altro vino bianco, o rosso, corposo.<\/li>\n<li>Per la preparazione del <strong>fondo<\/strong> e&#8217; possibile utilizzare solo olio, solo burro oppure un mis di entrambi<\/li>\n<li>Per sfumare potete utilizzare anche del vino <strong>Marsala<\/strong><\/li>\n<li>Per la cottura potete utilizzare solamente il vino prescelto, oppure sfumare la carne con il vino e proseguire la lenta cottura con del <strong>brodo<\/strong><\/li>\n<li>Per diminuire i tempi di cottura, e&#8217; possibile effettuare una <strong>marinatura<\/strong>.<\/li>\n<li style=\"text-align: justify;\">Per l&#8217;occasione, non ho utilizzato la pentola a pressione per la cottura, bensi&#8217; la mia pentola pesante di ghisa.<\/li>\n<\/ul>\n<figure id=\"attachment_40506\" aria-describedby=\"caption-attachment-40506\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-40506\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia2-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia2-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia2-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia2-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_guancia2-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-40506\" class=\"wp-caption-text\">Guancia di vitello al vino rosso<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Iniziamo con il dire che molti anni fa, la <strong>guancia<\/strong> era considerata un pezzo di carne decisamente non nobile.<br \/>\nAl giorno d&#8217;oggi, questa sua svalutazione si e&#8217; ridimensionata, iniziando a fare tendenza per conto suo.<br \/>\nNon e&#8217; piu&#8217; facile da trovare, tanto che per poterla acquistare bisogna proprio andare in magelleria (gioielleria, visto il prezzo) e prenotarla anticipatamente.<\/p>\n<p style=\"text-align: justify;\">Non vi nascondo la paura nel cucinarla e trattarla a dovere, visti i 67euro per circa 950gr!<\/p>\n<p style=\"text-align: justify;\">La guancia e&#8217; una parte estremamente ricca di muscoli, ma su cui l\u00e2\u20ac\u2122animale non appoggia mai il suo peso, ma che comunque e&#8217; sempre in movimento a causa della masticazione.<br \/>\nSe ne ricava una carne non grassa, ricca di fibre molto preziose, che se cotta con attenzione diventa succosa e saporita, battendo per gusto e consistenza anche i tagli pi\u00c3\u00b9 pregiati.<\/p>\n<p style=\"text-align: justify;\">La guancia (di vitello) e&#8217; molto utilizzata per preparare dei brasati e perfetta per le lunghe cotture, specialmente per la bassa temperatura.<br \/>\nQuesto significa lasciarla sobbollire nel brodo, o in un mix di brodo e vino, insieme a ingredienti aromatici come cipolla, aglio, sedano, carote e foglie di alloro.<br \/>\nDisponete la parte aromatica sotto e intorno la guancia, versate abbastanza liquido da coprire la carne per met\u00c3\u00a0 e lasciate sobbollire da tre a sei ore, poi fate il test della forchetta (cottura)<\/p>\n<p style=\"text-align: justify;\">Per controllare che questa carne sia cotta perfettamente, bisogna provare a punzecchiare i rebbi di una forchetta: la compattezza deve essere pari al burro, cosi&#8217; da riuscire ad estrarre la forchetta con estrema facilita&#8217;.<br \/>\nSe non volete brasarla per ore, un altro metodo per renderla tenera e lasciarla marinare per una notte.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tobias aveva voglia del brasato, io avevo deciso di preparare la guancia (di vitello), prendendo spunto dal film &#8220;Chef&#8220;<\/p>\n","protected":false},"author":2,"featured_media":40506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[249],"class_list":["post-40481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti","tag-dutch_oven"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=40481"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40481\/revisions"}],"predecessor-version":[{"id":40551,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40481\/revisions\/40551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/40506"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=40481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=40481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=40481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}