{"id":40455,"date":"2023-05-04T12:14:11","date_gmt":"2023-05-04T10:14:11","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=40455"},"modified":"2023-04-21T17:29:17","modified_gmt":"2023-04-21T15:29:17","slug":"minestrone-alla-toscana","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/05\/04\/minestrone-alla-toscana\/","title":{"rendered":"Minestrone alla toscana"},"content":{"rendered":"<p style=\"text-align: justify;\">Perche&#8217; non preparare un &#8220;<strong>Minestrone alla toscana<\/strong>&#8220;, ottimo pasto completo e saziante?<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">A mio avviso si tratta di un delizioso comfort food che aiuta e che rinvigorisce, senza intaccare troppo il regno animale?<\/p>\n<p style=\"text-align: justify;\">La filiera &#8220;<strong>Del Colle<\/strong>&#8221; inizia la sua passione per i cereali ed i legumi nel 1996, riscoprendo antiche variet\u00c3\u00a0 e produzioni caratteristiche della loro regione, la Toscana.<\/p>\n<p style=\"text-align: justify;\">La busta acquistata in italia, mi ha fornito un ottimo mix tradizionale di cereali e di legumi, composto da fagioli dall\u00e2\u20ac\u2122occhio, piselli verdi decorticati, farro perlato, orzo perlato, lenticchie rosse intere, lenticchie gialle decorticate, azuki verdi.<\/p>\n<p style=\"text-align: justify;\">Una vera sferzata di energia e di proteine vegetali a tutto campo!<\/p>\n<figure id=\"attachment_40458\" aria-describedby=\"caption-attachment-40458\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-40458\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_1674148102422-e1674148963691-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_1674148102422-e1674148963691-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_1674148102422-e1674148963691-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_1674148102422-e1674148963691-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_1674148102422-e1674148963691-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-40458\" class=\"wp-caption-text\">Minestrone alla toscana<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Per la preparazione della zuppa e&#8217; sufficiente seguire le istruzioni senza procedere all&#8217;ammollo anche se, personalmente, ho preferito (ri-)ciacquare preventivamente il prodotto,\u00c2\u00a0 come anche consigliato.<\/p>\n<p>La cottura e&#8217; stata fatta in una pentola pesante, evitando di utilizzare la pentola a pressione, procedendo lentamente ed a fuoco basso, come richiesto.<\/p>\n<figure id=\"attachment_40457\" aria-describedby=\"caption-attachment-40457\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-40457\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_mine1-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_mine1-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_mine1-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_mine1-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/05\/ok_mine1-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-40457\" class=\"wp-caption-text\">Minestrone alla toscana<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Un giro di olio a crudo prima della cottura e&#8230; la cena e&#8217; servita.<\/p>\n<p style=\"text-align: justify;\">Chiaramente e&#8217; possibile effettuare tutte le variazioni e personalizzazioni del caso, come un soffritto, l&#8217;aggiunta di aglio, l&#8217;inserimento di rosmarino fresco ed altro ancora.<\/p>\n<p style=\"text-align: justify;\">E dire che e&#8217; passato pochissimo tempo da quando avevo accennato ad una zuppa, magari toscana&#8230;<br \/>\nRicordate? ne facevo riferimento proprio qui con il &#8220;<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/04\/11\/pinocchio_cioccolata-calda\/\">Pinocchio di Guillermo del Toros<\/a><\/strong><\/em>&#8220;<\/p>\n<p style=\"text-align: justify;\">Spesso le mie parole si avverano. Chissa&#8217; la prossima volta a che cosa accennero&#8217;&#8230;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perche&#8217; non preparare un &#8220;Minestrone alla toscana&#8220;, ottimo pasto completo e saziante?<\/p>\n","protected":false},"author":2,"featured_media":40457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,138,51,57],"tags":[54,55,256],"class_list":["post-40455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-piatti_unici","category-primi_piatti","category-zuppa","tag-cereali","tag-legumi","tag-vegetariano"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=40455"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40455\/revisions"}],"predecessor-version":[{"id":41662,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40455\/revisions\/41662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/40457"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=40455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=40455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=40455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}