{"id":40440,"date":"2023-04-11T12:24:27","date_gmt":"2023-04-11T10:24:27","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=40440"},"modified":"2023-04-21T08:57:05","modified_gmt":"2023-04-21T06:57:05","slug":"pinocchio_cioccolata-calda","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/04\/11\/pinocchio_cioccolata-calda\/","title":{"rendered":"&#8220;Pinocchio di Guillermo del Toros&#8221; &#8211; Cioccolata calda"},"content":{"rendered":"<p style=\"text-align: justify;\">Avete gia&#8217; visto l&#8217;ultimo &#8220;<strong>Pinocchio di Guillermo del Toros&#8221;<\/strong>?<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Diciamo subito che questo Pinocchio non e&#8217; la solita storia, bensi una reinterpretazione della famosa favola, che tutti noi conosciamo, trasformato in un film d&#8217;animazione in stop-motion, del 2022, diretto dallo stesso Guillermo del Toro e da Mark Gustafson.<\/p>\n<figure id=\"attachment_40446\" aria-describedby=\"caption-attachment-40446\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40446 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino4.jpg\" alt=\"\" width=\"474\" height=\"316\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino4.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino4-150x100.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino4-300x200.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-40446\" class=\"wp-caption-text\">Immagine da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Anche in questo caso un pezzo di legno prende vita, sognando di diventare un bambino vero.<br \/>\nNon esiste il Paese dei Balocchi bensi&#8217; tutta la favola e&#8217; ambientata nell&#8217;Italia fascista degli anni &#8217;30.<\/p>\n<p style=\"text-align: justify;\">Il &#8220;<em>Pinocchio di Guillermo del Toros<\/em>&#8221; e&#8217; goloso, veramente goloso.<br \/>\nPiu&#8217; di una volta ha chiesto della<strong> cioccolata calda<\/strong> per acquietarsi un poco.<br \/>\nCome resistere a questa tentazione e non prepararla che io , per &#8220;celebrare&#8221; lo stop motion?<\/p>\n<p style=\"text-align: justify;\">Niente di che per la preparazione di questa bevanda.. ho solo aperto una busta di Ciobar che avevo ancora a disposizione a casa \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40444\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_pino2-1024x803.jpeg\" alt=\"\" width=\"525\" height=\"412\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_pino2-1024x803.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_pino2-150x118.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_pino2-300x235.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_pino2-768x602.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">A<strong> differenza della favola originale<\/strong>, il falegname Geppetto perde suo figlio in Italia durante la prima guerra mondiale a causa dell&#8217;esplosione di bombe sganciate da aeroplani.<br \/>\nGeppetto decide di piantare una pigna per far crescere un albero, proprio accanto alla tomba di suo figlio.<br \/>\nDopo vent&#8217;anni, Geppetto abbatte l&#8217;albero per scolpire un burattino di legno come surrogato di suo figlio, addormentandosi ubriaco prima del completamento del suo surrogato.<br \/>\nAppare un fantasma che d\u00c3\u00a0 vita al burattino di legno, chiamandolo Pinocchio, mentre il grillo parlante, di nome Sebastian, promette di prendersene cura.<\/p>\n<figure id=\"attachment_40447\" aria-describedby=\"caption-attachment-40447\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40447 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino3.jpg\" alt=\"\" width=\"474\" height=\"315\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino3.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino3-150x100.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino3-300x199.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-40447\" class=\"wp-caption-text\">Immagine da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Al risveglio di Geppetto questi non accetta Pinocchio come suo figlio, ma lentamente il suo modo inizia a cambiare.<br \/>\n&#8230;.<\/p>\n<p style=\"text-align: justify;\">Non voglio svelare oltre, il finale e&#8217; sempre lo stesso, ma e&#8217; la modalita&#8217; e l&#8217;ambiente circostante diverso.<br \/>\nNon vi resta che trovare una serata, prepararvi anche voi una cioccolata calda, magari con panna, ed iniziare la visione.<\/p>\n<figure id=\"attachment_40449\" aria-describedby=\"caption-attachment-40449\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40449 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino.jpg\" alt=\"\" width=\"474\" height=\"267\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino-300x169.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-40449\" class=\"wp-caption-text\">Immagine da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Che cosa e&#8217; lo &#8220;stop-motion&#8221;<\/strong> (da http:\/\/stop-motion.it\/tutorials-animazione-stop-motion\/cos-e-una-stop-motion\/ )?<\/p>\n<figure id=\"attachment_40445\" aria-describedby=\"caption-attachment-40445\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40445 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino5.jpg\" alt=\"\" width=\"474\" height=\"237\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino5.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino5-150x75.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/pino5-300x150.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-40445\" class=\"wp-caption-text\">Immagine da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La Stop-motion \u00c3\u00a8 una particolare tecnica di animazione che si effettua attraverso scatti fotografici.<br \/>\nCi\u00c3\u00b2 che la differenzia da un normale video \u00c3\u00a8 la sua natura, una stop-motion diviene video solo in fase di montaggio, prima di allora rimane ancora una serie di scatti fotografici. Grazie ad una stop-motion \u00c3\u00a8 possibile creare delle situazioni irreali come animare oggetti o pupazzi, creare sparizioni improvvise o sostituzioni di corpi etc..<br \/>\nSe la sequenza di immagini che avevamo deciso in fase di progettazione riesce a stupirci possiamo ritenerci soddisfatti.<br \/>\nLa stop-motion abbraccia in egual misura la fotografia, l\u00e2\u20ac\u2122utilizzo del computer e la creativit\u00c3\u00a0 di chi la mette in atto. Per realizzarla abbiamo bisogno di una macchina fotografica e di un soggetto da fotografare seguendo una logica di movimento, direzione e cambiamento, il computer servir\u00c3\u00a0 infine per montare i fotogrammi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40443\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_Pinocchio-576x1024.jpeg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_Pinocchio-576x1024.jpeg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_Pinocchio-84x150.jpeg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_Pinocchio-169x300.jpeg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/04\/ok_Pinocchio-768x1365.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avete gia&#8217; visto l&#8217;ultimo &#8220;Pinocchio di Guillermo del Toros&#8221;?<\/p>\n","protected":false},"author":2,"featured_media":40448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149,22],"tags":[84,251,129],"class_list":["post-40440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bevande","category-food","tag-cioccolato","tag-foodmedia","tag-tv_kino"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=40440"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40440\/revisions"}],"predecessor-version":[{"id":41656,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40440\/revisions\/41656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/40448"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=40440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=40440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=40440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}