{"id":40270,"date":"2023-01-01T18:30:14","date_gmt":"2023-01-01T17:30:14","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=40270"},"modified":"2023-01-06T18:54:40","modified_gmt":"2023-01-06T17:54:40","slug":"in-civilta-capodanno-e-botti","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2023\/01\/01\/in-civilta-capodanno-e-botti\/","title":{"rendered":"(In)-Civilta&#8217;. Capodanno e botti"},"content":{"rendered":"<p style=\"text-align: justify;\">Quando torno in Italia, ma anche quando parlo al telefono con il Nonno, e&#8217; sempre ad elogiare le persone tedesche, il loro spirito mentale, teutonico.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Il loro essere &#8220;forti&#8221;, la loro &#8220;infallibilita'&#8221;.<\/p>\n<p style=\"text-align: justify;\">Nessuno vede o si accorge veramente dell&#8217;altro lato della medaglia fino a quando non si vive con loro, a stretto contatto.<br \/>\nNon mi riferisco a Stephan, ma a gran parte del nostro vicinato.<\/p>\n<p style=\"text-align: justify;\">Alla loro mancanza di sensibilita&#8217;, al loro essere superiori ad ogni costo, al loro menefreghismo e mancanza di tatto.<br \/>\nNon voglie essere paragonata a chissa&#8217; chi, o superiore. Ma un minimo di educazione deve esistere, da entrambe le parti.<\/p>\n<p style=\"text-align: justify;\">Come si possono iniziare a sparare i fuochi d&#8217;artificio alle 17 del pomeriggio?<br \/>\nEd andare avanti per ore, senza un minimo di contegno?<br \/>\nLogicamente il tutto viene effettuato direttamente sotto casa, senza curarsi se il vicinato possiede animali domestici impauriti.<br \/>\nAl momento di aver fatto notare la situazione, il frastuono e&#8217; cessato.<\/p>\n<p style=\"text-align: justify;\">Poi &#8230; arriva la mezzanotte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40278\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847721-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847721-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847721-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847721-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847721-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ed ancora fuochi, suoni, luci, che si protraggono sino alle 2 di notte.<br \/>\nTralasciamo il rispetto per i beni comunali, mettendo i razzi all&#8217;interno dei tombini e dando fuoco alle micce.<br \/>\nTralasciamo il rispetto per i beni delle altre persone, calpestando i fiori e buttando l&#8217;eventuale spazzatura nei bidoni sbagliati.<br \/>\nTralasciamo il fracasso fatto fino a tardi, insomma, a Capodanno ci puo&#8217; anche stare&#8230; ma tutto ha un limite (ed un mal di testa da giorni).<\/p>\n<p style=\"text-align: justify;\">Arriviamo alla mattina.<br \/>\nAlla sporcizia lasciata, una vera orda di zozzoni, insomma.<\/p>\n<p style=\"text-align: justify;\">Dalla finestra di casa si nota una piccola raccolta di sporcizia, posta a lato della strada.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40277\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847698-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847698-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847698-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847698-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847698-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ed il resto?<br \/>\nE tutto cio&#8217; lasciato nei giardini privati?<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40276\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847628-e1673027553809-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847628-e1673027553809-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847628-e1673027553809-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847628-e1673027553809-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673024847628-e1673027553809-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Avro&#8217; sbagliato, lo so, ma non ho potuto farne a meno.<br \/>\nCome molti resti di castagnole erano &#8220;volati&#8221; nel mio giardinetto, la stessa fine hanno (ri-)fatto, ma senza il botto, quelli raccolti da me.<\/p>\n<p style=\"text-align: justify;\">Finalmente, alle 14, si sono fatti vivi alcuni, solo per conservare l&#8217;apparenza.<br \/>\nOramai il gioco e&#8217; fatto.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40275\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673027174642-e1673027339835-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673027174642-e1673027339835-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673027174642-e1673027339835-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673027174642-e1673027339835-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2023\/01\/ok_1673027174642-e1673027339835-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Brindiamo e dimentichiamo.<\/p>\n<p>Buon anno!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando torno in Italia, ma anche quando parlo al telefono con il Nonno, e&#8217; sempre ad elogiare le persone tedesche, il loro spirito mentale, teutonico.<\/p>\n","protected":false},"author":2,"featured_media":40278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[140],"class_list":["post-40270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-civilta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=40270"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40270\/revisions"}],"predecessor-version":[{"id":40281,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/40270\/revisions\/40281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/40278"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=40270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=40270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=40270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}