{"id":401,"date":"2018-01-17T18:39:17","date_gmt":"2018-01-17T17:39:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/occhi-chiusi\/"},"modified":"2018-09-02T08:56:08","modified_gmt":"2018-09-02T07:56:08","slug":"occhi-chiusi","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/17\/occhi-chiusi\/","title":{"rendered":"Occhi chiusi?"},"content":{"rendered":"<p style=\"text-align: justify;\">State ancora dormendo e vi siete svegliati nel cuore (?) della notte?<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Non sapete che ora e&#8217; e non trovate gli occhiali?<br \/>\nNonostante tutto, non riuscite a vedere la sveglia posta &#8211; piu&#8217; o meno &#8211; vicino a voi?<\/p>\n<p style=\"text-align: justify;\">Grazie al regalo natalizio fattoci da Zia Olja e Zio Roberto, non avrete nessun problema nel sapere l&#8217;orario \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12495\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sveglia1.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sveglia1.jpg 640w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sveglia1-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sveglia1-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Ecco una meravigliosa sveglia con visore illuminato e.. proiettore a soffitto\/muro dell&#8217;orario!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12496\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sveglia2.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sveglia2.jpg 640w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sveglia2-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/sveglia2-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Si, lo so, le foto non sono della miglior specie.<br \/>\nMa vi assicuro circa la sua perfetta funzionalita&#8217;!<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>State ancora dormendo e vi siete svegliati nel cuore (?) della notte?<\/p>\n","protected":false},"author":2,"featured_media":12495,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[157],"class_list":["post-401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","tag-acquisto"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=401"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/401\/revisions"}],"predecessor-version":[{"id":12497,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/401\/revisions\/12497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/12495"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}