{"id":39800,"date":"2022-12-15T10:59:26","date_gmt":"2022-12-15T09:59:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=39800"},"modified":"2022-11-29T17:06:59","modified_gmt":"2022-11-29T16:06:59","slug":"pseudo-camille-carota-mandorla","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/12\/15\/pseudo-camille-carota-mandorla\/","title":{"rendered":"Impasto camille (tortine carota-mandorla)"},"content":{"rendered":"<p style=\"text-align: justify;\">Quando si vive oltre confine, ogni tanto vengono le &#8220;voglie&#8221;&#8230; di cibo nazionale.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Quest&#8217;oggi e&#8217; toccato alle &#8220;<strong>camille<\/strong>&#8220;.<br \/>\nNon so neppure io bene il motivo, non e&#8217; che ne magiavo cosi&#8217; tante a casa, se le compariamo alle scorpacciate di Fiesta.<\/p>\n<p style=\"text-align: justify;\">Ad ogni modo, mi sono incaponita per volerle fare.. con risultati non certo ottimali, almeno nella vista.<br \/>\nAggiungiamo pure il fatto di non possedere gli stampini giusti, per creare la famosa semicupola,\u00c2\u00a0 cosi mi si sono arrabattata con quanto disponevo.L&#8217;unica volta che avevo utilizzato questi stampini di silicone, che poi non sono neppure bastati, era per le <em><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2013\/03\/21\/pseudo-ciambelline-mrday\/\"><strong>ciambelline MrDay<\/strong><\/a><\/em>!<\/p>\n<p style=\"text-align: justify;\">Mica si puo&#8217; possedere tutto ed usarlo una sola volta!!<\/p>\n<figure id=\"attachment_39833\" aria-describedby=\"caption-attachment-39833\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39833\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam1-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam1-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam1-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam1-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam1-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39833\" class=\"wp-caption-text\">Camille (tortine carota-mandorla)<\/figcaption><\/figure>\n<p>Ingredienti &#8211; <em><strong><a href=\"https:\/\/ricetta.it\/camille\">Impasto camille<\/a><\/strong><\/em> (tortine carota-mandorla) &#8211; dipende dalla dimensione degli stampi<\/p>\n<pre>3 uova\r\n200 g di zucchero semolato\r\n250 g di carote (al netto degli scarti) (*)\r\n150 g di olio di semi\r\n100 ml di succo d'arancia\r\nla scorza grattugiata di 1 arancia\r\n200 g di farina 00\r\n100 g di farina di mandorle\r\n16 g di lievito per dolci<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Preriscaldate il forno ventilato\u00c2\u00a0 a 170\u00c2\u00b0, oppure statico a 180\u00c2\u00b0.<\/p>\n<p style=\"text-align: justify;\">In una ciotola rompete le uova e unite lo zucchero semolato.<br \/>\nMontate con le fruste elettriche fino ad ottenere un composto chiaro e cremoso.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39817\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458761-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458761-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458761-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458761-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458761-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nLavate e pelate le carote, pesatele, quindi tagliatele a pezzetti e frullatele.<\/p>\n<p style=\"text-align: justify;\">Versate l&#8217;olio di semi direttamente nel boccale del frullatore e azionatelo ancora.<br \/>\nVersate le carote frullate nel composto di uova e zucchero e mescolate.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39816\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458750-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458750-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458750-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458750-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458750-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aromatizzate l&#8217;impasto con la scorza grattugiata di un&#8217;arancia e 100 ml di succo spremuto di arancia.<br \/>\nDopodich\u00c3\u00a9 setacciandoli, aggiungete la farina\u00c2\u00a0 e il lievito per dolci, e amalgamate bene, facendo attenzione ad eliminare tutti i &#8220;frati&#8221;.<\/p>\n<p style=\"text-align: justify;\">Completate con la farina di mandorle (o in alternativa mandorle pelate tritate finemente).<br \/>\nVersate con un mestolino il composto in uno forme in silicone.<br \/>\nNon raggiungete il bordo con l&#8217;impasto, lasciate qualche mm, poich\u00c3\u00a9 in cottura tender\u00c3\u00a0 a gonfiarsi.<\/p>\n<p style=\"text-align: justify;\">Cuocete in forno ventilato gi\u00c3\u00a0 caldo a 170\u00c2\u00b0 per 15 minuti, oppure statico a 180\u00c2\u00b0 per 15-20 minuti.<\/p>\n<p>\u00c2\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39815\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458736-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458736-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458736-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458736-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669714458736-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Per controllare la cottura, fate la prova stecchino: infilandolo nell&#8217;impasto deve uscire pulito.<br \/>\nSe cos\u00c3\u00ac non fosse, aumentate di qualche minuto il tempo (*).<\/p>\n<p style=\"text-align: justify;\">Fate raffreddare completamente, dopodich\u00c3\u00a9 sformatele e servitele .<\/p>\n<figure id=\"attachment_39834\" aria-describedby=\"caption-attachment-39834\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39834\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam2-1024x839.jpeg\" alt=\"\" width=\"525\" height=\"430\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam2-1024x839.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam2-150x123.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam2-300x246.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam2-768x630.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39834\" class=\"wp-caption-text\">Camille (tortine carota-mandorla)<\/figcaption><\/figure>\n<p><strong>Note Varie e Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Utilizzate delle <strong>carote fresche<\/strong>, buone, dolci. O il risultato sapra&#8217; di poco. Ho usato un pacchetto di carote gia&#8217; sminuzzate e&#8230; si e&#8217; notato il (mancato) gusto.<\/li>\n<li style=\"text-align: justify;\">Nonostante non sia necessario ungere o infarinare lo <strong>stampo di silicone,<\/strong> personalmente lo consiglio (visti i risultati da me ottenuti durante l&#8217;estrazione).<\/li>\n<li style=\"text-align: justify;\">Per la <strong>cottura<\/strong> ricordate di non appoggiare lo stampo su una leccarda ma direttamente sulla griglia del forno, questo permette una cottura pi\u00c3\u00b9 uniforme e di non bruciare il fondo delle tortine.<\/li>\n<li style=\"text-align: justify;\">Il <strong>tempo di cottura<\/strong> e&#8217; indicativo. Molto dipende dal proprio forno, ma anche dalla dimensione degli stampi in silicone utilizzati.<\/li>\n<li style=\"text-align: justify;\">Personalmente non avevo gli <strong>stampi<\/strong> della forma e dimensione richiesti (semisgere di 8cm di diametro), cosi&#8217; ho utilizzato quanto in mio possesso, comprese le formine cartacee dei muffin.<br \/>\nSicuramente avrei fatto decisamente meglio ad inserire l&#8217;impasto in una tortiera.<\/li>\n<li style=\"text-align: justify;\">Se non avete la<strong> farina di mandorle<\/strong> potete tritare finemente delle mandorle pelate.<\/li>\n<li style=\"text-align: justify;\">Le camille si <strong>conservano<\/strong> per 3-4 giorni in un contenitore ermetico.<\/li>\n<li style=\"text-align: justify;\">Prima di toglierle dagli stampini \u00c3\u00a8 necessario <strong>farli raffreddare<\/strong> completamente: in caso contrario tenderanno a rompersi.<\/li>\n<\/ul>\n<figure id=\"attachment_39835\" aria-describedby=\"caption-attachment-39835\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39835\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam3-1024x602.jpeg\" alt=\"\" width=\"525\" height=\"309\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam3-1024x602.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam3-150x88.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam3-300x176.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_cam3-768x451.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39835\" class=\"wp-caption-text\">Camille (tortine carota-mandorla)<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando si vive oltre confine, ogni tanto vengono le &#8220;voglie&#8221;&#8230; di cibo nazionale.<\/p>\n","protected":false},"author":2,"featured_media":39835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,80],"tags":[258,88],"class_list":["post-39800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-muffins","tag-colazione","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=39800"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39800\/revisions"}],"predecessor-version":[{"id":39836,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39800\/revisions\/39836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/39835"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=39800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=39800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=39800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}