{"id":397,"date":"2018-11-17T13:39:17","date_gmt":"2018-11-17T12:39:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/vellutata-alla-zucca-e-sedano-rapa\/"},"modified":"2022-10-21T15:20:16","modified_gmt":"2022-10-21T13:20:16","slug":"vellutata-alla-zucca-e-sedano-rapa","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/11\/17\/vellutata-alla-zucca-e-sedano-rapa\/","title":{"rendered":"Vellutata alla zucca ( e sedano rapa)"},"content":{"rendered":"<p style=\"text-align: justify;\">Soliti della solita minestra?<br \/>\nA casa non si mangia abbastanza verdura e voi ne sentite la mancanza?<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Perche&#8217; non provate a preparare questa fantastica <strong>VELLUTATA di zucca (e sedano rapa)<\/strong>?<br \/>\nVi assicuro che il gusto non ne risente e, soprattutto, anche la vostra linea.<\/p>\n<p style=\"text-align: justify;\">La ricetta l&#8217;ho scovata nel vecchio faldone con gli articoli tratti da vecchie rivista di cucina.<\/p>\n<p style=\"text-align: justify;\">In particolare questa e&#8217; di CucinareBene (non ricordo la data, sicuramente piu&#8217; di 10 anni fa).<\/p>\n<figure id=\"attachment_13868\" aria-describedby=\"caption-attachment-13868\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13868 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7590.jpg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7590.jpg 640w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7590-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7590-300x169.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-13868\" class=\"wp-caption-text\">Vellutata alla zucca ( e sedano rapa)<\/figcaption><\/figure>\n<p>Le indicazioni si riferiscono a 6 porzioni, ma noi l&#8217;abbiamo divisa in 4.<\/p>\n<p style=\"text-align: justify;\">Tra () le quantita&#8217; da me usate per necessita&#8217; (evitando di lasciare piccole parti):<\/p>\n<p><strong>Ingredienti &#8211; Vellutata alla zucca ( e sedano rapa) &#8211; 4\/6 porzioni<br \/>\n<\/strong><\/p>\n<pre>250gr polpa di zucca (<i> 300gr <\/i>)\r\n80gr sedano rapa (<i> 100gr<\/i> )\r\n240gr cipolle ( <i>180gr<\/i> )\r\n5gr bacche di coriandolo ( <i>noce moscata una generosa grattata<\/i> )\r\n25gr burro (<i> 10gr<\/i> )\r\n20ml olio di oliva ( <i>1 cucchiaino <\/i>)\r\n300ml latte ( <i>parzialmente scremato<\/i> )\r\n20gr panna fresca ( <i>ricotta<\/i> )\r\npepe e sale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sbucciate il sedano rapa con un pelapatate, tagliatelo a pezzi non troppo grandi, e lo stesso fatelo con la zucca.<br \/>\nSbucciate e tritate finemente le cipolle con la mezzaluna<br \/>\nVersate l&#8217;olio ed il burro in una casseruola, fatelo sciogliere (eventualmente potete ometterli, inserendo un goccino di acqua).<br \/>\nAggiungete il trito di cipolle, mescolate con un cucchiaio di legno 2 minuti.<br \/>\nUnite le bacche di coriandolo (<i>noce moscata<\/i>) e i pezzi di sedano rapa e\u00c2\u00a0 zucca.<\/p>\n<p style=\"text-align: justify;\">Coprite e cuocete 20 minuti a fuoco vivace, mescolando spesso.<br \/>\nScolate le verdure e passatele al setaccio per ridurle a purea (<i>bamix direttamente nella pentola<\/i>), raccoglie il passato preparato e reinseritelo\u00c2\u00a0 nuovamente nella casseruola.<\/p>\n<p style=\"text-align: justify;\">Portate a ebollizione il latte (<i>nel micro<\/i>).<\/p>\n<p style=\"text-align: justify;\">Aggiungete\u00c2\u00a0 il latte a filo nella casseruola delle verdure, mescolando con il cucchiaio di legno per amalgamare uniformemente il composto.<br \/>\nAggiungete la panna (ricotta), insaporite con sale e pepe e terminate la cottura altri 5 minuti.<br \/>\nTogliete dal fuoco e lasciate riposare 5 minuti; salate e pepate se necessario, mescolate.<br \/>\nVersate la vellutata di zucca e servitela subito, ben calda.<\/p>\n<p style=\"text-align: justify;\">Devo ammettere che e&#8217; veramente ottima, tanto che anche Tobias l&#8217;ha mangiata.<\/p>\n<p style=\"text-align: justify;\">Vabbe&#8217;, non ho detto tutte le verdure contenute, ma lui non me lo ha chiesto \ud83d\ude42<\/p>\n<p>Si, lo so, la foto non ne rende giustizia!<\/p>\n<p><span style=\"color: #ff0000;\">Un po\u00e2\u20ac\u2122 di calcoli ProPoints:<\/span><\/p>\n<p style=\"text-align: justify;\">?pp &#8211; 100gr zucca sono 0pp<br \/>\n0pp &#8211; 100gr sedano rapa<br \/>\n0pp &#8211; 180gr cipolle<br \/>\n0pp &#8211; bacche di coriandolo\/noce moscata<br \/>\n1pp &#8211; 10gr burro<br \/>\n1pp &#8211; 1 cucchiaino olio di oliva<br \/>\n3pp &#8211; 250ml latte ( parzialmente scremato )<br \/>\n1pp &#8211; 30gr ricotta<br \/>\n0pp &#8211; pepe e sale<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">6 PP in totale , quindi 2PP scarsi a persona.<\/span><br \/>\nNon ho inserito gli esatti pesi utilizzati nella ricetta, dato che dipende molto dalla quantita&#8217; del prodotto finale che volete ottenere.<br \/>\nI punteggi PP sono dati in base ai valori medi.<\/p>\n<p style=\"text-align: justify;\">\nUn po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soliti della solita minestra? A casa non si mangia abbastanza verdura e voi ne sentite la mancanza?<\/p>\n","protected":false},"author":2,"featured_media":13868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,51,57],"tags":[49],"class_list":["post-397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-primi_piatti","category-zuppa","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=397"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/397\/revisions"}],"predecessor-version":[{"id":39236,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/397\/revisions\/39236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/13868"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}