{"id":39689,"date":"2022-12-19T12:26:15","date_gmt":"2022-12-19T11:26:15","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=39689"},"modified":"2023-07-05T13:08:46","modified_gmt":"2023-07-05T11:08:46","slug":"vita-zucchina_frittelle-zucchina","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/12\/19\/vita-zucchina_frittelle-zucchina\/","title":{"rendered":"&#8220;La mia vita da Zucchina&#8221; &#8211; Frittelle di zucchina"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>&#8220;La mia vita da Zucchina&#8221;<\/strong> (<strong>&#8220;Ma vie de Courgette&#8221;<\/strong>) \u00c3\u00a8 un film del 2016 diretto da Claude Barras.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Basato sul romanzo &#8220;Autobiografia di una zucchina&#8221; di Gilles Paris (poi riedito con il titolo del film), rappresenta l&#8217;esordio di Barras nel lungometraggio ed \u00c3\u00a8 realizzato in animazione a passo uno.<\/p>\n<figure id=\"attachment_39727\" aria-describedby=\"caption-attachment-39727\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39727 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/zucchina2.jpg\" alt=\"\" width=\"474\" height=\"286\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/zucchina2.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/zucchina2-150x91.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/zucchina2-300x181.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-39727\" class=\"wp-caption-text\">&#8220;La mia vita da zucchina&#8221; &#8211; Immagine da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">E&#8217; un\u00c2\u00a0 lungometraggio animato che non si guarda principalmente per i disegni, quanto per la storia e gli insegnamenti che vuole dare.<\/p>\n<p style=\"text-align: justify;\">A volte e&#8217; crudo e diretto, tanto da poter sconcertare chi lo guarda.<br \/>\nDiciamo che, a mio parere, non e&#8217; proprio adattissimo ai bambini piccoli, soprattutto se lasciati soli davanti alla televisione.<\/p>\n<p style=\"text-align: justify;\">Si affrontano temi difficili, come bambini vittime di abusi, abbandonati, con genitori uccisi o in prigione, per questo penso che per la visione e&#8217; gradita\u00c2\u00a0 la presenza dei genitori, per poter aiutare a spiegare queste situazioni.<\/p>\n<p style=\"text-align: justify;\">Non manca, inoltre, un lato relativamente comico a tutto questo, giusto per sollevare la drammaticita&#8217;.<\/p>\n<p style=\"text-align: justify;\">Il messaggio, diretto e crudele, e&#8217; ben prefissato: nessuno ce la fa da solo, ma il gruppo puo&#8217; aiutare a fare la forza e, insieme, a risolvere le situazioni.<br \/>\nNessuno viene abbandonato e lo spirito dell&#8217;unita&#8217; e&#8217; rimarcata.<br \/>\nLa speranza non muore mai, come l&#8217;amicizia.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">\u00e2\u20ac\u0153Noi siamo come dei fiori selvatici che nessuno ha voglia di cogliere&#8221;<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Per questo motivo ho pensato di cucinare qualcosa con la zucchina: prima tagliuzzata e cruda, come l&#8217;essere umano. Poi spremuta per estrarre tutto cio&#8217; che e&#8217; superfluo. Per poi essere unita ad altri ingredienti, pochi, ma che producono un ottimo risultato insieme, ben amalgamati.<br \/>\nProprio come l&#8217;esistenza di &#8220;Zucchina&#8221; stessa, secondo me.<\/p>\n<figure id=\"attachment_39738\" aria-describedby=\"caption-attachment-39738\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39738\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frittelle-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frittelle-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frittelle-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frittelle-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frittelle-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39738\" class=\"wp-caption-text\">Frittelle di zucchina<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; <a href=\"https:\/\/eatsmarter.de\/rezepte\/zucchini-puffer\"><em>Zucchini puffer \/\/ frittelle di zucchina<\/em><\/a><\/strong> &#8211; 4 persone<\/p>\n<pre>1 cipolla\r\n1 spicchio d'aglio\r\n3 cucchiai di olio d'oliva\r\n800 grammi di zucchine\r\nsale\r\n3 uova\r\n8 cucchiai di farina di farro integrale\r\npepe\r\n2 cucchiai di pangrattato integrale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sbucciate la cipolla e l&#8217;aglio e tritateli finemente.<br \/>\nScaldate un goccio di olio in una padella e rosolateli a fuoco medio, finch\u00c3\u00a9 non diventano traslucidi.<br \/>\nRimuovete la padella dal fuoco e lasciate raffreddare.<\/p>\n<p style=\"text-align: justify;\">\u00c2\u00a0Lavate le zucchine, pulitele e grattugiatele, mettetele in un colino, aggiustate di sale e lasciate riposare per circa 15-20 minuti.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39737\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112964-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112964-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112964-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112964-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112964-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nQuindi spremere bene e mescolatele con il composto di cipolle.<\/p>\n<p style=\"text-align: justify;\">Sbattete le uova con la farina e mescolatele con le zucchine grattugiate.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39736\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112954-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112954-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112954-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112954-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112954-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nAggiustate di pepe e aggiungete abbastanza pangrattato fino ad ottenere un composto spumoso ma non pi\u00c3\u00b9 liquido.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39735\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112945-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112945-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112945-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112945-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112945-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nScaldate un cucchiaio di olio in una padella e adagiatevi dei mucchietti di pasta (*).<\/p>\n<p style=\"text-align: justify;\">Appiattiteli leggermente e friggerli su entrambi i lati a fuoco medio fino a doratura.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39734\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112936-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112936-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112936-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112936-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_1669384112936-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Tenere in caldo le frittelle cotte prima di servirle<\/p>\n<figure id=\"attachment_39739\" aria-describedby=\"caption-attachment-39739\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39739\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frit1-1024x543.jpeg\" alt=\"\" width=\"525\" height=\"278\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frit1-1024x543.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frit1-150x80.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frit1-300x159.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/12\/ok_frit1-768x407.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39739\" class=\"wp-caption-text\">Frittelle di zucchina<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Ho evitato di fare delle<strong> piccole frittelle<\/strong>, propendendo per una grossa.<\/li>\n<li style=\"text-align: justify;\">Nel mio caso ho<strong> diviso gli ingredienti<\/strong>, cosi&#8217; da preparare per una sola persona.<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">Icare \u00c3\u00a8 un bambino di nove anni che vive con la madre, alcolizzata da quando il marito li ha abbandonati. Un giorno, Icare fa cadere una pila di lattine di birra con cui stava giocando in soffitta, disturbando la madre; la donna prova a salire in soffitta per punirlo fisicamente e Icare le chiude la botola sulla testa, spingendola inavvertitamente gi\u00c3\u00b9 per le scale e causandone la morte.<\/p>\n<figure id=\"attachment_39726\" aria-describedby=\"caption-attachment-39726\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39726 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/zucchina3.jpg\" alt=\"\" width=\"474\" height=\"266\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/zucchina3.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/zucchina3-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/zucchina3-300x168.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-39726\" class=\"wp-caption-text\">&#8220;La mia vita da zucchina&#8221; &#8211; Immagine da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Successivamente il bambino fa una deposizione all&#8217;agente di polizia Raymond, informandolo che preferisce essere chiamato &#8220;Zucchina&#8221;, come lo aveva soprannominato la madre. Essendo rimasto solo, Icare viene portato da Raymond in un orfanotrofio; si porta con s\u00c3\u00a9 solo una lattina di birra e un aquilone con sopra il disegno di un supereroe, ricordi rispettivamente di sua madre e suo padre.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La mia vita da Zucchina&#8221; (&#8220;Ma vie de Courgette&#8221;) \u00c3\u00a8 un film del 2016 diretto da Claude Barras.<\/p>\n","protected":false},"author":2,"featured_media":39728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148,22,60,61,63],"tags":[251,265,129,256],"class_list":["post-39689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antipasti","category-food","category-secondi_piatti","category-uova-formaggio","category-vegetariani","tag-foodmedia","tag-nascondo_le_verdure","tag-tv_kino","tag-vegetariano"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=39689"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39689\/revisions"}],"predecessor-version":[{"id":39742,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39689\/revisions\/39742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/39728"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=39689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=39689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=39689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}