{"id":39419,"date":"2022-11-15T12:18:10","date_gmt":"2022-11-15T11:18:10","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=39419"},"modified":"2022-11-09T15:28:52","modified_gmt":"2022-11-09T14:28:52","slug":"trancio-di-salmone-al-pepe","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/11\/15\/trancio-di-salmone-al-pepe\/","title":{"rendered":"Trancio di salmone al pepe."},"content":{"rendered":"<p style=\"text-align: justify;\">Ho acquistato dei <strong>tranci di salmone<\/strong> al supermercato.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Non avendo idea di come prepararli ho sfogliato un po&#8217; delle mie riviste o meglio, pagine cartacee divise nei raccoglitori.<\/p>\n<p style=\"text-align: justify;\">Nella sezione &#8220;<strong>pesce<\/strong>&#8221; mi e&#8217; balzata all&#8217;occhio questa ricettina facile e veloce di tranci al pepe.<\/p>\n<p style=\"text-align: justify;\">Stranamente avevo tutti gli ingredienti in casa, cosi&#8217; mi sono data da fare per prepararla per la cena.<\/p>\n<p style=\"text-align: justify;\">Oggi, poi, non so come mi e&#8217; venuto un dubbio ed ho provato a cercarla nel mio blog. Sorpresa, l&#8217;avevo <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2007\/09\/03\/trancio-tonno-pepe\/\">gia&#8217; cucinata<\/a><\/strong><\/em> ma sostituendo il salmone al tonno.<br \/>\nSe l&#8217;idea era presente nei miei faldoni, sicuramente perche&#8217; era semplice e, soprattutto, piaciuta.<\/p>\n<p style=\"text-align: justify;\">Provatela anche voi, e fatemelo sapere!<\/p>\n<figure id=\"attachment_39432\" aria-describedby=\"caption-attachment-39432\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39432\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39432\" class=\"wp-caption-text\">Trancio di salmone al pepe<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Trancio di salmone al pepe &#8211; 4 persone<\/strong><\/p>\n<pre>tranci di salmone (*) - circa 500gr\r\n1 spicchio di aglio\r\n3 cucchiai (scarsi) di olio (*)\r\n1\/2 cucchiaio di pepe verde (*)\r\n1\/2 cucchiaio di pepe rosa\r\n1\/2 cucchiaio di salsa di soia<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Spremete lo spicchio d&#8217;aglio (o tagliatelo sottile) ed unitelo all&#8217;olio ed alla salsa di soia, in un bicchierino.<br \/>\nMescolate velocemente il tutto con una forchetta.<\/p>\n<p style=\"text-align: justify;\">Mettete i tranci di salmone in una terrina, cospargeteli con il pepe rosa e verde ed irrorateli con la salsina.<\/p>\n<figure id=\"attachment_39429\" aria-describedby=\"caption-attachment-39429\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39429\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248695-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248695-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248695-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248695-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248695-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39429\" class=\"wp-caption-text\">Trancio di salmone al pepe<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Copriteli con pellicola e lasciate marinare in frigo per qualche ora, rigirandoli ogni tanto, cosi&#8217; da insaporirsi bene.<\/p>\n<p style=\"text-align: justify;\">Trasferite il pesce in una teglia foderata con carta forno, versatevi sopra la marinata e mettete in forno gia&#8217; caldo, statico, a 180gradi.<\/p>\n<figure id=\"attachment_39430\" aria-describedby=\"caption-attachment-39430\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39430\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248678-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248678-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248678-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248678-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248678-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39430\" class=\"wp-caption-text\">Trancio di salmone al pepe<\/figcaption><\/figure>\n<figure id=\"attachment_39431\" aria-describedby=\"caption-attachment-39431\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39431\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248663-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248663-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248663-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248663-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248663-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39431\" class=\"wp-caption-text\">Trancio di salmone al pepe<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cuocete 10-15 minuti, secondo lo spessore del pesce (*).<\/p>\n<figure id=\"attachment_39432\" aria-describedby=\"caption-attachment-39432\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39432\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248646-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39432\" class=\"wp-caption-text\">Trancio di salmone al pepe<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Servite i tranci ben cosparsi dalla salsina rilasciata dopo la cottura.<\/p>\n<figure id=\"attachment_39433\" aria-describedby=\"caption-attachment-39433\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39433\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248630-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248630-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248630-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248630-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/11\/ok_1667977248630-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39433\" class=\"wp-caption-text\">Trancio di salmone al pepe<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Come ho scritto in precedenza, e&#8217; possibile <strong>sostituire<\/strong> il salmone anche con tonno<\/li>\n<li style=\"text-align: justify;\">Per il tonno, asciutto, potete inserire qualche cucchiaio in piu&#8217; di <strong>olio<\/strong>. Per il salmone&#8230; meglio di no.<\/li>\n<li style=\"text-align: justify;\">Il mio <strong>pepe verde<\/strong> era in salamoia.<\/li>\n<li style=\"text-align: justify;\">I nostri tranci erano abbastanza alti, cosi&#8217; la <strong>cottura<\/strong> si e&#8217; prolungata ad una ventina di minuti.<\/li>\n<\/ul>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ho acquistato dei tranci di salmone al supermercato.<\/p>\n","protected":false},"author":2,"featured_media":39433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,77,60],"tags":[257,106],"class_list":["post-39419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pesce","category-secondi_piatti","tag-light","tag-ricetta_perfetta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=39419"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39419\/revisions"}],"predecessor-version":[{"id":39436,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39419\/revisions\/39436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/39433"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=39419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=39419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=39419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}