{"id":39114,"date":"2022-10-18T09:59:26","date_gmt":"2022-10-18T07:59:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=39114"},"modified":"2022-10-16T15:59:44","modified_gmt":"2022-10-16T13:59:44","slug":"dm-bio-pancakes-di-zucca-speziati","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/10\/18\/dm-bio-pancakes-di-zucca-speziati\/","title":{"rendered":"DM Bio &#8211; Pancakes di zucca speziati"},"content":{"rendered":"<p style=\"text-align: justify;\">Cosa c&#8217;e&#8217; di piu&#8217; bello dell&#8217;autunno?<\/p>\n<p style=\"text-align: justify;\">Per me e&#8217; la stagione preferita, piu&#8217; ancora della primavera.<br \/>\nI suoi colori mi mettono allegria, riempiendo il cuore. Molto di piu&#8217; che il vedere i boccioli di fiori, in effetti.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Per non parlare delle zucche.<br \/>\nUn vero benessere per la mia anima.. ed il mio stomaco.<\/p>\n<p style=\"text-align: justify;\">Perche&#8217; non iniziare in bellezza, in una calda domenica di meta&#8217; ottobre, con degli ottimi pancakes alla zucca speziata?<\/p>\n<p style=\"text-align: justify;\">Durante il mio ultimo giro da DM Ho trovato questo preparato (prodotto secco) della <strong>DM Bio &#8211; Pancakes di zucca speziati (Pumpkin spice pancakes)<\/strong><\/p>\n<figure id=\"attachment_39120\" aria-describedby=\"caption-attachment-39120\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39120 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059334-666x1024.jpg\" alt=\"\" width=\"525\" height=\"807\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059334-666x1024.jpg 666w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059334-97x150.jpg 97w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059334-195x300.jpg 195w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059334-768x1182.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39120\" class=\"wp-caption-text\">DM Bio &#8211; Pancakes di zucca speziati (Pumpkin spice pancakes)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">cosi&#8217; ho pensato bene di acquistarli per provarli.<\/p>\n<p style=\"text-align: justify;\">La facilita&#8217; nella preparazione e&#8217; stata subito evidente, anche se ho avuto un lieve pensiero circa l&#8217;aggiunta dell&#8217;acqua minerale (&#8220;Mineralwasser&#8221;): con o senza bollicine?<br \/>\nAlla fine le ho inserite, insieme a del latte di mucca (suggeriva quello di soia) e dell&#8217;olio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39119\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059325-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059325-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059325-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059325-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059325-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">L&#8217;impasto e&#8217; risultato morbido, ma non liquido, consistente e la tenuta durante la cottura (sulla piastra delle crepes, logicamente), perfetta.<\/p>\n<p style=\"text-align: justify;\">Come non iniziare bene la giornata?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39118\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059316-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059316-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059316-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059316-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_1665928059316-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">E voi, come preferite iniziare la giornata?<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cosa c&#8217;e&#8217; di piu&#8217; bello dell&#8217;autunno? Per me e&#8217; la stagione preferita, piu&#8217; ancora della primavera. I suoi colori mi mettono allegria, riempiendo il cuore. Molto di piu&#8217; che il vedere i boccioli di fiori, in effetti.<\/p>\n","protected":false},"author":2,"featured_media":39119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,80],"tags":[],"class_list":["post-39114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-muffins"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=39114"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39114\/revisions"}],"predecessor-version":[{"id":39124,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39114\/revisions\/39124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/39119"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=39114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=39114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=39114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}