{"id":39095,"date":"2022-10-13T12:07:05","date_gmt":"2022-10-13T10:07:05","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=39095"},"modified":"2022-10-21T14:38:59","modified_gmt":"2022-10-21T12:38:59","slug":"ossobuco_pap","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/10\/13\/ossobuco_pap\/","title":{"rendered":"Ossibuchi in pentola a pressione"},"content":{"rendered":"<p style=\"text-align: justify;\">Avevo voglia di qualche cibo italiano, cosi&#8217; ho acquistato degli ossi buchi.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nIn questa stagione autunnale, poi, ci stanno veramente bene, Per me e&#8217; proprio un comfort food!<\/p>\n<p style=\"text-align: justify;\">Questa volta la ricetta l&#8217;ho presa direttamente dal ricettario della pentola a pressione Lagostina.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-39102\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_IMG_20221009_132929-01-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_IMG_20221009_132929-01-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_IMG_20221009_132929-01-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_IMG_20221009_132929-01-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_IMG_20221009_132929-01-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ottima e veloce!<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Ossibuchi in pentola a pressione &#8211; 4 persone<\/strong><\/p>\n<pre>4 ossi buchi (circa 600-700gr)\r\n80gr di burro\r\n1\/2 bicchiere di vino bianco secco\r\n<strong>battuto con:<\/strong>\r\n sedano\r\n carota\r\n prezzemolo\r\n cipolla\r\n scorza di limone\r\n1 scatola di pelati (250gr)\r\n1\/2 bicchiere di brodo (anche di dado)\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Nella pentola scoperta fate dorare gli ossibuchi in burro imbiondito, spruzzate con il vino bianco, lasciatelo evaporare, salate e pepate.<br \/>\nUnite il battuto di sedano, carota, prezzemolo, cipolla e scorza di limone grattugiata.<\/p>\n<p style=\"text-align: justify;\">Lasciate insaporire poi aggiungete i pomodori pelati ed il brodo.<br \/>\nChiudete la pentola, all&#8217;inizio del sibilo abbassate la fiamma e calcolate 45 minuti di cottura.<\/p>\n<figure id=\"attachment_39104\" aria-describedby=\"caption-attachment-39104\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-39104\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_osso3-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_osso3-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_osso3-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_osso3-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/10\/ok_osso3-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-39104\" class=\"wp-caption-text\">Ossobuco<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Servite gli ossi buchi preferibilmente con il risotto oppure con un pure&#8217; di patate.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Tagliuzzate il bordo della carne, cosi&#8217; da evitare che si arricci durante la cottura.<\/li>\n<li style=\"text-align: justify;\">Se la carne e&#8217; abbastanza grande, fate dorare gli ossibuchi pochi per volta.<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">Decisamente questo e&#8217; un grande piatto della cucina italiana, lombarda in particolare.<br \/>\nEcco perche&#8217; ho pensato di riproporlo, anche, per il mio FoodMEDIA e per tutti gli\/le appassionati, come me, del <strong>Paradiso delle Signore<\/strong>.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avevo voglia di qualche cibo italiano, cosi&#8217; ho acquistato degli ossi buchi.<\/p>\n","protected":false},"author":2,"featured_media":39104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,180,60],"tags":[251,53,129],"class_list":["post-39095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-pentola-a-pressione","category-secondi_piatti","tag-foodmedia","tag-pentola_a_pressione","tag-tv_kino"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=39095"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39095\/revisions"}],"predecessor-version":[{"id":39220,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/39095\/revisions\/39220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/39104"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=39095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=39095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=39095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}