{"id":38600,"date":"2022-10-05T12:09:40","date_gmt":"2022-10-05T10:09:40","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=38600"},"modified":"2022-09-16T19:03:48","modified_gmt":"2022-09-16T17:03:48","slug":"e-oggi-cosa-cucino","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/10\/05\/e-oggi-cosa-cucino\/","title":{"rendered":"E oggi, cosa cucino?"},"content":{"rendered":"<p style=\"text-align: justify;\">Non so se anche voi avete il problema del &#8220;<em><strong>E oggi, cosa cucino?<\/strong><\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Di sicuro&#8230; io si.<\/p>\n<p style=\"text-align: justify;\">Da quando sono a dieta, poi, questa necessita&#8217; me la auto-richiedo.<br \/>\nL&#8217;essere a dieta o meglio il seguire un regime di alimentazione controllata senza regole e senza un doppio controllo &#8220;superiore&#8221; (nutrizionista, dietologo, gruppo di sostegno) puo&#8217; portare a diverse conseguenze:<\/p>\n<ul>\n<li style=\"text-align: justify;\">il mangiare sempre le stesse cose, perche&#8217; piacciono o sono facili da preparare<\/li>\n<li style=\"text-align: justify;\">la monotonia del piatto, con la conseguenza che si sgarra piu&#8217; facilmente.<\/li>\n<\/ul>\n<figure id=\"attachment_38698\" aria-describedby=\"caption-attachment-38698\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38698\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda.jpg\" alt=\"\" width=\"474\" height=\"355\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda-150x112.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda-300x225.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-38698\" class=\"wp-caption-text\">Da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ecco, io vorrei evitare di sgarrare piu&#8217; spesso di quanto faccia solitamente, cosi&#8217; che, da qualche anno, ho iniziato a preparare un plan (bi-)settimana del cibo.<\/p>\n<p style=\"text-align: justify;\">Ho notato che, in questo modo, ottengo ulteriori vantaggi\/benefici<\/p>\n<ul>\n<li style=\"text-align: justify;\">risparmio tempo e denaro quando faccio i miei acquisti<\/li>\n<li style=\"text-align: justify;\">spreco meno cibo perche&#8217; riesco a terminarlo piu&#8217; facilmente<\/li>\n<li style=\"text-align: justify;\">effettuo i miei acquisti meno spesso (avendo una sola automobile, la devo condividere con il marito)<\/li>\n<li style=\"text-align: justify;\">ho la possibilita&#8217; di riutilizzare il cibo preparato in altro modo, o le eventuali confezioni non terminate<\/li>\n<li style=\"text-align: justify;\">posso giostrarmi sulla preparazione dei piatti piu&#8217; facilmente.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_38697\" aria-describedby=\"caption-attachment-38697\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38697\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda2.jpg\" alt=\"\" width=\"474\" height=\"474\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda2.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda2-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda2-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/domanda2-100x100.jpg 100w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-38697\" class=\"wp-caption-text\">Da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Con una pianificazione la mia vita si semplifica decisamente.<br \/>\nUna volta che ci si ingrana, si impiega veramente poco tempo nella sua consultazione e, eventualmente, anche nello spostamento delle preparazioni.<\/p>\n<p style=\"text-align: justify;\">Senza contare che si riesce a giostrare la settimana abbastanza bene, mangiando di tutto: carne, pesce, uova, legumi e&#8230; PIZZA (o giornata libera, che dir si voglia).<br \/>\nLe giornate non sono rigide, ma flessibili cosi&#8217; da adattarsi alle esigenze: un pasto leggero e veloce si si ha un appuntamento medico alle 14, oppure una partita di tennis da tavolo (per Stephan).<\/p>\n<p style=\"text-align: justify;\">Se si vive in famiglia, o si ha una famiglia, allora inevitabile e&#8217; anche l&#8217;adottare un calendario comune, giusto per avere sott&#8217;occhio tutti gli appuntamenti.<br \/>\nA tal proposito noi ne abbiamo costituito uno familiare, logicamente colorato.<\/p>\n<p style=\"text-align: justify;\">Ritornando al <strong>plan settimanale<\/strong>&#8230;<\/p>\n<p style=\"text-align: justify;\">Ho visto che esistono diverse apps scaricabili che aiutano in tal senso.<br \/>\nLa maggior parte sono a pagamento, e permettono di integrare diversi calendari incrociando i dati, o semplicemente aiutando a stilare la lista della spesa.<br \/>\nPersonalmente mon ne ho da suggerire, forse perche&#8217; sono di vecchio stampo e preferisco vedere bene il mio sheet.<\/p>\n<p style=\"text-align: justify;\">Anche molti schemi stampabili di supporto sono disponibili in rete.<br \/>\nMa l&#8217;avere tutta quella &#8220;cartaccia in giro&#8221; mi opprime e rende infelice, pensando agli alberi tagliti inutilmente.<br \/>\nSenza considerare che, conoscendomi, trascorrerei il mio tempo cancellando i pasti e spostandoli di giorno in giorno.<\/p>\n<p style=\"text-align: justify;\">Il<strong> mio modello ideale<\/strong> per la pianificazione dei pasti?<br \/>\nSicuramente non si tratta di grossi fogli volanti e, al momento, e&#8217; solamente un piccolo e semplice foglio Excel, con le sue colonne e, naturalmente, anche con colori diversi ed parti evidenziate.<\/p>\n<figure id=\"attachment_38695\" aria-describedby=\"caption-attachment-38695\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-38695\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/ok_1663339876991-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/ok_1663339876991-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/ok_1663339876991-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/ok_1663339876991-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/09\/ok_1663339876991-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-38695\" class=\"wp-caption-text\">Plan cibo<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">I colori mi aiutano ad identificare gli ingredienti da acquistare (o che non sono certa di avere in casa), cosi&#8217; come quelle preparazioni &#8220;degne di nota&#8221; da venir inserite come post su questo Blog.<\/p>\n<p style=\"text-align: justify;\">Le colonne mi identificano se si tratta di un &#8220;pasto in solitaria&#8221;, oppure se Tobias e&#8217; a casa, o Stephan.<br \/>\nIl resto delle colonne possono essere di note o di link di ricette che vorrei provare a preparare. Magari alleggerendole o ritrasformandole a seconda di quanto dispongo in dispensa.<\/p>\n<p style=\"text-align: justify;\">Voi come fate?<br \/>\nAndate a braccio o vi organizzate in qualche modo?<\/p>\n<p style=\"text-align: justify;\">Aspetto con ansia di leggere i vostri commenti!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non so se anche voi avete il problema del &#8220;E oggi, cosa cucino?&#8220;.<\/p>\n","protected":false},"author":2,"featured_media":38694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,22,46],"tags":[],"class_list":["post-38600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-food","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/38600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=38600"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/38600\/revisions"}],"predecessor-version":[{"id":38699,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/38600\/revisions\/38699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/38694"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=38600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=38600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=38600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}