{"id":38100,"date":"2022-07-26T12:15:59","date_gmt":"2022-07-26T10:15:59","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=38100"},"modified":"2022-07-16T16:35:03","modified_gmt":"2022-07-16T14:35:03","slug":"zucchine_ripiene","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/07\/26\/zucchine_ripiene\/","title":{"rendered":"Zucchine ripiene  (da MSP)"},"content":{"rendered":"<p style=\"text-align: justify;\">A volte ritornano&#8230;.<br \/>\nMa questo, con me, oramai lo sapete.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Per la mia preparazione light in &#8220;solitaria&#8221;, senza nessuno a casa con me con cui mangiare o, peggio, dover preparare qualche cibo piu&#8217; calorico del solito, sono tornata al mio sito di quasi-origine: <strong>MSP<\/strong> ossia <strong>MangiaSenzaPancia<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Questa comunita&#8217;, capitanata dalla prode Giovanna, produce una grande quantita&#8217; di ricettine dietetiche e sfiziose, ottime per me ma anche per tutti coloro che, pur non essendo a stretto regime alimentare, vogliono comunque seguire un&#8217;alimentazione sana e leggera.<\/p>\n<p style=\"text-align: justify;\">Ho preso spunto da queste &#8220;zucchine ripiene&#8221; che ho trovato&#8230; fantastiche!<br \/>\nSono stata contenta che nessuno dei miei familiari abbia avuto la tentazione di assaggiarle&#8230; cosi&#8217; che non mi e&#8217; restato che surgelare la seconda porzione e godermela, in futuro, in santa pace.<\/p>\n<figure id=\"attachment_38110\" aria-describedby=\"caption-attachment-38110\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-38110\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-1024x540.jpeg\" alt=\"\" width=\"525\" height=\"277\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-1024x540.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-150x79.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-300x158.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-768x405.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-38110\" class=\"wp-caption-text\">Zucchine ripiene<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/blog.giallozafferano.it\/msp\/zucchine-ripiene-light\/\">Zucchine ripiene<\/a><\/strong><\/em><\/p>\n<pre>2 zucchine grandi (o 2 piccole)\r\n1 cipolla piccola\r\n70gr di ricotta\r\n2 cucchiai di parmigiano grattugiato\r\n90gr di prosciutto magro cotto, a dadini\r\nbasilico\r\nolio\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavate le zucchine ed eliminate le estremita&#8217;.<br \/>\nSe le zucchine sono molte lunghe, tagliatele a meta&#8217; in modo da accorciarle e poi, in ogni caso, a meta&#8217; per il lungo.<br \/>\nFate lessare leggermente le zucchine, per qualche minuto (*), e lasciatele intiepidire.<br \/>\nScavate la polpa e tagliatela a tocchetti.<br \/>\nMettete le zucchine capovolte in uno scolapasta e la polpa in un altro colino ad asciugarsi per qualche minuto.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo tagliata la cipolla a dadini piccoli, mescolatela insieme alla ricotta, al prosciutto cotto a dadini, al parmigiano, al basilixo, insaporite con sale ed un po&#8217; di pepe macinato fresco, se lo desidetate.<br \/>\nAggiungete la polpa delle zucchine e date unamescolata delicata per evitare che la polpa si schiacci troppo.<\/p>\n<p style=\"text-align: justify;\">Ponete le zucchine sul piano di lavoro e suddividete il ripieno in parti uguali, facendolo aderire bene nella parte scavata delle zucchine.<br \/>\nDistribuite il formaggio su tutte le zucchine.<\/p>\n<p style=\"text-align: justify;\">Spruzzate di olio una teglia, o usate la carta forno.<br \/>\nCuocete in <strong>forno<\/strong> a 180gradi per circa 30 minuti, poi aumentate la temperatura a 220gradi per altri 10 minuti, in modo da far gratinare.<\/p>\n<p style=\"text-align: justify;\">Se cuocete in<strong> friggitrice ad aria<\/strong>:<br \/>\npotete inserirle direttamente nel cestello o, come ho fatto io, in un contenitore.<br \/>\nCuocete a 180gradi per 15 minuti o poco piu&#8217;, cosi&#8217; da far gratinare bene il formaggio.<\/p>\n<figure id=\"attachment_38110\" aria-describedby=\"caption-attachment-38110\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-38110\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-1024x540.jpeg\" alt=\"\" width=\"525\" height=\"277\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-1024x540.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-150x79.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-300x158.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_zucchine-768x405.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-38110\" class=\"wp-caption-text\">Zucchine ripiene<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Per lessare le <strong>zucchine<\/strong> utilizzate il metodo di cottura che piu&#8217; prediligete: pentola con acqua bollente, pentola a pressione, forno microonde, etc..<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A volte ritornano&#8230;. Ma questo, con me, oramai lo sapete.<\/p>\n","protected":false},"author":2,"featured_media":38110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,138,61],"tags":[86,257,49],"class_list":["post-38100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-piatti_unici","category-uova-formaggio","tag-friggitrice","tag-light","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/38100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=38100"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/38100\/revisions"}],"predecessor-version":[{"id":38111,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/38100\/revisions\/38111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/38110"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=38100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=38100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=38100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}