{"id":37100,"date":"2022-07-01T11:55:03","date_gmt":"2022-07-01T09:55:03","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=37100"},"modified":"2022-05-31T18:34:31","modified_gmt":"2022-05-31T16:34:31","slug":"nuvola-di-uovo-basic","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/07\/01\/nuvola-di-uovo-basic\/","title":{"rendered":"Nuvola di uovo &#8220;basic&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">Quando ci si impunta&#8230; si va avanti sino alla fine.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Queste uova erano state preparate la prima volta agli inizi di maggio, aggiungendo del <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/05\/13\/nuvola-uovo-formaggio-toast\/\">formaggio grattugiato <\/a><\/strong><\/em>nell&#8217;albume mixato.<\/p>\n<p style=\"text-align: justify;\">Stavolta ho deciso di prepararle in formato &#8220;basic&#8221;, senza strane aggiunte&#8230;<\/p>\n<figure id=\"attachment_37386\" aria-describedby=\"caption-attachment-37386\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-37386\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_Nuvole03-1024x598.jpeg\" alt=\"\" width=\"525\" height=\"307\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_Nuvole03-1024x598.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_Nuvole03-150x88.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_Nuvole03-300x175.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_Nuvole03-768x449.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-37386\" class=\"wp-caption-text\">Nuvole di uova<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Nuvola di uovo &#8220;basic&#8221; <\/strong> &#8211; 4 persone<\/p>\n<pre>4 uova grandi\r\n1 ciuffo di erba cipollina \/ prezzemolo\r\nsucco di limone\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sgusciate le uova e separate i tuorli dagli albumi, inserendo i tuorli in coppette separate.<br \/>\nMontate questi ultimi a neve, con 3 gocce di succo di limone.<\/p>\n<p style=\"text-align: justify;\">Foderate la placca con un foglio di carta da forno e, con l&#8217;aiuto di un cucchiaio, dividete la meringa ottenuta in 4 parti, formando dei dischi irregolari e creando un incavo al centro.<\/p>\n<figure id=\"attachment_37390\" aria-describedby=\"caption-attachment-37390\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-37390\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326704-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326704-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326704-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326704-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326704-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-37390\" class=\"wp-caption-text\">Nuvole di uova<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cuocete le nuvole in forno caldo a 200gradi per 3 minuti.<br \/>\nSistemate i tuorli delicatamente al centro delle nuvole e mettetele in forno ancora per 1 minuto (*).<\/p>\n<figure id=\"attachment_37389\" aria-describedby=\"caption-attachment-37389\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-37389\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326683-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326683-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326683-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326683-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326683-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-37389\" class=\"wp-caption-text\">Nuvole di uova<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Spolverizzate le uova con l&#8217;erba cipollina tagliuzzata o con il prezzemolo. Oppure con un pizzico di paprica affumicata come ho fatto io&#8230; \ud83d\ude09<\/p>\n<p style=\"text-align: justify;\">Accompagnate la preparazione con fette di pane tostate ed una insalatina, se vi fa piacere!<\/p>\n<figure id=\"attachment_37388\" aria-describedby=\"caption-attachment-37388\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-37388\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326660-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326660-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326660-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326660-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1654013326660-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-37388\" class=\"wp-caption-text\">Nuvole di uova<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Devo ammettere che, questa volta, le <strong>Nuvole di uovo<\/strong> sono risultate decisamente meglio della precedente!<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando ci si impunta&#8230; si va avanti sino alla fine.<\/p>\n","protected":false},"author":2,"featured_media":37386,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148,22,60,61],"tags":[],"class_list":["post-37100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antipasti","category-food","category-secondi_piatti","category-uova-formaggio"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/37100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=37100"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/37100\/revisions"}],"predecessor-version":[{"id":37392,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/37100\/revisions\/37392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/37386"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=37100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=37100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=37100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}