{"id":36954,"date":"2022-04-25T09:00:36","date_gmt":"2022-04-25T07:00:36","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=36954"},"modified":"2022-04-29T11:32:43","modified_gmt":"2022-04-29T09:32:43","slug":"pescara-dove-ho-mangiato","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/04\/25\/pescara-dove-ho-mangiato\/","title":{"rendered":"Pescara &#8211; Dove ho mangiato"},"content":{"rendered":"<p style=\"text-align: justify;\">Durante il giro &#8220;lavorativo&#8221; a Pescara, nonostante la dieta, mi e&#8217; capitato di mangiare.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">OK, lo ammetto.<br \/>\nNon ho seguito il mio regime alimentare al grammo, ma ho tentato di non abbuffarmi troppo e, allo stesso tempo, di provare indescrivibili portate soprattutto a base di pesce.<\/p>\n<p style=\"text-align: justify;\">Subito alla prima sera, Anna (perfetta padrona di casa) ci ha accompagnato al &#8220;<strong>Grand Canyon Restaurant<\/strong>&#8220;, cosi&#8217; da avere subito un positivo imbatto nella cucina locale.<\/p>\n<p style=\"text-align: justify;\">Ho avuto modo di provare le\u00c2\u00a0 &#8220;<strong>Pallotte Cacio e Ovo<\/strong>&#8220;, ossia delle deliziosissime polpettine abruzzesi preparate senza la carne ma contenenti formaggio (Rigantino\/cacio\/pecorino\/grana), uova e pane raffermo, poi leggermente fritte e ripassate nel sugo.<br \/>\nDire che mi hanno impressionato per la loro leggera crosticina croccante&#8230; e&#8217; dire poco.<\/p>\n<figure id=\"attachment_36986\" aria-describedby=\"caption-attachment-36986\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36986\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560797-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560797-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560797-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560797-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560797-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36986\" class=\"wp-caption-text\">Pescara &#8211; Pallotte cacio e ovo &#8211; Grand Canyon Restaurant<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Sono passata al secondo piatto, lasciandomi trasportare dagli <strong>arrosticini<\/strong>.<br \/>\nVeramente deliziosi!<br \/>\nNon li avevo mai assaggiati prima e, devo ammettere, nonostante la tipologia della carne (sono di capra) mi hanno saputo coinvolgere ed avvolgere piacevolmente.<\/p>\n<figure id=\"attachment_36984\" aria-describedby=\"caption-attachment-36984\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36984\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560776-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560776-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560776-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560776-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560776-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36984\" class=\"wp-caption-text\">Pescara &#8211; Arrosticini &#8211; Grand Canyon Restaurant<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Anche le verdure grigliate meritavano, non avendo troppo olio come condimento.<\/p>\n<figure id=\"attachment_36985\" aria-describedby=\"caption-attachment-36985\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36985\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560787-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560787-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560787-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560787-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560787-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36985\" class=\"wp-caption-text\">Pescara &#8211; Verdure grigliate &#8211; Grand Canyon Restaurant<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Durante la permanenza all&#8217;Esposizione siamo andati al Ristorante &#8220;<strong>Franco<\/strong>&#8221; per dei pasti da asporto: una volta con spaghetti alla chitarra ai frutti di mare, la volta successiva con della pasta aglio, olio e scampi ed un contorno.<\/p>\n<figure id=\"attachment_36990\" aria-describedby=\"caption-attachment-36990\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36990\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224157189-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224157189-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224157189-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224157189-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224157189-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36990\" class=\"wp-caption-text\">Pescara -\u00c2\u00a0 Spaghetti alla chitacca con frutti di mare &#8211; Da Franco<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Non contenti abbiamo consumato un Aperitivo-cena serale, in compagnia degli altri espositori.<br \/>\nQui di seguito potete trovare una carrellata di quanto ingerito \ud83d\ude09<\/p>\n<figure id=\"attachment_36983\" aria-describedby=\"caption-attachment-36983\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36983\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560536-e1651223043587-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560536-e1651223043587-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560536-e1651223043587-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560536-e1651223043587-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560536-e1651223043587-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36983\" class=\"wp-caption-text\">Pescara &#8211; Aperitivo &#8211; Da Franco<\/figcaption><\/figure>\n<figure id=\"attachment_36982\" aria-describedby=\"caption-attachment-36982\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36982\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560521-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560521-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560521-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560521-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560521-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36982\" class=\"wp-caption-text\">Pescara &#8211; Saute&#8217; di cozze &#8211; Da Franco<\/figcaption><\/figure>\n<figure id=\"attachment_36980\" aria-describedby=\"caption-attachment-36980\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36980\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560499-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560499-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560499-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560499-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560499-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36980\" class=\"wp-caption-text\">Pescara &#8211; Risotto ai frutti di mare &#8211; Da Franco<\/figcaption><\/figure>\n<figure id=\"attachment_36979\" aria-describedby=\"caption-attachment-36979\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36979\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560488-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560488-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560488-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560488-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560488-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36979\" class=\"wp-caption-text\">Pescara &#8211; Pasta ai frutti di mare &#8211; Da Franco<\/figcaption><\/figure>\n<figure id=\"attachment_36977\" aria-describedby=\"caption-attachment-36977\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36977\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560466-e1651223150789-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560466-e1651223150789-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560466-e1651223150789-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560466-e1651223150789-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560466-e1651223150789-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36977\" class=\"wp-caption-text\">Pescara &#8211; Frittura con cipolle di tropea e aceto &#8211; Da Franco<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Assolutamente da prenotare in anticipo, vista la grande affluenza di persone!<br \/>\nPersonalmente mi sono trovata bene, solamente i pasti da asporto erano un po&#8217; troppo salati..<\/p>\n<p style=\"text-align: justify;\">Le colazioni ed una cena l&#8217;ho effettuata presso l<strong>&#8216;Hotel Regent<\/strong>.<br \/>\nDiciamo che dopo i primi giorni, la colazione e&#8217; stata un po&#8217; piu&#8217; ricca. Le bevande calde provengono dalla macchinetta che le distribuisce, mentre quelle fredde sono decisamente troppo annacquate.<br \/>\nPer la sera a Buffet (il cibo in scaldavivande e distribuito dal responsabile di sala) c&#8217;era la presenza di portate di carne o di pesce.<br \/>\nLa mia scelta e&#8217; caduta su quest&#8217;ultimo.. nel complesso buono ma leggermente &#8220;triste&#8221;<\/p>\n<figure id=\"attachment_36993\" aria-describedby=\"caption-attachment-36993\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36993\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172151-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172151-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172151-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172151-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172151-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36993\" class=\"wp-caption-text\">Pescara &#8211; Risotto ai frutti di mare &#8211; Hotel Regent<\/figcaption><\/figure>\n<figure id=\"attachment_36992\" aria-describedby=\"caption-attachment-36992\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36992\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172131-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172131-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172131-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172131-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172131-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36992\" class=\"wp-caption-text\">Pescara &#8211; Cacio e ovo con dadolata di verdure &#8211; Hotel Regent<\/figcaption><\/figure>\n<figure id=\"attachment_36991\" aria-describedby=\"caption-attachment-36991\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36991\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172104-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172104-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172104-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172104-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651224172104-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36991\" class=\"wp-caption-text\">Pescara &#8211; Dolce &#8211; Hotel Regent<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Avendo fatto tardi nello smontare il nostro stand espositivo, non abbiamo fatto a tempo a cenare in albergo o in qualche altro ristorante aperto nella zona.<br \/>\nE cosi&#8217; e&#8217; stata poi la volta per testare l&#8217; &#8220;<strong>Area Bistro&#8217;<\/strong> &#8220;, non lontana dall&#8217;Hotel Regent. Onestamente non ho ancora capito bene il nome del locale, in quanto potrebbe essere &#8220;<strong>Carattere81<\/strong>&#8220;.<\/p>\n<figure id=\"attachment_36976\" aria-describedby=\"caption-attachment-36976\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36976\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560324-e1651222705135-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560324-e1651222705135-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560324-e1651222705135-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560324-e1651222705135-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560324-e1651222705135-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36976\" class=\"wp-caption-text\">Pescara &#8211; Carattere81<\/figcaption><\/figure>\n<p>Ad ogni modo abbiamo preso qualche cosa di veloce, come 2 hamburger al piatto (ossia senza pane) e del contorno.<br \/>\nLa vista dei taglieri era semplicemente strepitosa ma la stanchezza si sentiva e non vedevo l&#8217;ora di ritornare in camera.<\/p>\n<figure id=\"attachment_36973\" aria-describedby=\"caption-attachment-36973\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36973\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560293-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560293-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560293-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560293-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1651160560293-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36973\" class=\"wp-caption-text\">Pescara &#8211; Burger al piatto &#8211; Carattere81<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong> Per Informazioni<\/strong><\/p>\n<p><strong>Grand Canyon Restaurant<\/strong><br \/>\nViale Amerigo Vespucci, 110<br \/>\nPescara<\/p>\n<p>Ristorante Franco<br \/>\nVia Papa Giovanni XXIII<br \/>\nPescara<\/p>\n<p><strong>Area Bar &amp; Bistro&#8217; \/ Carattere81<\/strong><br \/>\nVia Pepe, 157<br \/>\nPescara<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante il giro &#8220;lavorativo&#8221; a Pescara, nonostante la dieta, mi e&#8217; capitato di mangiare.<\/p>\n","protected":false},"author":2,"featured_media":36959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,22,25,21],"tags":[28],"class_list":["post-36954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-food","category-italia","category-travel","tag-dove_mangiare"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=36954"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36954\/revisions"}],"predecessor-version":[{"id":36994,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36954\/revisions\/36994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/36959"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=36954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=36954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=36954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}