{"id":36887,"date":"2022-04-27T11:35:10","date_gmt":"2022-04-27T09:35:10","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=36887"},"modified":"2022-04-19T11:43:59","modified_gmt":"2022-04-19T09:43:59","slug":"pollo-speziato","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/04\/27\/pollo-speziato\/","title":{"rendered":"Pollo speziato"},"content":{"rendered":"<p style=\"text-align: justify;\">L&#8217;idea originale era quella di preparare del<strong> Pollo Biryani.<\/strong><br \/>\nPurtroppo, dopo la marinatura in frigorifero, non ho potuto continuare nella preparazione dello stesso, cosi&#8217; ho convertito il pasto con un &#8220;<strong>Pollo speziato<\/strong>&#8220;.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Dopo la mia lezione di yoga sono scesa in cucina per continuare con il Biryani, lo avevo immaginato da tanti minuti&#8230; ma Stephan lo aveva gia&#8217; messo in padella.<br \/>\nE, come carboidrati, stava scaldando del pane in cassetta.<\/p>\n<p style=\"text-align: justify;\">Ho dovuto optare e cambiare nel mio percorso.<br \/>\nAd ogni modo la marinatura non ha fatto altro che ammorbidirlo, e questo non e&#8217; stato affatto male.<\/p>\n<figure id=\"attachment_36918\" aria-describedby=\"caption-attachment-36918\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36918\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo1-1-1024x611.jpeg\" alt=\"\" width=\"525\" height=\"313\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo1-1-1024x611.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo1-1-150x90.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo1-1-300x179.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo1-1-768x459.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36918\" class=\"wp-caption-text\">Pollo speziato<\/figcaption><\/figure>\n<p><strong>Ingredienti<\/strong> &#8211; <em><strong>Pollo speziato<\/strong><\/em> &#8211; 3 persone<\/p>\n<pre>600 gr di petto di pollo\r\n200 ml di yogurt bianco magro\r\n1 spicchio di aglio\r\n1 cucchiaino scarso di curcuma in polvere\r\n\u00c2\u00bd cucchiaino di zenzero in polvere\r\n1 pizzico di cardamomo\r\nqualche chiodo di garofano\r\n1 cucchiaino di cumino\r\n1 pizzico di cannella in polvere\r\n<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate tagliando il petto di pollo in bocconcini piuttosto piccoli.<br \/>\nGrattugiate la curcuma e lo zenzero, se utilizzate quelli freschi.<br \/>\nSe alcune spezie non sono in polvere (come ad esempio i chiodi di garofano o il cumino), macinateli con un mortaio o con un macinaspezie.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36873\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1649940115924-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1649940115924-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1649940115924-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1649940115924-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1649940115924-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Inserite il petto di pollo in un piatto e conditelo con tutte le spezie eccetto lo zafferano.<br \/>\nVersatevi anche lo yogurt e mescolate bene.<br \/>\nCoprite con un foglio di pellicola e lasciate marinare il pollo in frigorifero per almeno 2 ore, se avete tempo anche 6-8 ore.<\/p>\n<p style=\"text-align: justify;\">Inserite il pollo e\u00c2\u00a0 tutta la marinatura in una padella, salatelo e rosolate a fiamma vivace per 5-6 minuti, finch\u00c3\u00a9 il pollo non avr\u00c3\u00a0 preso colore.<\/p>\n<p style=\"text-align: justify;\">Regolate di sale, coprite con un coperchio e cuocete il pollo a fiamma moderata per 8-10 minuti senza mescolare.<\/p>\n<p style=\"text-align: justify;\">Servite il pollo speziato subito.<\/p>\n<figure id=\"attachment_36919\" aria-describedby=\"caption-attachment-36919\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36919\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo2-1024x611.jpeg\" alt=\"\" width=\"525\" height=\"313\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo2-1024x611.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo2-150x90.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo2-300x179.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_pollo2-768x459.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36919\" class=\"wp-caption-text\">Pollo speziato<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;idea originale era quella di preparare del Pollo Biryani. Purtroppo, dopo la marinatura in frigorifero, non ho potuto continuare nella preparazione dello stesso, cosi&#8217; ho convertito il pasto con un &#8220;Pollo speziato&#8220;.<\/p>\n","protected":false},"author":2,"featured_media":36919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230,64,22,60],"tags":[],"class_list":["post-36887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-carne","category-food","category-secondi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=36887"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36887\/revisions"}],"predecessor-version":[{"id":36920,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36887\/revisions\/36920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/36919"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=36887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=36887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=36887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}