{"id":36656,"date":"2022-04-05T11:48:26","date_gmt":"2022-04-05T09:48:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=36656"},"modified":"2024-03-19T11:57:49","modified_gmt":"2024-03-19T10:57:49","slug":"filetto_maiale-mele-senape","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/04\/05\/filetto_maiale-mele-senape\/","title":{"rendered":"Filetto di maiale con mele e senape"},"content":{"rendered":"<p style=\"text-align: justify;\">Sempre alla ricerca di ricettine golose ed invitanti, mangiabili da tutta la famiglia, sono approdata a questo <strong>&#8220;Filetto di maiale con mele e senape&#8221;.<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">La fonte e&#8217; la rivista &#8220;Cucinare Bene&#8221; (non so se esiste ancora) di almeno 15 anni fa&#8230;<\/p>\n<p style=\"text-align: justify;\">Che dire&#8230; semplice e veloce nella sua preparazione ma allo stesso tempo gustoso.<br \/>\nNon vi spaventate e neppure stupitevi per l&#8217;abbinamento senape-mela.<br \/>\nQuest&#8217;ultima, una volta cotta, risultera&#8217; addolcita ma, allo stesso tempo, con una nota pungente<\/p>\n<figure id=\"attachment_36670\" aria-describedby=\"caption-attachment-36670\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36670\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_filetto1-1024x562.jpeg\" alt=\"\" width=\"525\" height=\"288\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_filetto1-1024x562.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_filetto1-150x82.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_filetto1-300x165.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_filetto1-768x421.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36670\" class=\"wp-caption-text\">Filetto di maiale con mele e senape<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Filetto di maiale con mele e senape<\/strong> &#8211; 4 persone<\/p>\n<pre>1 filetto di maiale\r\n2 mele gialle\r\n1 rametto di rosmarino\r\n1 cucchiaio di senape (*)\r\n50gr di panna (*)\r\n2 cucchiai di olio\r\n30gr di burro\r\n1\/2 bicchiere di vino bianco\r\n1 cucchiaio di prezzemolo tritato\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Tagliate il filetto in scaloppe alte 2 cm.<br \/>\nBattetele leggermente e mettetele in una pirofila con l&#8217;olio, le foglie di rosmarino e il pepe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36669\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206726-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206726-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206726-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206726-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206726-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Lasciatele insaporire per 5 minuti.<\/p>\n<p style=\"text-align: justify;\">Intanto sbucciate le mele e tagliatele a spicchi.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36668\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206716-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206716-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206716-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206716-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206716-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nIn una padella scaldata rosolatevi i filetti 3-4 minuti per parte, bagnate con il vino bianco e lasciate evaporare. Salateli, toglieteli dal tegame e tenete al caldo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36667\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206705-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206705-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206705-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206705-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206705-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Nella stessa padella sciogliete il burro, saltatevi gli spicchi di mele per 3-4 minuti a fuoco vivo, unite la senape stemperata con la panna.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36666\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206695-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206695-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206695-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206695-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206695-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Unite i filettini di maiale e lasciate insaporire.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36665\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206685-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206685-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206685-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206685-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206685-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Servite il filetto spolverato di prezzemolo tritato (che logicamente non ho fatto..)<\/p>\n<figure id=\"attachment_36663\" aria-describedby=\"caption-attachment-36663\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36663\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206664-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206664-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206664-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206664-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206664-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36663\" class=\"wp-caption-text\">Filetto di maiale con mele e senape<\/figcaption><\/figure>\n<figure id=\"attachment_36664\" aria-describedby=\"caption-attachment-36664\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36664\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206675-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206675-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206675-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206675-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206675-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36664\" class=\"wp-caption-text\">Filetto di maiale con mele e senape<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Noi lo abbiamo gustato accompagnandolo con del riso a vapore (una semplice busta di Uncle&#8217;s Ben, cotto nel microonde).<\/p>\n<figure id=\"attachment_36662\" aria-describedby=\"caption-attachment-36662\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36662\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206654-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206654-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206654-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206654-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/04\/ok_1648546206654-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36662\" class=\"wp-caption-text\">Filetto di maiale con mele e senape<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Aspetto i vostri risultati!<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Logicamente ho omesso la <strong>panna<\/strong>, sostituendola con dello yoghurt magro.<\/li>\n<li style=\"text-align: justify;\">La <strong>senape<\/strong> che ho utilizzato per questa preparazione e&#8217; quella francese e dolce.<\/li>\n<li style=\"text-align: justify;\">Il <strong>vino<\/strong> inserito mi e&#8217; sembrato un po&#8217; troppo, meglio diminuire un pochino la dose indicata<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sempre alla ricerca di ricettine golose ed invitanti, mangiabili da tutta la famiglia, sono approdata a questo &#8220;Filetto di maiale con mele e senape&#8221;.<\/p>\n","protected":false},"author":2,"featured_media":36670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[],"class_list":["post-36656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=36656"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36656\/revisions"}],"predecessor-version":[{"id":44649,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36656\/revisions\/44649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/36670"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=36656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=36656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=36656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}