{"id":36280,"date":"2022-03-14T12:28:19","date_gmt":"2022-03-14T11:28:19","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=36280"},"modified":"2022-07-13T16:39:00","modified_gmt":"2022-07-13T14:39:00","slug":"poirot-scones","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/03\/14\/poirot-scones\/","title":{"rendered":"Poirot. Scones"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Hercule Poirot<\/strong> e&#8217; un immaginario detective belga creato dalla scrittrice britannica Agatha Christie.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nPoirot \u00c3\u00a8 uno dei personaggi pi\u00c3\u00b9 famosi e longevi di Christie, apparso in 33 romanzi, due opere teatrali (Black Coffee e Alibi) e pi\u00c3\u00b9 di 50 racconti pubblicati tra il 1920 e il 1975.<\/p>\n<p style=\"text-align: justify;\">I suoi racconti sono stati interpretati alla radio, al cinema e in televisione da vari attori.<\/p>\n<p style=\"text-align: justify;\">Hercule Poirot e&#8217; sicuramente un gourmet e, in ogni episodio, sceneggiato o film, lo vediamo deliziarsi con del buon (se non ottimo) cibo.<\/p>\n<figure id=\"attachment_36283\" aria-describedby=\"caption-attachment-36283\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36283\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/02\/hercule.jpg\" alt=\"\" width=\"474\" height=\"365\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/02\/hercule.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/02\/hercule-150x116.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/02\/hercule-300x231.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-36283\" class=\"wp-caption-text\">Immagine presa dal Web<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ecco perche&#8217; ho pensato di dedicargli questi biscottini tipici della tradizione inglese: gli <strong>scones<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Per chi no li conoscesse, gli &#8220;scones&#8221; possono essere paragonati a delle piccole focaccine da forno.<br \/>\nSolitamente sono a base di grano, o farina d&#8217;avena, con lievito in polvere come agente lievitante e cotto su teglie. Gli scones sono spesso leggermente zuccherate.<br \/>\nQuesta &#8220;focaccina&#8221; e&#8217; uno tra i prodotti piu&#8217; conosciuti durante il &#8220;<em>tea time<\/em>&#8221; anglosassone.<\/p>\n<figure id=\"attachment_36315\" aria-describedby=\"caption-attachment-36315\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36315 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scones1-1024x832.jpeg\" alt=\"\" width=\"525\" height=\"427\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scones1-1024x832.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scones1-150x122.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scones1-300x244.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scones1-768x624.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36315\" class=\"wp-caption-text\">Scones<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Scones<\/strong> &#8211;<\/p>\n<pre>500gr farina\r\n300ml latte\r\n160gr uvetta\r\n110gr burro\r\n2 cucchiai abbondanti lievito per dolci (baking powder)\r\n2 cucchiai zucchero\r\n1 cucchiaino sale\r\n1 uovo<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Setacciate la farina, aggiungeteci il lievito, lo zucchero e il sale e mescolate.<\/p>\n<p style=\"text-align: justify;\">Aggiungete il burro morbido a fiocchetti e, con la punta delle dita, sbriciolatelo nella farina finch\u00c3\u00a9 sia completamente assorbito.<br \/>\nAggiungete l\u00e2\u20ac\u2122uvetta e mescolate bene.<br \/>\nVersate il latte al centro e, con una forchetta, mescolate.<\/p>\n<p style=\"text-align: justify;\">Lavorate poi rapidamente l\u00e2\u20ac\u2122impasto con le mani (se risulta troppo liquido, aggiungete un po\u00e2\u20ac\u2122 di farina fino a quando non sar\u00c3\u00a0 pi\u00c3\u00b9 colloso).<\/p>\n<p style=\"text-align: justify;\">Su una spianatoia leggermente infarinata, stendete l\u00e2\u20ac\u2122impasto a 3cm di spessore e, con un tagliapasta di 5cm, ritagliate gli scones (e ripetere l\u00e2\u20ac\u2122operazione con gli avanzi di impasto).<br \/>\nDisponete gli scones su una teglia da forno rivestita con carta da forno, lasciando 1 o 2 mm di spazio fra ognuno ma senza che si tocchino.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36313\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902038-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902038-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902038-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902038-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902038-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Sbattete l\u00e2\u20ac\u2122uovo e spenellate la superficie degli scones.<\/p>\n<p style=\"text-align: justify;\">Infornare a 180\u00c2\u00b0C per 15-20 minuti finch\u00c3\u00a9 saranno leggermente dorati.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36312\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902028-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902028-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902028-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902028-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_1645976902028-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Sfornate (a questo punto gli scones, che si dovrebbero essere gonfiati), staccateli delicatamente e lasciateli intiepidire su una griglia.<\/p>\n<figure id=\"attachment_36314\" aria-describedby=\"caption-attachment-36314\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36314 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scone01-674x1024.jpeg\" alt=\"\" width=\"525\" height=\"798\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scone01-674x1024.jpeg 674w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scone01-99x150.jpeg 99w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scone01-198x300.jpeg 198w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/03\/ok_scone01-768x1167.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-36314\" class=\"wp-caption-text\">Scones<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Servite tipiedi o a temperatura ambiente, con burro e marmellata&#8230;. molto british style.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Agatha Christie<\/strong> era volutamente vaga sulle origini di <strong>Poirot<\/strong>, poich\u00c3\u00a9 si pensa che fosse un uomo anziano anche nei primi romanzi.<br \/>\nIn &#8220;<em>An Autobiography<\/em>&#8221; ha ammesso di averlo gi\u00c3\u00a0 immaginato come un vecchio nel 1920. All&#8217;epoca, tuttavia, non aveva idea che avrebbe scritto opere con lui per i decenni a venire.<\/p>\n<p style=\"text-align: justify;\">Un breve passaggio in &#8220;<em>The Big Four&#8221;<\/em> fornisce informazioni originali sulla nascita o almeno sull&#8217;infanzia di Poirot nella citt\u00c3\u00a0 di Spa, in Belgio o nelle sue vicinanze.<br \/>\nUna tradizione alternativa sostiene che Poirot sia nato nel villaggio di Ellezelles (provincia di Hainaut, Belgio). Nel centro di questo villaggio si possono vedere alcuni memoriali dedicati a Hercule Poirot. Non sembra esserci alcun riferimento a questo negli scritti di Christie, ma la citt\u00c3\u00a0 di Ellezelles conserva una copia del certificato di nascita di Poirot in un memoriale locale che &#8220;attesta&#8221; la nascita di Poirot, nominando suo padre e sua madre come Jules-Louis Poirot e Godelieve Poirot.<\/p>\n<figure id=\"attachment_36287\" aria-describedby=\"caption-attachment-36287\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36287\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/02\/poi.jpg\" alt=\"\" width=\"474\" height=\"711\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/02\/poi.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/02\/poi-100x150.jpg 100w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/02\/poi-200x300.jpg 200w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-36287\" class=\"wp-caption-text\">Immagine presa dal Web<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Christie ha scritto che Poirot \u00c3\u00a8 cattolico di nascita, ma non viene descritto molto sulle sue successive convinzioni religiose, tranne sporadici riferimenti al suo &#8220;andare in chiesa&#8221;.<br \/>\nChristie fornisce poche informazioni sull&#8217;infanzia di Poirot, menzionando solo in &#8220;<em>Three Act Tragedy<\/em>&#8221; che proviene da una famiglia numerosa con poca ricchezza e ha almeno una sorella minore. Oltre al francese e all&#8217;inglese, Poirot parla correntemente anche il tedesco.<\/p>\n<p style=\"text-align: justify;\">In un episodio della serie &#8220;<em>A.B.C. contro Poirot<\/em>&#8221; scopriamo che Hercule, prima di arrivare in Gran Bretagna, era un prete cattolico.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hercule Poirot e&#8217; un immaginario detective belga creato dalla scrittrice britannica Agatha Christie.<\/p>\n","protected":false},"author":2,"featured_media":36285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78,69,22],"tags":[258,251,88],"class_list":["post-36280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biscotti","category-dessert","category-food","tag-colazione","tag-foodmedia","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=36280"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36280\/revisions"}],"predecessor-version":[{"id":36317,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/36280\/revisions\/36317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/36285"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=36280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=36280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=36280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}