{"id":35336,"date":"2022-01-30T17:34:57","date_gmt":"2022-01-30T16:34:57","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=35336"},"modified":"2022-01-29T15:43:07","modified_gmt":"2022-01-29T14:43:07","slug":"brodo-di-carne_pap","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/01\/30\/brodo-di-carne_pap\/","title":{"rendered":"Brodo di carne &#8211; in Pentola a pressione"},"content":{"rendered":"<p style=\"text-align: justify;\">Se avete la necessita&#8217;, come la sottoscritta, di avere un ottimo brodo di carne&#8230; ecco la soluzione \ud83d\ude42<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Per preparare un buon brodo di carne dovete inserite la carne\u00c2\u00a0 nell&#8217;acqua fredda, portandola poi ad ebollizione.<br \/>\nSe, diversamente, preferite ottenere una buona carne a discapito del brodo, allora la carne verra&#8217; inserita nel liquido caldo.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Brodo di carne<\/strong> &#8211; (Pentola da 8 litri)<\/p>\n<pre>1,500 gr di carne di manzo adatta al bollito\r\nuna cipolla pelata\r\n2 foglie di alloro\r\n2 gambi di sedano\r\n1 cucchiaio di concentrato di pomodoro\r\n2 carote\r\n4 chiodi di garofano\r\nacqua<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sciacquate la carne, meglio direttamente in pezzi, sotto il getto dell&#8217;acqua fredda.<\/p>\n<p style=\"text-align: justify;\">Inserite la carne nella pentola a pressione ed unite la cipolla pelata, nella quale avrete inserito i chiodi di garofano (cosi&#8217; da non disperderli in seguito), le carote pelate ed a pezzi ed i gambi di sedano lavati, con le fibre rimosse, anch&#8217;essi a pezzi. Per terminare potete aggiungere delle foglie di alloro ed il concentrato di pomodoro.<\/p>\n<figure id=\"attachment_35708\" aria-describedby=\"caption-attachment-35708\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-35708\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326893-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326893-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326893-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326893-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326893-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-35708\" class=\"wp-caption-text\">Brodo di carne<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Aggiungete tanta acqua sufficiente a coprire a filo la carne.<\/p>\n<figure id=\"attachment_35707\" aria-describedby=\"caption-attachment-35707\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-35707\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326885-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326885-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326885-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326885-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/ok_1643028326885-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-35707\" class=\"wp-caption-text\">Brodo di carne<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">A questo punto chiudete la pentola a pressione con il suo coperchio, accendete la fiamma vivace e portate a bollore.<br \/>\nQuando la pentola inizia a fischiare, abbassate la fiamma e calcolate circa 35 minuti (*)<\/p>\n<p style=\"text-align: justify;\">Fate sfiatare, dividete la carne e le verdure dal brodo.<br \/>\nSe volete sgrassare il liquido, potete farlo prima raffreddare, cosi&#8217; da eliminare facilmente il grasso che affiora in superficie.<\/p>\n<p style=\"text-align: justify;\">Eventualmente potete filtrate il brodo aiutandovi con un colino a trama fine.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Ho preferito cuocere la preparazione un po&#8217; di piu&#8217; di minuti. La mia non era solamente carne, ma anche qualche osso era presente.<\/li>\n<li style=\"text-align: justify;\">Naturalmente e&#8217; possibile preparare il brodo anche nella pentola convenzionale, dove il tempo di cottura sara&#8217; prolungato&#8230; oppure utlizzando proporzioni inferiori di ingredienti (a mio avviso non ne vale molto la pena&#8230;)<\/li>\n<li style=\"text-align: justify;\">Io ne ho cucinato abbastanza, cosi&#8217; da poterlo usare subito e, il surplus, da surgelare in monoporzioni per ogni evenienza, come per un ottimo risotto.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se avete la necessita&#8217;, come la sottoscritta, di avere un ottimo brodo di carne&#8230; ecco la soluzione \ud83d\ude42<\/p>\n","protected":false},"author":2,"featured_media":35708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,180,51,57],"tags":[53],"class_list":["post-35336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pentola-a-pressione","category-primi_piatti","category-zuppa","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/35336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=35336"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/35336\/revisions"}],"predecessor-version":[{"id":35720,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/35336\/revisions\/35720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/35708"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=35336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=35336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=35336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}