{"id":34171,"date":"2022-01-09T15:52:04","date_gmt":"2022-01-09T14:52:04","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=34171"},"modified":"2022-07-13T16:42:04","modified_gmt":"2022-07-13T14:42:04","slug":"salsiccia-patate-zucchine_airfryer","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/01\/09\/salsiccia-patate-zucchine_airfryer\/","title":{"rendered":"Salsiccia, patate e zucchine \u00e2\u20ac\u201c in friggitrice ad aria"},"content":{"rendered":"<p style=\"text-align: justify;\">Con gli strani orari di casa mi risulta difficile riuscire a preparare qualche cosa per l&#8217;intera famiglia in un colpo solo.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Tobias viene a casa a pranzo solamente il mercoledi&#8217;, poco dopo le 13:00, mentre gli altri giorni della settimana sono casuali e non si puo&#8217; fare affidamento sulla sua presenza.<br \/>\nStephan lavora da casa ma, spesso, mi avverte mezz&#8217;ora prima del previsto che ha delle riunioni, la maggior parte di queste dalle 13:00. Ed e&#8217; gia&#8217; tanto che avvisa.<br \/>\nIn tutto questo aggiungiamo anche i gusti personali&#8230;<\/p>\n<p style=\"text-align: justify;\">insomma&#8230; il &#8220;ristorante&#8221; a pranzo e&#8217; aperto ma e&#8217; sempre un dilemma sui piatti da offrire.<\/p>\n<p style=\"text-align: justify;\">Ho scovato questa preparazione con <strong>&#8220;Salsiccia, patate e zucchine<\/strong>&#8221; velocissima, soprattutto se ci si fa aiutare nella cottura dalla friggitrice ad aria, piu&#8217; per Stephan che per Tobias.<\/p>\n<figure id=\"attachment_34173\" aria-describedby=\"caption-attachment-34173\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-34173\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/salsiccia-1024x612.jpeg\" alt=\"\" width=\"525\" height=\"314\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/salsiccia-1024x612.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/salsiccia-150x90.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/salsiccia-300x179.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/salsiccia-768x459.jpeg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/salsiccia-2000x1200.jpeg 2000w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-34173\" class=\"wp-caption-text\">Salsiccia patate e zucchine<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Salsiccia, patate e zucchine<\/strong> &#8211; 2 persone<\/p>\n<pre>salsiccia\r\nzucchina\r\npatate\r\n1 cucchiaino di olio\r\nsale\r\npepe\r\nspezie e\/o erbe aromatiche<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate a preparare la verdura: lavate la zucchina e tagliatela a fettine (rondelle) di circa mezzo centimetro.<\/p>\n<p style=\"text-align: justify;\">Pelate le patate, affettatele (rondelle, mezzaluna, tocchetti) non troppo grandi e di dimensione simile, giusto per facilitare la cottura.<\/p>\n<p style=\"text-align: justify;\">Inserite i pezzetti di zucchina e di patata in una ciotola, aggiungete un cucchiaino di sale, del pepe macinato ed insaporite con le spezie o le erbe aromatiche.<br \/>\nNella mia preparazione ho inserito della paprica affumicata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34175\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690421-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690421-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690421-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690421-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690421-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Mescolate bene con le mani cosi&#8217; da condire gli ingredienti in maniera uniforme.<br \/>\nTagliate la salsiccia a pezzetti ed unitela.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34174\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690431-e1636559818523-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690431-e1636559818523-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690431-e1636559818523-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690431-e1636559818523-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690431-e1636559818523-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690431-e1636559818523-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete la salsiccia tagliata a pezzetti e amalgamatela.<\/p>\n<p style=\"text-align: justify;\">Spostate la verdura e la salsiccia a pezzetti dalla ciotola al cestello della vostra airfryer.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34176\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690412-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690412-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690412-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690412-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1636552690412-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Azionate la friggitrice ad aria a 200\u00c2\u00b0 e cuocete per 10-12 minuti circa: non serve mescolare.<br \/>\nVerificate la cottura (dipende molto dalla dimensione dei pezzetti).<br \/>\nEventualmente cuocete per ulteriori 2-3 minuti.<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Niente vieta di cuocere in padella o in forno!<\/li>\n<li style=\"text-align: justify;\">La salsiccia utlizzata era pre-aromatizzata al rosmarino. Potrebbe anche essere normale \ud83d\ude09<\/li>\n<li style=\"text-align: justify;\">Meglio non sbriciolare la salsiccia, potrebbe cuocere molto prima rispetto agli altri componenti.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con gli strani orari di casa mi risulta difficile riuscire a preparare qualche cosa per l&#8217;intera famiglia in un colpo solo.<\/p>\n","protected":false},"author":2,"featured_media":34173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[86],"class_list":["post-34171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti","tag-friggitrice"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/34171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=34171"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/34171\/revisions"}],"predecessor-version":[{"id":34177,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/34171\/revisions\/34177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/34173"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=34171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=34171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=34171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}